{"id":87240,"date":"2024-05-15T10:41:33","date_gmt":"2024-05-15T13:41:33","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=87240"},"modified":"2026-05-08T23:38:20","modified_gmt":"2026-05-09T02:38:20","slug":"passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/","title":{"rendered":"Passageiro \u00e9 arremessado para fora de carro durante capotamento e morre"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Um homem, de 45 anos, morreu v\u00edtima de acidente de tr\u00e2nsito na manh\u00e3 desta ter\u00e7a-feira (14), na Rodovia General Euclides de Oliveira Figueiredo, a Rodovia da Integra\u00e7\u00e3o (SP-563), em\u00a0<a class=\"\" href=\"https:\/\/g1.globo.com\/sp\/presidente-prudente-regiao\/cidade\/mirante-do-paranapanema\/\" data-mrf-link=\"https:\/\/g1.globo.com\/sp\/presidente-prudente-regiao\/cidade\/mirante-do-paranapanema\/\">Mirante do Paranapanema (SP)<\/a>.<\/p>\n<div id=\"chunk-1h844\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"31\" data-block-id=\"7\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Article links\">De acordo com as informa\u00e7\u00f5es repassadas pela Pol\u00edcia Militar Rodovi\u00e1ria, ele era passageiro de um carro, com placas de Toledo (PR), que capotou quando trafegava pelo km 35,200, no sentido sul.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-afuuu\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"22\" data-block-id=\"8\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Article links\">Ainda segundo a pol\u00edcia, o homem dormia no banco traseiro do ve\u00edculo e foi arremessado para fora do autom\u00f3vel durante o capotamento.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-dgm34\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"13\" data-block-id=\"9\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Article links\">Um outro homem, de 35 anos, que dirigia o carro, sofreu ferimentos leves.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-ekvqk\"><\/div>\n<div id=\"chunk-9ra3f\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"23\" data-block-id=\"10\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Article links\">A pol\u00edcia informou que o motorista foi submetido a um teste de embriaguez, que n\u00e3o constatou o consumo de bebida alco\u00f3lica por ele.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-4o4gq\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"16\" data-block-id=\"11\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Article links\">A Pol\u00edcia Cient\u00edfica realizou a per\u00edcia no local para identificar as causas e circunst\u00e2ncias do acidente.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-628u1\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"14\" data-block-id=\"12\">\n<p class=\" content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Article links\">A ocorr\u00eancia tamb\u00e9m foi registrada na Delegacia da Pol\u00edcia Civil, que investigar\u00e1 o caso.<\/p>\n<\/div>\n<\/div>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Article links\">\n<p data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Article links\">\n<p data-track-category=\"Link no Texto\" data-track-links=\"\" data-mrf-recirculation=\"Article links\">Fonte: G1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem, de 45 anos, morreu v\u00edtima de acidente de tr\u00e2nsito na manh\u00e3 desta ter\u00e7a-feira (14), na Rodovia General Euclides de Oliveira Figueiredo, a Rodovia da Integra\u00e7\u00e3o (SP-563), em\u00a0Mirante do Paranapanema (SP). De acordo com as informa\u00e7\u00f5es repassadas pela Pol\u00edcia Militar Rodovi\u00e1ria, ele era passageiro de um carro, com placas de Toledo (PR), que capotou [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":87241,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-87240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Passageiro \u00e9 arremessado para fora de carro durante capotamento e morre - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Passageiro \u00e9 arremessado para fora de carro durante capotamento e morre - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Um homem, de 45 anos, morreu v\u00edtima de acidente de tr\u00e2nsito na manh\u00e3 desta ter\u00e7a-feira (14), na Rodovia General Euclides de Oliveira Figueiredo, a Rodovia da Integra\u00e7\u00e3o (SP-563), em\u00a0Mirante do Paranapanema (SP). De acordo com as informa\u00e7\u00f5es repassadas pela Pol\u00edcia Militar Rodovi\u00e1ria, ele era passageiro de um carro, com placas de Toledo (PR), que capotou [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-15T13:41:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T02:38:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/05\/cats-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"984\" \/>\n\t<meta property=\"og:image:height\" content=\"738\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Passageiro \u00e9 arremessado para fora de carro durante capotamento e morre\",\"datePublished\":\"2024-05-15T13:41:33+00:00\",\"dateModified\":\"2026-05-09T02:38:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/\"},\"wordCount\":180,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/05\/cats-7.jpg\",\"articleSection\":[\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/\",\"name\":\"Passageiro \u00e9 arremessado para fora de carro durante capotamento e morre - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/05\/cats-7.jpg\",\"datePublished\":\"2024-05-15T13:41:33+00:00\",\"dateModified\":\"2026-05-09T02:38:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/05\/cats-7.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/05\/cats-7.jpg\",\"width\":984,\"height\":738,\"caption\":\"Segundo a Pol\u00edcia Rodovi\u00e1ria, o homem, de 45 anos, dormia no banco traseiro do ve\u00edculo no momento do acidente de tr\u00e2nsito, em Mirante do Paranapanema (SP), nesta ter\u00e7a-feira (14).\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Passageiro \u00e9 arremessado para fora de carro durante capotamento e morre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Passageiro \u00e9 arremessado para fora de carro durante capotamento e morre - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/","og_locale":"pt_BR","og_type":"article","og_title":"Passageiro \u00e9 arremessado para fora de carro durante capotamento e morre - R\u00e1dio Life FM","og_description":"Um homem, de 45 anos, morreu v\u00edtima de acidente de tr\u00e2nsito na manh\u00e3 desta ter\u00e7a-feira (14), na Rodovia General Euclides de Oliveira Figueiredo, a Rodovia da Integra\u00e7\u00e3o (SP-563), em\u00a0Mirante do Paranapanema (SP). De acordo com as informa\u00e7\u00f5es repassadas pela Pol\u00edcia Militar Rodovi\u00e1ria, ele era passageiro de um carro, com placas de Toledo (PR), que capotou [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2024-05-15T13:41:33+00:00","article_modified_time":"2026-05-09T02:38:20+00:00","og_image":[{"width":984,"height":738,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/05\/cats-7.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Passageiro \u00e9 arremessado para fora de carro durante capotamento e morre","datePublished":"2024-05-15T13:41:33+00:00","dateModified":"2026-05-09T02:38:20+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/"},"wordCount":180,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/05\/cats-7.jpg","articleSection":["Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/","url":"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/","name":"Passageiro \u00e9 arremessado para fora de carro durante capotamento e morre - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/05\/cats-7.jpg","datePublished":"2024-05-15T13:41:33+00:00","dateModified":"2026-05-09T02:38:20+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/05\/cats-7.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/05\/cats-7.jpg","width":984,"height":738,"caption":"Segundo a Pol\u00edcia Rodovi\u00e1ria, o homem, de 45 anos, dormia no banco traseiro do ve\u00edculo no momento do acidente de tr\u00e2nsito, em Mirante do Paranapanema (SP), nesta ter\u00e7a-feira (14)."},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/passageiro-e-arremessado-para-fora-de-carro-durante-capotamento-e-morre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Passageiro \u00e9 arremessado para fora de carro durante capotamento e morre"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/87240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=87240"}],"version-history":[{"count":1,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/87240\/revisions"}],"predecessor-version":[{"id":87242,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/87240\/revisions\/87242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/87241"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=87240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=87240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=87240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}