{"id":85537,"date":"2024-04-10T08:49:18","date_gmt":"2024-04-10T11:49:18","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=85537"},"modified":"2026-05-11T02:43:28","modified_gmt":"2026-05-11T05:43:28","slug":"dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/","title":{"rendered":"Dupla \u00e9 presa com mais de 85 quilos de maconha e skank em porta-malas de carro na SP-294, em Parapu\u00e3"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Dois moradores em Birigui, com idades de 44 e 19 anos, foram presos em flagrante na noite desta ter\u00e7a-feira (9) durante a\u00e7\u00e3o da Pol\u00edcia Militar Rodovi\u00e1ria na Rodovia Comandante Jo\u00e3o Ribeiro de Barros, km 561, em Parapu\u00e3.<\/p>\n<p>Segundo a PM Rodovi\u00e1ria, equipes do TOR abordaram um ve\u00edculo suspeito, um Fiat Cronos com placas de Birigui, ocupado por dois indiv\u00edduos. Ao fiscalizar o autom\u00f3vel os policiais constataram no porta malas uma carga com maconha e skank acondicionadas em caixas de papel\u00e3o.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.sigamais.com\/arquivo\/uploads\/whatsapp-image-20240410-at-044442ajpg171274589366166da5cfb06.jpg\" \/><\/p>\n<p>Foram contados 96 tabletes de maconha que pesaram 80,233 quilos e 12 tabletes de skank, pesando 4,819 quilos. A droga apreendida totalizou 85,052 quilos.<\/p>\n<p>Conforme o policiamento, o condutor de 44 anos e o passageiro de 19 anos receberam voz de pris\u00e3o em flagrante no local, por tr\u00e1fico de drogas. Os dois indiv\u00edduos, o ve\u00edculo e o entorpecente foram apresentados ao plant\u00e3o da Central de Pol\u00edcia Judici\u00e1ria em Tup\u00e3. A dupla permaneceu presa \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: Siga Mais<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dois moradores em Birigui, com idades de 44 e 19 anos, foram presos em flagrante na noite desta ter\u00e7a-feira (9) durante a\u00e7\u00e3o da Pol\u00edcia Militar Rodovi\u00e1ria na Rodovia Comandante Jo\u00e3o Ribeiro de Barros, km 561, em Parapu\u00e3. Segundo a PM Rodovi\u00e1ria, equipes do TOR abordaram um ve\u00edculo suspeito, um Fiat Cronos com placas de Birigui, [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":85538,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[66,24],"tags":[],"class_list":["post-85537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dupla \u00e9 presa com mais de 85 quilos de maconha e skank em porta-malas de carro na SP-294, em Parapu\u00e3 - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dupla \u00e9 presa com mais de 85 quilos de maconha e skank em porta-malas de carro na SP-294, em Parapu\u00e3 - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Dois moradores em Birigui, com idades de 44 e 19 anos, foram presos em flagrante na noite desta ter\u00e7a-feira (9) durante a\u00e7\u00e3o da Pol\u00edcia Militar Rodovi\u00e1ria na Rodovia Comandante Jo\u00e3o Ribeiro de Barros, km 561, em Parapu\u00e3. Segundo a PM Rodovi\u00e1ria, equipes do TOR abordaram um ve\u00edculo suspeito, um Fiat Cronos com placas de Birigui, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-10T11:49:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T05:43:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/04\/whatsapp-image-20240410-at-044513-ajpeg171274591766166dbdb2cf5.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"337\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Dupla \u00e9 presa com mais de 85 quilos de maconha e skank em porta-malas de carro na SP-294, em Parapu\u00e3\",\"datePublished\":\"2024-04-10T11:49:18+00:00\",\"dateModified\":\"2026-05-11T05:43:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/\"},\"wordCount\":187,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/04\/whatsapp-image-20240410-at-044513-ajpeg171274591766166dbdb2cf5.jpeg\",\"articleSection\":[\"Pol\u00edcia\",\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/\",\"name\":\"Dupla \u00e9 presa com mais de 85 quilos de maconha e skank em porta-malas de carro na SP-294, em Parapu\u00e3 - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/04\/whatsapp-image-20240410-at-044513-ajpeg171274591766166dbdb2cf5.jpeg\",\"datePublished\":\"2024-04-10T11:49:18+00:00\",\"dateModified\":\"2026-05-11T05:43:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/04\/whatsapp-image-20240410-at-044513-ajpeg171274591766166dbdb2cf5.jpeg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/04\/whatsapp-image-20240410-at-044513-ajpeg171274591766166dbdb2cf5.jpeg\",\"width\":600,\"height\":337,\"caption\":\"Pris\u00e3o da dupla foi feita pela equipe TOR da PM Rodovi\u00e1ria. Ve\u00edculo e homens presos s\u00e3o de Birigui.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dupla \u00e9 presa com mais de 85 quilos de maconha e skank em porta-malas de carro na SP-294, em Parapu\u00e3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dupla \u00e9 presa com mais de 85 quilos de maconha e skank em porta-malas de carro na SP-294, em Parapu\u00e3 - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/","og_locale":"pt_BR","og_type":"article","og_title":"Dupla \u00e9 presa com mais de 85 quilos de maconha e skank em porta-malas de carro na SP-294, em Parapu\u00e3 - R\u00e1dio Life FM","og_description":"Dois moradores em Birigui, com idades de 44 e 19 anos, foram presos em flagrante na noite desta ter\u00e7a-feira (9) durante a\u00e7\u00e3o da Pol\u00edcia Militar Rodovi\u00e1ria na Rodovia Comandante Jo\u00e3o Ribeiro de Barros, km 561, em Parapu\u00e3. Segundo a PM Rodovi\u00e1ria, equipes do TOR abordaram um ve\u00edculo suspeito, um Fiat Cronos com placas de Birigui, [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2024-04-10T11:49:18+00:00","article_modified_time":"2026-05-11T05:43:28+00:00","og_image":[{"width":600,"height":337,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/04\/whatsapp-image-20240410-at-044513-ajpeg171274591766166dbdb2cf5.jpeg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Dupla \u00e9 presa com mais de 85 quilos de maconha e skank em porta-malas de carro na SP-294, em Parapu\u00e3","datePublished":"2024-04-10T11:49:18+00:00","dateModified":"2026-05-11T05:43:28+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/"},"wordCount":187,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/04\/whatsapp-image-20240410-at-044513-ajpeg171274591766166dbdb2cf5.jpeg","articleSection":["Pol\u00edcia","Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/","url":"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/","name":"Dupla \u00e9 presa com mais de 85 quilos de maconha e skank em porta-malas de carro na SP-294, em Parapu\u00e3 - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/04\/whatsapp-image-20240410-at-044513-ajpeg171274591766166dbdb2cf5.jpeg","datePublished":"2024-04-10T11:49:18+00:00","dateModified":"2026-05-11T05:43:28+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/04\/whatsapp-image-20240410-at-044513-ajpeg171274591766166dbdb2cf5.jpeg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/04\/whatsapp-image-20240410-at-044513-ajpeg171274591766166dbdb2cf5.jpeg","width":600,"height":337,"caption":"Pris\u00e3o da dupla foi feita pela equipe TOR da PM Rodovi\u00e1ria. Ve\u00edculo e homens presos s\u00e3o de Birigui."},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/dupla-e-presa-com-mais-de-85-quilos-de-maconha-e-skank-em-porta-malas-de-carro-na-sp-294-em-parapua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Dupla \u00e9 presa com mais de 85 quilos de maconha e skank em porta-malas de carro na SP-294, em Parapu\u00e3"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/85537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=85537"}],"version-history":[{"count":2,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/85537\/revisions"}],"predecessor-version":[{"id":85540,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/85537\/revisions\/85540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/85538"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=85537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=85537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=85537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}