{"id":82222,"date":"2024-01-25T08:59:00","date_gmt":"2024-01-25T11:59:00","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=82222"},"modified":"2026-05-09T00:32:27","modified_gmt":"2026-05-09T03:32:27","slug":"preso-e-encontrado-morto-na-penitenciaria-de-luc","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/","title":{"rendered":"Preso \u00e9 encontrado morto na penitenci\u00e1ria de Luc\u00e9lia"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Um preso foi morto dentro da penitenci\u00e1ria de Luc\u00e9lia no s\u00e1bado (20).<\/p>\n<p>Conforme apurado, o crime aconteceu em uma cela do chamado \u201cseguro\u201d, onde os agentes foram chamados por outro detento que ocupava o mesmo espa\u00e7o que a v\u00edtima.<\/p>\n<p>Foram verificados os sinais vitais, por\u00e9m, a v\u00edtima j\u00e1 estava em \u00f3bito.<\/p>\n<p>A Pol\u00edcia Civil e Per\u00edcia Criminal foram acionadas e se depararam com o corpo ca\u00eddo perto da porta da cela.<\/p>\n<p>O homem estava com os tornozelos e bra\u00e7os amarrados, tinha uma toalha na boca e um cord\u00e3o envolto ao pesco\u00e7o, al\u00e9m de um machucado na cabe\u00e7a.<\/p>\n<p>O corpo foi levado para exames no Instituto M\u00e9dico Legal de Adamantina.<\/p>\n<p>Conforme consta no registro policial, o detento que acionou os agentes foi conduzido para o Plant\u00e3o da Pol\u00edcia Civil, onde foi ouvido e permaneceu preso em flagrante sob a suspeita da autoria do crime, o que ser\u00e1 investigado com a abertura de um inqu\u00e9rito policial.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: Folha Regional<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um preso foi morto dentro da penitenci\u00e1ria de Luc\u00e9lia no s\u00e1bado (20). Conforme apurado, o crime aconteceu em uma cela do chamado \u201cseguro\u201d, onde os agentes foram chamados por outro detento que ocupava o mesmo espa\u00e7o que a v\u00edtima. Foram verificados os sinais vitais, por\u00e9m, a v\u00edtima j\u00e1 estava em \u00f3bito. A Pol\u00edcia Civil e [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":82223,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-82222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Preso \u00e9 encontrado morto na penitenci\u00e1ria de Luc\u00e9lia - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preso \u00e9 encontrado morto na penitenci\u00e1ria de Luc\u00e9lia - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Um preso foi morto dentro da penitenci\u00e1ria de Luc\u00e9lia no s\u00e1bado (20). Conforme apurado, o crime aconteceu em uma cela do chamado \u201cseguro\u201d, onde os agentes foram chamados por outro detento que ocupava o mesmo espa\u00e7o que a v\u00edtima. Foram verificados os sinais vitais, por\u00e9m, a v\u00edtima j\u00e1 estava em \u00f3bito. A Pol\u00edcia Civil e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-25T11:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T03:32:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/penitenciarialucelia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"717\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Preso \u00e9 encontrado morto na penitenci\u00e1ria de Luc\u00e9lia\",\"datePublished\":\"2024-01-25T11:59:00+00:00\",\"dateModified\":\"2026-05-09T03:32:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/\"},\"wordCount\":187,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/penitenciarialucelia.jpg\",\"articleSection\":[\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/\",\"name\":\"Preso \u00e9 encontrado morto na penitenci\u00e1ria de Luc\u00e9lia - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/penitenciarialucelia.jpg\",\"datePublished\":\"2024-01-25T11:59:00+00:00\",\"dateModified\":\"2026-05-09T03:32:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/penitenciarialucelia.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/penitenciarialucelia.jpg\",\"width\":1000,\"height\":717,\"caption\":\"Com p\u00e9s e m\u00e3os amarradas, ferimento na cabe\u00e7a e uma toalha na boca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preso \u00e9 encontrado morto na penitenci\u00e1ria de Luc\u00e9lia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preso \u00e9 encontrado morto na penitenci\u00e1ria de Luc\u00e9lia - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/","og_locale":"pt_BR","og_type":"article","og_title":"Preso \u00e9 encontrado morto na penitenci\u00e1ria de Luc\u00e9lia - R\u00e1dio Life FM","og_description":"Um preso foi morto dentro da penitenci\u00e1ria de Luc\u00e9lia no s\u00e1bado (20). Conforme apurado, o crime aconteceu em uma cela do chamado \u201cseguro\u201d, onde os agentes foram chamados por outro detento que ocupava o mesmo espa\u00e7o que a v\u00edtima. Foram verificados os sinais vitais, por\u00e9m, a v\u00edtima j\u00e1 estava em \u00f3bito. A Pol\u00edcia Civil e [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2024-01-25T11:59:00+00:00","article_modified_time":"2026-05-09T03:32:27+00:00","og_image":[{"width":1000,"height":717,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/penitenciarialucelia.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Preso \u00e9 encontrado morto na penitenci\u00e1ria de Luc\u00e9lia","datePublished":"2024-01-25T11:59:00+00:00","dateModified":"2026-05-09T03:32:27+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/"},"wordCount":187,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/penitenciarialucelia.jpg","articleSection":["Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/","url":"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/","name":"Preso \u00e9 encontrado morto na penitenci\u00e1ria de Luc\u00e9lia - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/penitenciarialucelia.jpg","datePublished":"2024-01-25T11:59:00+00:00","dateModified":"2026-05-09T03:32:27+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/penitenciarialucelia.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/penitenciarialucelia.jpg","width":1000,"height":717,"caption":"Com p\u00e9s e m\u00e3os amarradas, ferimento na cabe\u00e7a e uma toalha na boca"},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/preso-e-encontrado-morto-na-penitenciaria-de-luc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Preso \u00e9 encontrado morto na penitenci\u00e1ria de Luc\u00e9lia"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/82222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=82222"}],"version-history":[{"count":3,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/82222\/revisions"}],"predecessor-version":[{"id":82229,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/82222\/revisions\/82229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/82223"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=82222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=82222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=82222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}