{"id":81510,"date":"2024-01-08T08:53:14","date_gmt":"2024-01-08T11:53:14","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=81510"},"modified":"2026-03-12T01:06:56","modified_gmt":"2026-03-12T04:06:56","slug":"mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/","title":{"rendered":"Mulher desmaia e sofre traumatismo intracraniano ap\u00f3s ser agredida pelo marido, em Martin\u00f3polis"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Um homem, de 51 anos, foi preso neste s\u00e1bado (6) por tentativa de feminic\u00eddio ao agredir a esposa com socos e chutes, em\u00a0<a href=\"https:\/\/g1.globo.com\/sp\/presidente-prudente-regiao\/cidade\/martinopolis-sp\/\">Martin\u00f3polis (SP)<\/a>. A mulher, de 37 anos, sofreu traumatismo intracraniano devido \u00e0s les\u00f5es.<\/p>\n<p>Segundo o delegado respons\u00e1vel pelo caso, Renato Pinheiro, as agress\u00f5es ocorreram na madrugada do dia 1\u00ba de janeiro. Segundo a v\u00edtima, ela teria desmaiado ap\u00f3s o companheiro arremess\u00e1-la contra um muro e agredi-la com socos e chutes. A mulher acredita que o suspeito s\u00f3 parou de agredi-la por acreditar que ela havia morrido.<\/p>\n<p>Devido a gravidade das les\u00f5es, ela precisou ser internada no Hospital Regional (HR) de\u00a0<a href=\"https:\/\/g1.globo.com\/sp\/presidente-prudente-regiao\/cidade\/presidente-prudente\/\">Presidente Prudente (SP)<\/a>, onde permaneceu at\u00e9 a \u00faltima quinta-feira (4).<\/p>\n<p>Ao ter conhecimento dos fatos, uma equipe da Pol\u00edcia Civil foi at\u00e9 o HR e ouviu a v\u00edtima. Al\u00e9m disso, a equipe teve acesso ao prontu\u00e1rio m\u00e9dico que constatou que a mulher sofreu traumatismo intracraniano.<\/p>\n<p>Diante da gravidade das les\u00f5es, o delegado representou pela pris\u00e3o preventiva do suspeito, que foi concedida pelo Poder Judici\u00e1rio nesta sexta-feira (5). Os agentes realizaram as buscas pelo homem ao longo do dia, mas n\u00e3o o encontraram.<\/p>\n<p>Por volta das 1h deste s\u00e1bado, o envolvido apresentou-se de forma espont\u00e2nea na Delegacia de Pol\u00edcia, onde foi preso. Ele foi encaminhado \u00e0 unidade prisional de Presidente Prudente e passar\u00e1 por audi\u00eancia de cust\u00f3dia ainda neste s\u00e1bado.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte:\u00a0 G1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem, de 51 anos, foi preso neste s\u00e1bado (6) por tentativa de feminic\u00eddio ao agredir a esposa com socos e chutes, em\u00a0Martin\u00f3polis (SP). A mulher, de 37 anos, sofreu traumatismo intracraniano devido \u00e0s les\u00f5es. Segundo o delegado respons\u00e1vel pelo caso, Renato Pinheiro, as agress\u00f5es ocorreram na madrugada do dia 1\u00ba de janeiro. Segundo a [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":81511,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[66,24],"tags":[],"class_list":["post-81510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mulher desmaia e sofre traumatismo intracraniano ap\u00f3s ser agredida pelo marido, em Martin\u00f3polis - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mulher desmaia e sofre traumatismo intracraniano ap\u00f3s ser agredida pelo marido, em Martin\u00f3polis - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Um homem, de 51 anos, foi preso neste s\u00e1bado (6) por tentativa de feminic\u00eddio ao agredir a esposa com socos e chutes, em\u00a0Martin\u00f3polis (SP). A mulher, de 37 anos, sofreu traumatismo intracraniano devido \u00e0s les\u00f5es. Segundo o delegado respons\u00e1vel pelo caso, Renato Pinheiro, as agress\u00f5es ocorreram na madrugada do dia 1\u00ba de janeiro. Segundo a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-08T11:53:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-12T04:06:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/cats-7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"984\" \/>\n\t<meta property=\"og:image:height\" content=\"738\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Mulher desmaia e sofre traumatismo intracraniano ap\u00f3s ser agredida pelo marido, em Martin\u00f3polis\",\"datePublished\":\"2024-01-08T11:53:14+00:00\",\"dateModified\":\"2026-03-12T04:06:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/\"},\"wordCount\":259,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/cats-7.jpg\",\"articleSection\":[\"Pol\u00edcia\",\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/\",\"name\":\"Mulher desmaia e sofre traumatismo intracraniano ap\u00f3s ser agredida pelo marido, em Martin\u00f3polis - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/cats-7.jpg\",\"datePublished\":\"2024-01-08T11:53:14+00:00\",\"dateModified\":\"2026-03-12T04:06:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/cats-7.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/cats-7.jpg\",\"width\":984,\"height\":738,\"caption\":\"Homem, de 51 anos, se entregou \u00e0 Pol\u00edcia Civil neste s\u00e1bado (6) e foi preso. V\u00edtima informou que o suspeito s\u00f3 parou de atac\u00e1-la por acreditar que ela estava morta.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mulher desmaia e sofre traumatismo intracraniano ap\u00f3s ser agredida pelo marido, em Martin\u00f3polis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mulher desmaia e sofre traumatismo intracraniano ap\u00f3s ser agredida pelo marido, em Martin\u00f3polis - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/","og_locale":"pt_BR","og_type":"article","og_title":"Mulher desmaia e sofre traumatismo intracraniano ap\u00f3s ser agredida pelo marido, em Martin\u00f3polis - R\u00e1dio Life FM","og_description":"Um homem, de 51 anos, foi preso neste s\u00e1bado (6) por tentativa de feminic\u00eddio ao agredir a esposa com socos e chutes, em\u00a0Martin\u00f3polis (SP). A mulher, de 37 anos, sofreu traumatismo intracraniano devido \u00e0s les\u00f5es. Segundo o delegado respons\u00e1vel pelo caso, Renato Pinheiro, as agress\u00f5es ocorreram na madrugada do dia 1\u00ba de janeiro. Segundo a [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2024-01-08T11:53:14+00:00","article_modified_time":"2026-03-12T04:06:56+00:00","og_image":[{"width":984,"height":738,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/cats-7.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Mulher desmaia e sofre traumatismo intracraniano ap\u00f3s ser agredida pelo marido, em Martin\u00f3polis","datePublished":"2024-01-08T11:53:14+00:00","dateModified":"2026-03-12T04:06:56+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/"},"wordCount":259,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/cats-7.jpg","articleSection":["Pol\u00edcia","Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/","url":"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/","name":"Mulher desmaia e sofre traumatismo intracraniano ap\u00f3s ser agredida pelo marido, em Martin\u00f3polis - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/cats-7.jpg","datePublished":"2024-01-08T11:53:14+00:00","dateModified":"2026-03-12T04:06:56+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/cats-7.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2024\/01\/cats-7.jpg","width":984,"height":738,"caption":"Homem, de 51 anos, se entregou \u00e0 Pol\u00edcia Civil neste s\u00e1bado (6) e foi preso. V\u00edtima informou que o suspeito s\u00f3 parou de atac\u00e1-la por acreditar que ela estava morta."},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/mulher-desmaia-e-sofre-traumatismo-intracraniano-apos-ser-agredida-pelo-marido-em-martinopolis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Mulher desmaia e sofre traumatismo intracraniano ap\u00f3s ser agredida pelo marido, em Martin\u00f3polis"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/81510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=81510"}],"version-history":[{"count":1,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/81510\/revisions"}],"predecessor-version":[{"id":81512,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/81510\/revisions\/81512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/81511"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=81510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=81510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=81510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}