{"id":79055,"date":"2023-11-20T19:52:23","date_gmt":"2023-11-20T22:52:23","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=79055"},"modified":"2025-11-29T18:46:30","modified_gmt":"2025-11-29T21:46:30","slug":"menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/","title":{"rendered":"Menino de dois anos morre ap\u00f3s ser picado por cascavel durante acampamento, em Panorama"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Um menino, de apenas dois anos, identificado como Gael Henry Jesus Ribeiro, morreu ap\u00f3s ser picado por uma cascavel\u00a0<em>(Caudisona durissa)<\/em>, na noite deste s\u00e1bado (18), em\u00a0<a href=\"https:\/\/g1.globo.com\/sp\/presidente-prudente-regiao\/cidade\/panorama\/\">Panorama (SP)<\/a>.<\/p>\n<p>A fam\u00edlia da crian\u00e7a estava acampada na regi\u00e3o do C\u00f3rrego dos Macacos, em um local conhecido como Angico, na zona rural da cidade, onde foi pescar.<\/p>\n<p>Em determinado momento, o menino se deslocou at\u00e9 outro ponto junto a um dos irm\u00e3os, que teria ido urinar, quando foi atacado na panturrilha pela cobra, segundo a Pol\u00edcia Civil.<\/p>\n<p>No mesmo instante, o pai matou a serpente e a levou, junto com a crian\u00e7a, para o Pronto Atendimento Municipal (PAM), a fim de que os profissionais identificassem a esp\u00e9cie e ministrassem o soro anticrot\u00e1lico, no entanto, por haver um guizo na ponta do rabo do animal, j\u00e1 imaginou se tratar de uma cascavel.<\/p>\n<p>A v\u00edtima deu entrada na unidade de sa\u00fade por volta das 19h e foi atendida por um m\u00e9dico. Na ocasi\u00e3o, ele ministrou um soro para hidrata\u00e7\u00e3o e antibi\u00f3ticos na crian\u00e7a, que tamb\u00e9m foi submetida a exames, ainda de acordo com a Pol\u00edcia Civil.<\/p>\n<p>Entretanto, apenas na manh\u00e3 deste domingo (19), por volta das 7h40, \u00e9 que o soro anticrot\u00e1lico para o veneno foi aplicado em Gael, cerca de 12 horas ap\u00f3s o acidente.<\/p>\n<p>Em seguida, ele foi transferido para o Hospital Regional (HR), em\u00a0<a href=\"https:\/\/g1.globo.com\/sp\/presidente-prudente-regiao\/cidade\/presidente-prudente\/\">Presidente Prudente (SP)<\/a>, onde deu entrada \u00e0s 11h58, por\u00e9m, como estava \u201cbastante debilitado\u201d, n\u00e3o resistiu e morreu \u00e0s 13h02, conforme a pol\u00edcia.<\/p>\n<p>O corpo da crian\u00e7a foi encaminhado ao Instituto M\u00e9dico Legal (IML) para realiza\u00e7\u00e3o do exame necrosc\u00f3pico.<\/p>\n<p>Gael foi sepultado na tarde desta segunda-feira (20), no Cemit\u00e9rio Municipal de Panorama.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/s2-g1.glbimg.com\/Cbh3gaXCu7ERhiXcqJul-zxY8cY=\/0x0:540x960\/984x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2023\/g\/A\/qlHJ9zQ0WhY8qOcLAFyw\/t48fl655b1a3d84f37.jpeg\" alt=\"Gael Henry Jesus Ribeiro, de apenas dois anos, morreu ap\u00f3s ser picado por uma cascavel, na zona rural de Panorama (SP) \u2014 Foto: Redes sociais\" \/><\/p>\n<p><strong>&#8216;Cortei a cabe\u00e7a da cobra&#8217;, diz pai da crian\u00e7a<\/strong><\/p>\n<p>O pai de Gael, Jos\u00e9 Ribeiro, disse que conseguiu cortar a cabe\u00e7a da cobra logo ap\u00f3s o filho ter sido atacado pela cascavel.<\/p>\n<p>\u201cMeu menino aqui do lado viu na hora que a cobra atacou o mais novinho num lugar limpo. A\u00ed rapidamente, no apavoro, eu fui l\u00e1 e cortei a cabe\u00e7a dela. Coloquei ela dentro de uma sacolinha e n\u00f3s corremos o mais r\u00e1pido poss\u00edvel para o hospital. Chegando aqui no hospital, o m\u00e9dico fez os primeiros procedimentos. Disse que ia fazer um exame nele de seis em seis horas, mas eu vi que o estado dele estava piorando. Quando o dia amanheceu, voltei \u00e0 Santa Casa [e] o menino estava pior ainda. Estava geladinho. Estava dormindo, n\u00e3o acordava. Perguntei para o m\u00e9dico [e] o m\u00e9dico falou que ele estava bem. Os pulm\u00f5ezinhos estavam funcionando, estava respirando\u201d, disse Jos\u00e9 Ribeiro em entrevista \u00e0\u00a0<strong>TV Fronteira<\/strong>.<\/p>\n<p>O pai ainda lembrou que, quando o filho foi transferido para o Hospital Regional, em Presidente Prudente, a uma dist\u00e2ncia de mais de 140km de Panorama, o estado de sa\u00fade da crian\u00e7a j\u00e1 era \u201cmuito grave\u201d.<\/p>\n<p>\u201cQuando foi encaminhar ele, j\u00e1 era em torno de umas 10 [horas], 10 e pouco. Ele j\u00e1 chegou l\u00e1 em [Presidente] Prudente num estado muito grave. Os m\u00e9dicos j\u00e1 n\u00e3o tinham o que fazer muito, n\u00e3o. Foram entub\u00e1-lo e ele teve um ataque card\u00edaco. Ficaram em torno de uns 40 minutos tentando reanim\u00e1-lo, mas infelizmente veio a \u00f3bito. No meu ponto de vista, foi neglig\u00eancia, porque num caso desse tinha de ter transferido o menino na hora para um lugar de mais recursos\u201d, lamentou Jos\u00e9 Ribeiro.<\/p>\n<p>O irm\u00e3o de Gael, Elielton Jesus Ribeiro, afirmou que houve muita demora no atendimento do paciente em Panorama.<\/p>\n<p>\u201cEu vi a hora que a cobra deu o bote nele. Eu peguei ele do lado da cobra, porque ele caiu na hora da picada. Eu peguei do lado. Vim socorrer. Meu pai cortou a cabe\u00e7a da cobra e n\u00f3s viemos para a Santa Casa aqui\u201d, disse Elielton.<\/p>\n<p>\u201cParece que o soro foi em 12 horas. Veio uma ambul\u00e2ncia de outra cidade para vir buscar ele para transferir para [Presidente] Prudente\u201d, complementou o irm\u00e3o.<\/p>\n<p>&#8211;:&#8211;\/&#8211;:&#8211;<\/p>\n<p><strong>Outro lado<\/strong><\/p>\n<p>A secret\u00e1ria de Sa\u00fade de Panorama, Vanessa Steluti, disse que Gael Henry Jesus Ribeiro chegou ao Pronto Atendimento Municipal e, \u201cde imediato, o m\u00e9dico plantonista ligou para o Instituto Butant\u00e3 e seguiu todo o protocolo\u201d.<\/p>\n<p>\u201cA crian\u00e7a n\u00e3o apresentava sintomas e, por instru\u00e7\u00e3o do Butant\u00e3, n\u00e3o foi aplicado o soro de imediato. Porque o soro, se administrado de forma desnecess\u00e1ria, pode causar danos ao paciente, como um choque anafil\u00e1tico, por exemplo\u201d, ressaltou.<\/p>\n<p>\u00c0 reportagem, ela ainda informou que, quando a crian\u00e7a apresentou o primeiro sintoma, o m\u00e9dico \u201centrou com o soro\u201d.<\/p>\n<p>\u201cPedimos a vaga para Presidente Prudente dar continuidade e a crian\u00e7a chegou est\u00e1vel [no Hospital Regional]. Agora, eu estou aguardando para saber o que aconteceu com essa crian\u00e7a dentro do hospital, em Prudente\u201d, finalizou.<\/p>\n<p>A secret\u00e1ria municipal de Sa\u00fade de Panorama, Vanessa Steluti, garantiu que a crian\u00e7a estava \u201cest\u00e1vel\u201d quando foi transferida para Presidente Prudente.<\/p>\n<p>\u201cPassado esse per\u00edodo de observa\u00e7\u00e3o, na parte da manh\u00e3, a crian\u00e7a apresentou, pelos exames, uma altera\u00e7\u00e3o e foram feitos todos os soros necess\u00e1rios e pedimos a transfer\u00eancia a partir deste momento. Quando ela foi transferida, saiu daqui est\u00e1vel. Quando a m\u00e9dica que fez a transfer\u00eancia deixou a crian\u00e7a l\u00e1 no hospital de [Presidente] Prudente, essa crian\u00e7a estava saturando bem e ela estava est\u00e1vel. De acordo com os procedimentos do [Instituto] Butant\u00e3, essa crian\u00e7a se apresentava est\u00e1vel. Ent\u00e3o, n\u00e3o tinha naquele momento por que fazer a transfer\u00eancia. A partir do momento em que foi constatada uma altera\u00e7\u00e3o, imediatamente n\u00f3s j\u00e1 fizemos essa transfer\u00eancia\u201d, explicou a secret\u00e1ria.<\/p>\n<p>Vanessa ressaltou que, para garantir a seguran\u00e7a do paciente, foi acionada uma ambul\u00e2ncia equipada com uma Unidade de Terapia Intensiva (UTI) para fazer a transfer\u00eancia do menino de Panorama para Presidente Prudente.<\/p>\n<p>\u201cChamamos a ambul\u00e2ncia UTI para resguardar o caminho, apesar de a crian\u00e7a estar est\u00e1vel aqui, n\u00f3s fizemos esse trajeto com uma ambul\u00e2ncia UTI, de acordo com o que tem de ser para a seguran\u00e7a do paciente, e, como eu disse, chegou at\u00e9 Presidente Prudente est\u00e1vel\u201d, complementou a secret\u00e1ria de Sa\u00fade.<\/p>\n<p>Em nota oficial enviada , o Hospital Regional de Presidente Prudente informou que o paciente em quest\u00e3o deu entrada neste domingo (19) no Pronto-socorro infantil da unidade em estado grave, \u00e0s 11h58, onde foi prontamente atendido pela equipe m\u00e9dica e multiprofissional. Devido \u00e0 gravidade do seu quadro cl\u00ednico, o \u00f3bito do menino foi constatado no mesmo dia, \u00e0s 13h02, ainda segundo o HR.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: G1<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um menino, de apenas dois anos, identificado como Gael Henry Jesus Ribeiro, morreu ap\u00f3s ser picado por uma cascavel\u00a0(Caudisona durissa), na noite deste s\u00e1bado (18), em\u00a0Panorama (SP). A fam\u00edlia da crian\u00e7a estava acampada na regi\u00e3o do C\u00f3rrego dos Macacos, em um local conhecido como Angico, na zona rural da cidade, onde foi pescar. Em determinado [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":79056,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-79055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Menino de dois anos morre ap\u00f3s ser picado por cascavel durante acampamento, em Panorama - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Menino de dois anos morre ap\u00f3s ser picado por cascavel durante acampamento, em Panorama - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Um menino, de apenas dois anos, identificado como Gael Henry Jesus Ribeiro, morreu ap\u00f3s ser picado por uma cascavel\u00a0(Caudisona durissa), na noite deste s\u00e1bado (18), em\u00a0Panorama (SP). A fam\u00edlia da crian\u00e7a estava acampada na regi\u00e3o do C\u00f3rrego dos Macacos, em um local conhecido como Angico, na zona rural da cidade, onde foi pescar. Em determinado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-20T22:52:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-29T21:46:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/11\/men.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Menino de dois anos morre ap\u00f3s ser picado por cascavel durante acampamento, em Panorama\",\"datePublished\":\"2023-11-20T22:52:23+00:00\",\"dateModified\":\"2025-11-29T21:46:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/\"},\"wordCount\":1164,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/11\/men.jpg\",\"articleSection\":[\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/\",\"name\":\"Menino de dois anos morre ap\u00f3s ser picado por cascavel durante acampamento, em Panorama - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/11\/men.jpg\",\"datePublished\":\"2023-11-20T22:52:23+00:00\",\"dateModified\":\"2025-11-29T21:46:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/11\/men.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/11\/men.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"V\u00edtima deu entrada no Pronto Atendimento Municipal (PAM) na noite de s\u00e1bado (18), por\u00e9m, recebeu o soro anticrot\u00e1lico apenas na manh\u00e3 de domingo (19), 12 horas depois do acidente.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Menino de dois anos morre ap\u00f3s ser picado por cascavel durante acampamento, em Panorama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Menino de dois anos morre ap\u00f3s ser picado por cascavel durante acampamento, em Panorama - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/","og_locale":"pt_BR","og_type":"article","og_title":"Menino de dois anos morre ap\u00f3s ser picado por cascavel durante acampamento, em Panorama - R\u00e1dio Life FM","og_description":"Um menino, de apenas dois anos, identificado como Gael Henry Jesus Ribeiro, morreu ap\u00f3s ser picado por uma cascavel\u00a0(Caudisona durissa), na noite deste s\u00e1bado (18), em\u00a0Panorama (SP). A fam\u00edlia da crian\u00e7a estava acampada na regi\u00e3o do C\u00f3rrego dos Macacos, em um local conhecido como Angico, na zona rural da cidade, onde foi pescar. Em determinado [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2023-11-20T22:52:23+00:00","article_modified_time":"2025-11-29T21:46:30+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/11\/men.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Menino de dois anos morre ap\u00f3s ser picado por cascavel durante acampamento, em Panorama","datePublished":"2023-11-20T22:52:23+00:00","dateModified":"2025-11-29T21:46:30+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/"},"wordCount":1164,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/11\/men.jpg","articleSection":["Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/","url":"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/","name":"Menino de dois anos morre ap\u00f3s ser picado por cascavel durante acampamento, em Panorama - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/11\/men.jpg","datePublished":"2023-11-20T22:52:23+00:00","dateModified":"2025-11-29T21:46:30+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/11\/men.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/11\/men.jpg","width":1920,"height":1080,"caption":"V\u00edtima deu entrada no Pronto Atendimento Municipal (PAM) na noite de s\u00e1bado (18), por\u00e9m, recebeu o soro anticrot\u00e1lico apenas na manh\u00e3 de domingo (19), 12 horas depois do acidente."},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/menino-de-dois-anos-morre-apos-ser-picado-por-cascavel-durante-acampamento-em-panorama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Menino de dois anos morre ap\u00f3s ser picado por cascavel durante acampamento, em Panorama"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/79055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=79055"}],"version-history":[{"count":2,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/79055\/revisions"}],"predecessor-version":[{"id":79058,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/79055\/revisions\/79058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/79056"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=79055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=79055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=79055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}