{"id":77642,"date":"2023-10-14T08:32:43","date_gmt":"2023-10-14T11:32:43","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=77642"},"modified":"2026-04-06T19:42:44","modified_gmt":"2026-04-06T22:42:44","slug":"aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/","title":{"rendered":"Aposta da Quina realizada em Luc\u00e9lia ganha pr\u00eamio de R$ 13,4 milh\u00f5es"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"font-weight: 400\">Uma aposta da Quina realizada em Luc\u00e9lia foi a \u00fanica ganhadora do pr\u00eamio principal da loteria, de R$ 13.415.923,25. O sorteio do Concurso 6265mfoi foi realizado nesta sexta-feira (13). Foi uma aposta simples, feita na \u00fanica casa lot\u00e9rica da cidade, com cinco acertos. Os n\u00fameros sorteados foram 44 \u2013 52 \u2013 63 \u2013 71 \u2013 77.<\/p>\n<p style=\"font-weight: 400\">Conforme a Caixa, outros 87 apostas fizeram quatro acertos e levaram, cada uma, a premia\u00e7\u00e3o no valor de R$ 7.525,26. J\u00e1 5.604 fizeram tr\u00eas acertos, com pr\u00eamio individual de R$ 111,26. E 149.081 fizeram dois acertos, com premia\u00e7\u00e3o de R$ 4,18 para cada contemplado.\u00a0<a href=\"https:\/\/loterias.caixa.gov.br\/Paginas\/Locais-Sorte.aspx?modalidade=QUINA&amp;concurso=6265&amp;titulo=Quina\"><strong>Veja aqui o detalhamento das apostas ganhadoras<\/strong><\/a>.<\/p>\n<p style=\"font-weight: 400\">Para concorrer na Quina \u00e9 preciso marcar de 5 a 15 n\u00fameros dentre os 80 dispon\u00edveis no volante, e ganha o pr\u00eamio principal quem acertar as cinco dezenas, como ocorreu com a aposta milion\u00e1ria realizada em Luc\u00e9lia. O valor da aposta de cinco n\u00fameros \u00e9 R$ 2,50. Quanto mais n\u00fameros marcar, maior o pre\u00e7o da aposta e maiores as chances de ganhar.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: Siga Mais<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma aposta da Quina realizada em Luc\u00e9lia foi a \u00fanica ganhadora do pr\u00eamio principal da loteria, de R$ 13.415.923,25. O sorteio do Concurso 6265mfoi foi realizado nesta sexta-feira (13). Foi uma aposta simples, feita na \u00fanica casa lot\u00e9rica da cidade, com cinco acertos. Os n\u00fameros sorteados foram 44 \u2013 52 \u2013 63 \u2013 71 \u2013 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":77643,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-77642","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aposta da Quina realizada em Luc\u00e9lia ganha pr\u00eamio de R$ 13,4 milh\u00f5es - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aposta da Quina realizada em Luc\u00e9lia ganha pr\u00eamio de R$ 13,4 milh\u00f5es - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Uma aposta da Quina realizada em Luc\u00e9lia foi a \u00fanica ganhadora do pr\u00eamio principal da loteria, de R$ 13.415.923,25. O sorteio do Concurso 6265mfoi foi realizado nesta sexta-feira (13). Foi uma aposta simples, feita na \u00fanica casa lot\u00e9rica da cidade, com cinco acertos. Os n\u00fameros sorteados foram 44 \u2013 52 \u2013 63 \u2013 71 \u2013 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-14T11:32:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-06T22:42:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/10\/loterias4anagbr16251662916092970x550jpg1697281651652a767347fc7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"337\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Aposta da Quina realizada em Luc\u00e9lia ganha pr\u00eamio de R$ 13,4 milh\u00f5es\",\"datePublished\":\"2023-10-14T11:32:43+00:00\",\"dateModified\":\"2026-04-06T22:42:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/\"},\"wordCount\":181,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/10\/loterias4anagbr16251662916092970x550jpg1697281651652a767347fc7.jpg\",\"articleSection\":[\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/\",\"name\":\"Aposta da Quina realizada em Luc\u00e9lia ganha pr\u00eamio de R$ 13,4 milh\u00f5es - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/10\/loterias4anagbr16251662916092970x550jpg1697281651652a767347fc7.jpg\",\"datePublished\":\"2023-10-14T11:32:43+00:00\",\"dateModified\":\"2026-04-06T22:42:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/10\/loterias4anagbr16251662916092970x550jpg1697281651652a767347fc7.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/10\/loterias4anagbr16251662916092970x550jpg1697281651652a767347fc7.jpg\",\"width\":600,\"height\":337,\"caption\":\"Sorteio foi realizado nesta sexta-feira (13). Foi a \u00fanica aposta ganhadora do primeiro pr\u00eamio.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aposta da Quina realizada em Luc\u00e9lia ganha pr\u00eamio de R$ 13,4 milh\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aposta da Quina realizada em Luc\u00e9lia ganha pr\u00eamio de R$ 13,4 milh\u00f5es - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/","og_locale":"pt_BR","og_type":"article","og_title":"Aposta da Quina realizada em Luc\u00e9lia ganha pr\u00eamio de R$ 13,4 milh\u00f5es - R\u00e1dio Life FM","og_description":"Uma aposta da Quina realizada em Luc\u00e9lia foi a \u00fanica ganhadora do pr\u00eamio principal da loteria, de R$ 13.415.923,25. O sorteio do Concurso 6265mfoi foi realizado nesta sexta-feira (13). Foi uma aposta simples, feita na \u00fanica casa lot\u00e9rica da cidade, com cinco acertos. Os n\u00fameros sorteados foram 44 \u2013 52 \u2013 63 \u2013 71 \u2013 [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2023-10-14T11:32:43+00:00","article_modified_time":"2026-04-06T22:42:44+00:00","og_image":[{"width":600,"height":337,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/10\/loterias4anagbr16251662916092970x550jpg1697281651652a767347fc7.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Aposta da Quina realizada em Luc\u00e9lia ganha pr\u00eamio de R$ 13,4 milh\u00f5es","datePublished":"2023-10-14T11:32:43+00:00","dateModified":"2026-04-06T22:42:44+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/"},"wordCount":181,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/10\/loterias4anagbr16251662916092970x550jpg1697281651652a767347fc7.jpg","articleSection":["Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/","url":"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/","name":"Aposta da Quina realizada em Luc\u00e9lia ganha pr\u00eamio de R$ 13,4 milh\u00f5es - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/10\/loterias4anagbr16251662916092970x550jpg1697281651652a767347fc7.jpg","datePublished":"2023-10-14T11:32:43+00:00","dateModified":"2026-04-06T22:42:44+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/10\/loterias4anagbr16251662916092970x550jpg1697281651652a767347fc7.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/10\/loterias4anagbr16251662916092970x550jpg1697281651652a767347fc7.jpg","width":600,"height":337,"caption":"Sorteio foi realizado nesta sexta-feira (13). Foi a \u00fanica aposta ganhadora do primeiro pr\u00eamio."},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/aposta-da-quina-realizada-em-lucelia-ganha-premio-de-r-134-milhoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Aposta da Quina realizada em Luc\u00e9lia ganha pr\u00eamio de R$ 13,4 milh\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/77642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=77642"}],"version-history":[{"count":4,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/77642\/revisions"}],"predecessor-version":[{"id":77647,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/77642\/revisions\/77647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/77643"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=77642"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=77642"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=77642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}