{"id":76069,"date":"2023-09-08T16:00:48","date_gmt":"2023-09-08T19:00:48","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=76069"},"modified":"2026-05-01T07:06:03","modified_gmt":"2026-05-01T10:06:03","slug":"acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/","title":{"rendered":"Acidente entre caminh\u00f5es mata duas pessoas e interdita por tr\u00eas horas tr\u00e2nsito na ponte sobre o Rio Paran\u00e1 na divisa entre SP e MS"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<div id=\"chunk-br12p\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"44\" data-block-id=\"3\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Um acidente de tr\u00e2nsito envolvendo tr\u00eas caminh\u00f5es, na manh\u00e3 desta sexta-feira (8), deixou duas v\u00edtimas fatais na Ponte H\u00e9lio Serejo, na BR-267, que faz divisa entre os Estados de S\u00e3o Paulo, em\u00a0<a class=\"\" href=\"https:\/\/g1.globo.com\/sp\/presidente-prudente-regiao\/cidade\/presidente-epitacio\/\">Presidente Epit\u00e1cio<\/a>, e Mato Grosso do Sul, em\u00a0<a class=\"\" href=\"https:\/\/g1.globo.com\/ms\/mato-grosso-do-sul\/cidade\/bataguassu\/\">Bataguassu<\/a> .<\/p>\n<\/div>\n<\/div>\n<div class=\"wall protected-content\">\n<div id=\"chunk-5niq1\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"33\" data-block-id=\"4\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Segundo a Pol\u00edcia Rodovi\u00e1ria informou \u00e0s 13h54,<strong>\u00a0<\/strong><strong><span class=\"highlight highlighted\">a via foi totalmente liberada e o tr\u00e2nsito voltou a fluir normalmente em ambos os sentidos \u00e0s 13h40, ap\u00f3s um per\u00edodo de tr\u00eas horas de interdi\u00e7\u00e3o.<\/span><\/strong><\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-8kfs9\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"22\" data-block-id=\"5\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A Pol\u00edcia Rodovi\u00e1ria foi acionada e a Concession\u00e1ria Cart, respons\u00e1vel pela administra\u00e7\u00e3o da via em Presidente Epit\u00e1cio, tamb\u00e9m auxilia no atendimento.<\/p>\n<div id=\"chunk-fhjvs\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"36\" data-block-id=\"8\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Em nota , a Cart Concession\u00e1ria de Rodovias informou que presta apoio operacional com suas equipes de Resgate e Opera\u00e7\u00f5es no Estado de Mato Grosso do Sul em decorr\u00eancia de um acidente de tr\u00e2nsito.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-esoel\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"40\" data-block-id=\"9\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;Tal acidente traz reflexo no final do trecho de concess\u00e3o com lentid\u00e3o no tr\u00e1fego, monitorado pelo policiamento rodovi\u00e1rio de SP e equipes operacionais Cart. A Concession\u00e1ria refor\u00e7a a orienta\u00e7\u00e3o aos motoristas de respeito \u00e0 sinaliza\u00e7\u00e3o e velocidade no local&#8221;, finalizou.<\/p>\n<\/div>\n<\/div>\n<div id=\"chunk-7vndu\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"5\" data-block-id=\"10\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A ocorr\u00eancia est\u00e1 em andamento.<\/p>\n<\/div>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Fonte: G1<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um acidente de tr\u00e2nsito envolvendo tr\u00eas caminh\u00f5es, na manh\u00e3 desta sexta-feira (8), deixou duas v\u00edtimas fatais na Ponte H\u00e9lio Serejo, na BR-267, que faz divisa entre os Estados de S\u00e3o Paulo, em\u00a0Presidente Epit\u00e1cio, e Mato Grosso do Sul, em\u00a0Bataguassu . Segundo a Pol\u00edcia Rodovi\u00e1ria informou \u00e0s 13h54,\u00a0a via foi totalmente liberada e o tr\u00e2nsito voltou [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":76070,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[66,24],"tags":[],"class_list":["post-76069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acidente entre caminh\u00f5es mata duas pessoas e interdita por tr\u00eas horas tr\u00e2nsito na ponte sobre o Rio Paran\u00e1 na divisa entre SP e MS - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acidente entre caminh\u00f5es mata duas pessoas e interdita por tr\u00eas horas tr\u00e2nsito na ponte sobre o Rio Paran\u00e1 na divisa entre SP e MS - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Um acidente de tr\u00e2nsito envolvendo tr\u00eas caminh\u00f5es, na manh\u00e3 desta sexta-feira (8), deixou duas v\u00edtimas fatais na Ponte H\u00e9lio Serejo, na BR-267, que faz divisa entre os Estados de S\u00e3o Paulo, em\u00a0Presidente Epit\u00e1cio, e Mato Grosso do Sul, em\u00a0Bataguassu . Segundo a Pol\u00edcia Rodovi\u00e1ria informou \u00e0s 13h54,\u00a0a via foi totalmente liberada e o tr\u00e2nsito voltou [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-08T19:00:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-01T10:06:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"984\" \/>\n\t<meta property=\"og:image:height\" content=\"901\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Acidente entre caminh\u00f5es mata duas pessoas e interdita por tr\u00eas horas tr\u00e2nsito na ponte sobre o Rio Paran\u00e1 na divisa entre SP e MS\",\"datePublished\":\"2023-09-08T19:00:48+00:00\",\"dateModified\":\"2026-05-01T10:06:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/\"},\"wordCount\":234,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1-1.jpg\",\"articleSection\":[\"Pol\u00edcia\",\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/\",\"name\":\"Acidente entre caminh\u00f5es mata duas pessoas e interdita por tr\u00eas horas tr\u00e2nsito na ponte sobre o Rio Paran\u00e1 na divisa entre SP e MS - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1-1.jpg\",\"datePublished\":\"2023-09-08T19:00:48+00:00\",\"dateModified\":\"2026-05-01T10:06:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1-1.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1-1.jpg\",\"width\":984,\"height\":901,\"caption\":\"Ponte H\u00e9lio Serejo, que interliga Presidente Epit\u00e1cio (SP) e Bataguassu (MS), registrou um quil\u00f4metro de congestionamento durante o bloqueio nesta sexta-feira (8).\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acidente entre caminh\u00f5es mata duas pessoas e interdita por tr\u00eas horas tr\u00e2nsito na ponte sobre o Rio Paran\u00e1 na divisa entre SP e MS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acidente entre caminh\u00f5es mata duas pessoas e interdita por tr\u00eas horas tr\u00e2nsito na ponte sobre o Rio Paran\u00e1 na divisa entre SP e MS - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/","og_locale":"pt_BR","og_type":"article","og_title":"Acidente entre caminh\u00f5es mata duas pessoas e interdita por tr\u00eas horas tr\u00e2nsito na ponte sobre o Rio Paran\u00e1 na divisa entre SP e MS - R\u00e1dio Life FM","og_description":"Um acidente de tr\u00e2nsito envolvendo tr\u00eas caminh\u00f5es, na manh\u00e3 desta sexta-feira (8), deixou duas v\u00edtimas fatais na Ponte H\u00e9lio Serejo, na BR-267, que faz divisa entre os Estados de S\u00e3o Paulo, em\u00a0Presidente Epit\u00e1cio, e Mato Grosso do Sul, em\u00a0Bataguassu . Segundo a Pol\u00edcia Rodovi\u00e1ria informou \u00e0s 13h54,\u00a0a via foi totalmente liberada e o tr\u00e2nsito voltou [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2023-09-08T19:00:48+00:00","article_modified_time":"2026-05-01T10:06:03+00:00","og_image":[{"width":984,"height":901,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1-1.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Acidente entre caminh\u00f5es mata duas pessoas e interdita por tr\u00eas horas tr\u00e2nsito na ponte sobre o Rio Paran\u00e1 na divisa entre SP e MS","datePublished":"2023-09-08T19:00:48+00:00","dateModified":"2026-05-01T10:06:03+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/"},"wordCount":234,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1-1.jpg","articleSection":["Pol\u00edcia","Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/","url":"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/","name":"Acidente entre caminh\u00f5es mata duas pessoas e interdita por tr\u00eas horas tr\u00e2nsito na ponte sobre o Rio Paran\u00e1 na divisa entre SP e MS - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1-1.jpg","datePublished":"2023-09-08T19:00:48+00:00","dateModified":"2026-05-01T10:06:03+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1-1.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1-1.jpg","width":984,"height":901,"caption":"Ponte H\u00e9lio Serejo, que interliga Presidente Epit\u00e1cio (SP) e Bataguassu (MS), registrou um quil\u00f4metro de congestionamento durante o bloqueio nesta sexta-feira (8)."},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/acidente-entre-caminhoes-mata-duas-pessoas-e-interdita-por-tres-horas-transito-na-ponte-sobre-o-rio-parana-na-divisa-entre-sp-e-ms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Acidente entre caminh\u00f5es mata duas pessoas e interdita por tr\u00eas horas tr\u00e2nsito na ponte sobre o Rio Paran\u00e1 na divisa entre SP e MS"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/76069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=76069"}],"version-history":[{"count":2,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/76069\/revisions"}],"predecessor-version":[{"id":76072,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/76069\/revisions\/76072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/76070"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=76069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=76069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=76069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}