{"id":75857,"date":"2023-09-03T19:44:34","date_gmt":"2023-09-03T22:44:34","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=75857"},"modified":"2025-02-12T23:08:13","modified_gmt":"2025-02-13T02:08:13","slug":"quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/","title":{"rendered":"Quatro bolivianos s\u00e3o presos com coca\u00edna escondida em fundo falso de duas caminhonetes"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Quatro bolivianos foram presos em flagrante, na madrugada deste domingo (3), por tr\u00e1fico de droga no km 561,500 da Rodovia Raposo Tavares (SP-270), em\u00a0<b><a style=\"font-style: inherit\" href=\"https:\/\/g1.globo.com\/sp\/presidente-prudente-regiao\/cidade\/presidente-prudente\/\">Presidente Prudente (SP)<\/a><\/b>.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Segundo a Pol\u00edcia Rodovi\u00e1ria, uma equipe abordou uma caminhonete com placas da Bol\u00edvia com dois ocupantes, ambos bolivianos. O condutor do ve\u00edculo, um homem de 44 anos, apresentou nervosismo com a abordagem policial, o que fez os agentes realizarem uma vistoria no autom\u00f3vel.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Os policiais localizaram um carregamento de coca\u00edna escondido em um fundo falso no assoalho e nas laterais da carroceria da caminhonete, que totalizaram 160 tabletes do entorpecente.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Al\u00e9m do ve\u00edculo, tamb\u00e9m foram apreendidos dois aparelhos celulares, R$ 5.880, 100 d\u00f3lares e 2.110 Bolivianos, moeda utilizada na Bol\u00edvia.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">O condutor do ve\u00edculo e a passageira, uma mulher de 30 anos, foram presos em flagrante por tr\u00e1fico de droga e permaneceram \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a.<\/p>\n<p>Durante a retirada do entorpecente da caminhonete, os policiais notaram a passagem de outro ve\u00edculo semelhante e tamb\u00e9m com emplacamento da Bol\u00edvia. Os agentes acompanharam a caminhonete e fizeram a abordagem.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Durante a abordagem, a Pol\u00edcia Rodovi\u00e1ria constatou que haviam dois bolivianos no ve\u00edculo, o condutor de 26 anos e a passageira de 45 anos. Ao realizarem vistoria veicular, localizaram outro carregamento de coca\u00edna escondido em um fundo falso e nas laterais da carroceria.<\/p>\n<p>Com os dois envolvidos, os policiais apreenderam dois celulares, R$ 7.205 e 101 d\u00f3lares. Eles tamb\u00e9m foram presos em flagrante por tr\u00e1fico de droga e permaneceram \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">O entorpecente apreendido totalizou 269,500 kg.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/s2-g1.glbimg.com\/yRSYeGpALy2iJRU_y1AWOckZrZM=\/0x0:1600x738\/984x0\/smart\/filters:strip_icc()\/i.s3.glbimg.com\/v1\/AUTH_59edd422c0c84a879bd37670ae4f538a\/internal_photos\/bs\/2023\/r\/2\/3wu8KbRNefKvtrcVjETQ\/cocaina-3-.jpeg\" alt=\"Bolivianos s\u00e3o presos com coca\u00edna escondida em fundo falso de caminhonete, em Presidente Prudente (SP) \u2014 Foto: Pol\u00edcia Rodovi\u00e1ria\" \/><\/p>\n<p>Fonte: G1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quatro bolivianos foram presos em flagrante, na madrugada deste domingo (3), por tr\u00e1fico de droga no km 561,500 da Rodovia Raposo Tavares (SP-270), em\u00a0Presidente Prudente (SP). Segundo a Pol\u00edcia Rodovi\u00e1ria, uma equipe abordou uma caminhonete com placas da Bol\u00edvia com dois ocupantes, ambos bolivianos. O condutor do ve\u00edculo, um homem de 44 anos, apresentou nervosismo [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":75858,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[66,24],"tags":[],"class_list":["post-75857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quatro bolivianos s\u00e3o presos com coca\u00edna escondida em fundo falso de duas caminhonetes - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quatro bolivianos s\u00e3o presos com coca\u00edna escondida em fundo falso de duas caminhonetes - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Quatro bolivianos foram presos em flagrante, na madrugada deste domingo (3), por tr\u00e1fico de droga no km 561,500 da Rodovia Raposo Tavares (SP-270), em\u00a0Presidente Prudente (SP). Segundo a Pol\u00edcia Rodovi\u00e1ria, uma equipe abordou uma caminhonete com placas da Bol\u00edvia com dois ocupantes, ambos bolivianos. O condutor do ve\u00edculo, um homem de 44 anos, apresentou nervosismo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-03T22:44:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-13T02:08:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"984\" \/>\n\t<meta property=\"og:image:height\" content=\"454\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Quatro bolivianos s\u00e3o presos com coca\u00edna escondida em fundo falso de duas caminhonetes\",\"datePublished\":\"2023-09-03T22:44:34+00:00\",\"dateModified\":\"2025-02-13T02:08:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/\"},\"wordCount\":283,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1.jpg\",\"articleSection\":[\"Pol\u00edcia\",\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/\",\"name\":\"Quatro bolivianos s\u00e3o presos com coca\u00edna escondida em fundo falso de duas caminhonetes - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1.jpg\",\"datePublished\":\"2023-09-03T22:44:34+00:00\",\"dateModified\":\"2025-02-13T02:08:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1.jpg\",\"width\":984,\"height\":454,\"caption\":\"Ocorr\u00eancia foi registrada na madrugada deste domingo (3) e o entorpecente apreendido totalizou 269,500 kg.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quatro bolivianos s\u00e3o presos com coca\u00edna escondida em fundo falso de duas caminhonetes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quatro bolivianos s\u00e3o presos com coca\u00edna escondida em fundo falso de duas caminhonetes - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/","og_locale":"pt_BR","og_type":"article","og_title":"Quatro bolivianos s\u00e3o presos com coca\u00edna escondida em fundo falso de duas caminhonetes - R\u00e1dio Life FM","og_description":"Quatro bolivianos foram presos em flagrante, na madrugada deste domingo (3), por tr\u00e1fico de droga no km 561,500 da Rodovia Raposo Tavares (SP-270), em\u00a0Presidente Prudente (SP). Segundo a Pol\u00edcia Rodovi\u00e1ria, uma equipe abordou uma caminhonete com placas da Bol\u00edvia com dois ocupantes, ambos bolivianos. O condutor do ve\u00edculo, um homem de 44 anos, apresentou nervosismo [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2023-09-03T22:44:34+00:00","article_modified_time":"2025-02-13T02:08:13+00:00","og_image":[{"width":984,"height":454,"url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Quatro bolivianos s\u00e3o presos com coca\u00edna escondida em fundo falso de duas caminhonetes","datePublished":"2023-09-03T22:44:34+00:00","dateModified":"2025-02-13T02:08:13+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/"},"wordCount":283,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1.jpg","articleSection":["Pol\u00edcia","Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/","url":"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/","name":"Quatro bolivianos s\u00e3o presos com coca\u00edna escondida em fundo falso de duas caminhonetes - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1.jpg","datePublished":"2023-09-03T22:44:34+00:00","dateModified":"2025-02-13T02:08:13+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/09\/1.jpg","width":984,"height":454,"caption":"Ocorr\u00eancia foi registrada na madrugada deste domingo (3) e o entorpecente apreendido totalizou 269,500 kg."},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/quatro-bolivianos-sao-presos-com-cocaina-escondida-em-fundo-falso-de-duas-caminhonetes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Quatro bolivianos s\u00e3o presos com coca\u00edna escondida em fundo falso de duas caminhonetes"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/75857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=75857"}],"version-history":[{"count":2,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/75857\/revisions"}],"predecessor-version":[{"id":75860,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/75857\/revisions\/75860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/75858"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=75857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=75857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=75857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}