{"id":75340,"date":"2023-08-21T22:40:09","date_gmt":"2023-08-22T01:40:09","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=75340"},"modified":"2026-05-06T20:15:59","modified_gmt":"2026-05-06T23:15:59","slug":"seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/","title":{"rendered":"Seis pessoas ficam feridas na rodovia que liga Bastos a Rancharia"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Seis pessoas foram conduzidas para atendimento m\u00e9dico ap\u00f3s acidente ocorrido na Rodovia Brigadeiro Eduardo Gomes (SP-457), que liga os munic\u00edpios de Bastos (SP) e Rancharia (SP), na noite desta segunda-feira, dia 21. A colis\u00e3o que envolveu tr\u00eas ve\u00edculos, sendo uma caminhonete e dois autom\u00f3veis, aconteceu por volta das 19h40, na altura do quil\u00f4metro 83, munic\u00edpio de Rancharia.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Por motivos e em circunst\u00e2ncias a serem apuradas, ocorreu uma colis\u00e3o que envolveu uma caminhonete Hilux, placas de Tup\u00e3 (SP) com dois ocupantes e um Celta, placas de Ara\u00e7atuba (SP) com quatro ocupantes que seguiam no sentido Rancharia a Bastos e um Gol, placas de Iep\u00ea (SP), com um casal que vinha em sentido contr\u00e1rio. Duas pessoas do Gol e quatro do Celta foram conduzidas para o Pronto Socorro Municipal de Bastos.<\/div>\n<\/div>\n<div class=\"x11i5rnm xat24cr x1mh8g0r x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">Ainda de acordo com informa\u00e7\u00f5es, apuradas no local, duas pessoas que estavam na caminhonete Hilux n\u00e3o sofreram ferimentos. Participaram do socorro \u00e0s v\u00edtimas, quatro homens e uma senhora, duas ambul\u00e2ncias de Bastos e o Corpo de Bombeiro de Rancharia e Tup\u00e3. A Pol\u00edcia Rodovi\u00e1ria de Rancharia registrou a ocorr\u00eancia. A Pol\u00edcia Rodovi\u00e1ria de Tup\u00e3 tamb\u00e9m esteve no local do acidente.<\/div>\n<\/div>\n<div dir=\"auto\">\n<div class='flex flex-wrap items-center -mx-1'>\r\n<a class='thumbnail gallery p-1 w-1\/2 md:w-1\/4' href='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/369322672_7065147083496036_4255376094027223976_n.jpg'><img class='border border-white' src='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/369322672_7065147083496036_4255376094027223976_n-200x200.jpg' alt='369322672_7065147083496036_4255376094027223976_n' \/><\/a><a class='thumbnail gallery p-1 w-1\/2 md:w-1\/4' href='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/369883533_7065146250162786_3305651676479245031_n.jpg'><img class='border border-white' src='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/369883533_7065146250162786_3305651676479245031_n-200x200.jpg' alt='369883533_7065146250162786_3305651676479245031_n' \/><\/a><\/div>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Fonte: Valdecir Luis de Sousa<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seis pessoas foram conduzidas para atendimento m\u00e9dico ap\u00f3s acidente ocorrido na Rodovia Brigadeiro Eduardo Gomes (SP-457), que liga os munic\u00edpios de Bastos (SP) e Rancharia (SP), na noite desta segunda-feira, dia 21. A colis\u00e3o que envolveu tr\u00eas ve\u00edculos, sendo uma caminhonete e dois autom\u00f3veis, aconteceu por volta das 19h40, na altura do quil\u00f4metro 83, munic\u00edpio [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":75341,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[66,24],"tags":[],"class_list":["post-75340","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seis pessoas ficam feridas na rodovia que liga Bastos a Rancharia - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seis pessoas ficam feridas na rodovia que liga Bastos a Rancharia - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Seis pessoas foram conduzidas para atendimento m\u00e9dico ap\u00f3s acidente ocorrido na Rodovia Brigadeiro Eduardo Gomes (SP-457), que liga os munic\u00edpios de Bastos (SP) e Rancharia (SP), na noite desta segunda-feira, dia 21. A colis\u00e3o que envolveu tr\u00eas ve\u00edculos, sendo uma caminhonete e dois autom\u00f3veis, aconteceu por volta das 19h40, na altura do quil\u00f4metro 83, munic\u00edpio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-22T01:40:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T23:15:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/369169145_7065147426829335_5940164708258727966_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"572\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Seis pessoas ficam feridas na rodovia que liga Bastos a Rancharia\",\"datePublished\":\"2023-08-22T01:40:09+00:00\",\"dateModified\":\"2026-05-06T23:15:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/\"},\"wordCount\":231,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/369169145_7065147426829335_5940164708258727966_n.jpg\",\"articleSection\":[\"Pol\u00edcia\",\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/\",\"name\":\"Seis pessoas ficam feridas na rodovia que liga Bastos a Rancharia - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/369169145_7065147426829335_5940164708258727966_n.jpg\",\"datePublished\":\"2023-08-22T01:40:09+00:00\",\"dateModified\":\"2026-05-06T23:15:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/369169145_7065147426829335_5940164708258727966_n.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/369169145_7065147426829335_5940164708258727966_n.jpg\",\"width\":1000,\"height\":572},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seis pessoas ficam feridas na rodovia que liga Bastos a Rancharia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seis pessoas ficam feridas na rodovia que liga Bastos a Rancharia - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/","og_locale":"pt_BR","og_type":"article","og_title":"Seis pessoas ficam feridas na rodovia que liga Bastos a Rancharia - R\u00e1dio Life FM","og_description":"Seis pessoas foram conduzidas para atendimento m\u00e9dico ap\u00f3s acidente ocorrido na Rodovia Brigadeiro Eduardo Gomes (SP-457), que liga os munic\u00edpios de Bastos (SP) e Rancharia (SP), na noite desta segunda-feira, dia 21. A colis\u00e3o que envolveu tr\u00eas ve\u00edculos, sendo uma caminhonete e dois autom\u00f3veis, aconteceu por volta das 19h40, na altura do quil\u00f4metro 83, munic\u00edpio [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2023-08-22T01:40:09+00:00","article_modified_time":"2026-05-06T23:15:59+00:00","og_image":[{"width":1000,"height":572,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/369169145_7065147426829335_5940164708258727966_n.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Seis pessoas ficam feridas na rodovia que liga Bastos a Rancharia","datePublished":"2023-08-22T01:40:09+00:00","dateModified":"2026-05-06T23:15:59+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/"},"wordCount":231,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/369169145_7065147426829335_5940164708258727966_n.jpg","articleSection":["Pol\u00edcia","Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/","url":"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/","name":"Seis pessoas ficam feridas na rodovia que liga Bastos a Rancharia - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/369169145_7065147426829335_5940164708258727966_n.jpg","datePublished":"2023-08-22T01:40:09+00:00","dateModified":"2026-05-06T23:15:59+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/369169145_7065147426829335_5940164708258727966_n.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/369169145_7065147426829335_5940164708258727966_n.jpg","width":1000,"height":572},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/seis-pessoas-ficam-feridas-na-rodovia-que-liga-bastos-a-rancharia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Seis pessoas ficam feridas na rodovia que liga Bastos a Rancharia"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/75340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=75340"}],"version-history":[{"count":1,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/75340\/revisions"}],"predecessor-version":[{"id":75344,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/75340\/revisions\/75344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/75341"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=75340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=75340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=75340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}