{"id":75288,"date":"2023-08-19T18:06:54","date_gmt":"2023-08-19T21:06:54","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=75288"},"modified":"2026-04-28T05:23:32","modified_gmt":"2026-04-28T08:23:32","slug":"motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/","title":{"rendered":"Motorista com caminh\u00e3o placas de Panorama morre ap\u00f3s perder controle e cair no Rio do Peixe"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Motorista com caminh\u00e3o placas de Panorama morre ap\u00f3s perder controle e cair no Rio do Peixe<\/p>\n<p>&nbsp;<\/p>\n<p>Outras duas pessoas que estavam na cabine ficaram feridas<\/p>\n<p>Um grave acidente ocorreu na estrada vicinal que conecta Tup\u00e3 a Quat\u00e1 na tarde deste s\u00e1bado (19) deixando um morto e duas pessoas feridas. Um caminh\u00e3o estava se deslocando nessa dire\u00e7\u00e3o quando, ao se aproximar da ponte sobre o &#8220;Rio do Peixe&#8221;, o motorista perdeu o controle do ve\u00edculo. O caminh\u00e3o tombou e caiu dentro do rio.<\/p>\n<p>O ve\u00edculo transportava tr\u00eas indiv\u00edduos. Dois deles conseguiram sair da cabine por conta pr\u00f3pria. Um desses indiv\u00edduos, que sofreu ferimentos leves, foi prontamente socorrido por uma ambul\u00e2ncia e encaminhado para a Santa Casa de Quat\u00e1. Enquanto isso, a segunda v\u00edtima, com ferimentos mais graves, foi resgatada pelo Corpo de Bombeiros de Tup\u00e3.<\/p>\n<p>Al\u00e9m do Corpo de Bombeiros de Tup\u00e3, equipes do Corpo de Bombeiros de Rancharia tamb\u00e9m prestaram aux\u00edlio na ocorr\u00eancia, especialmente no processo de resgate da v\u00edtima que ficou presa nas ferragens.<\/p>\n<p>&#8220;O condutor ficou preso \u00e0s ferragens com a cabine semi encoberta. Mais dois ocupantes, fora do ve\u00edculo, tiveram ferimentos graves&#8221;, disse o sargento Figeroa, do Corpo de Bombeiros de Tup\u00e3.<\/p>\n<p>Tragicamente, apesar dos esfor\u00e7os, essa v\u00edtima foi retirada das ferragens em estado de parada cardiorrespirat\u00f3ria e levada com urg\u00eancia para o pronto-socorro da Santa Casa de Tup\u00e3. No entanto, infelizmente, n\u00e3o foi poss\u00edvel salvar sua vida. A identidade de v\u00edtima ainda n\u00e3o foi revelada.<\/p>\n<p>O caminh\u00e3o tinha placas de Panorama e estava carregado com blocos no momento do acidente. Um morador que testemunhou o momento do acidente relatou ter ouvido um barulho e foi ver o que havia acontecido. &#8220;Quando chegamos no local, o caminh\u00e3o j\u00e1 estava dentro do rio. Entrei no rio para ver se o rapaz ainda estava vivo, mas j\u00e1 estava morto&#8221;, contou.<\/p>\n<p>Um motorista que estava atr\u00e1s do caminh\u00e3o tamb\u00e9m relatou o momento do acidente. &#8220;Eu estava com meu ve\u00edculo atr\u00e1s e percebi que o caminh\u00e3o vinha numa velocidade onde ele perdeu o controle, n\u00e3o sei precisar se perdeu o freio, mas a princ\u00edpio ele atravessou a pista, bateu do lado direito do morro, tentou voltar mas caiu dentro do rio. Paramos o carro e vimos que dois rapazes conseguiram sair de dentro do caminh\u00e3o, ajudamos eles a subirem em um barranco, mas infelizmente o motorista veio a \u00f3bito&#8221;, conta.<\/p>\n<p>A Pol\u00edcia Militar de Tup\u00e3 e Quat\u00e1 estiveram no local para registrar o boletim de ocorr\u00eancia e para realizar a sinaliza\u00e7\u00e3o necess\u00e1ria. Al\u00e9m disso, a Per\u00edcia T\u00e9cnica do Instituto de Criminal\u00edstica tamb\u00e9m compareceu.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-75290\" src=\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479060929-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479060929-300x300.jpg 300w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479060929-150x150.jpg 150w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479060929-768x768.jpg 768w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479060929-200x200.jpg 200w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479060929-250x250.jpg 250w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479060929-500x500.jpg 500w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479060929-700x700.jpg 700w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479060929.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-75291\" src=\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479057911-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479057911-300x300.jpg 300w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479057911-150x150.jpg 150w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479057911-768x768.jpg 768w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479057911-200x200.jpg 200w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479057911-250x250.jpg 250w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479057911-500x500.jpg 500w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479057911-700x700.jpg 700w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479057911.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-75292\" src=\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479048464-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479048464-300x300.jpg 300w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479048464-150x150.jpg 150w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479048464-768x768.jpg 768w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479048464-200x200.jpg 200w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479048464-250x250.jpg 250w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479048464-500x500.jpg 500w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479048464-700x700.jpg 700w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479048464.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\nFonte: Tupacity<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Motorista com caminh\u00e3o placas de Panorama morre ap\u00f3s perder controle e cair no Rio do Peixe &nbsp; Outras duas pessoas que estavam na cabine ficaram feridas Um grave acidente ocorreu na estrada vicinal que conecta Tup\u00e3 a Quat\u00e1 na tarde deste s\u00e1bado (19) deixando um morto e duas pessoas feridas. Um caminh\u00e3o estava se deslocando [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":75289,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-75288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Motorista com caminh\u00e3o placas de Panorama morre ap\u00f3s perder controle e cair no Rio do Peixe - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Motorista com caminh\u00e3o placas de Panorama morre ap\u00f3s perder controle e cair no Rio do Peixe - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Motorista com caminh\u00e3o placas de Panorama morre ap\u00f3s perder controle e cair no Rio do Peixe &nbsp; Outras duas pessoas que estavam na cabine ficaram feridas Um grave acidente ocorreu na estrada vicinal que conecta Tup\u00e3 a Quat\u00e1 na tarde deste s\u00e1bado (19) deixando um morto e duas pessoas feridas. Um caminh\u00e3o estava se deslocando [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-19T21:06:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T08:23:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479052929.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Motorista com caminh\u00e3o placas de Panorama morre ap\u00f3s perder controle e cair no Rio do Peixe\",\"datePublished\":\"2023-08-19T21:06:54+00:00\",\"dateModified\":\"2026-04-28T08:23:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/\"},\"wordCount\":490,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479052929.jpg\",\"articleSection\":[\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/\",\"name\":\"Motorista com caminh\u00e3o placas de Panorama morre ap\u00f3s perder controle e cair no Rio do Peixe - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479052929.jpg\",\"datePublished\":\"2023-08-19T21:06:54+00:00\",\"dateModified\":\"2026-04-28T08:23:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479052929.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479052929.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Motorista com caminh\u00e3o placas de Panorama morre ap\u00f3s perder controle e cair no Rio do Peixe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Motorista com caminh\u00e3o placas de Panorama morre ap\u00f3s perder controle e cair no Rio do Peixe - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/","og_locale":"pt_BR","og_type":"article","og_title":"Motorista com caminh\u00e3o placas de Panorama morre ap\u00f3s perder controle e cair no Rio do Peixe - R\u00e1dio Life FM","og_description":"Motorista com caminh\u00e3o placas de Panorama morre ap\u00f3s perder controle e cair no Rio do Peixe &nbsp; Outras duas pessoas que estavam na cabine ficaram feridas Um grave acidente ocorreu na estrada vicinal que conecta Tup\u00e3 a Quat\u00e1 na tarde deste s\u00e1bado (19) deixando um morto e duas pessoas feridas. Um caminh\u00e3o estava se deslocando [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2023-08-19T21:06:54+00:00","article_modified_time":"2026-04-28T08:23:32+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479052929.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Motorista com caminh\u00e3o placas de Panorama morre ap\u00f3s perder controle e cair no Rio do Peixe","datePublished":"2023-08-19T21:06:54+00:00","dateModified":"2026-04-28T08:23:32+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/"},"wordCount":490,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479052929.jpg","articleSection":["Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/","url":"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/","name":"Motorista com caminh\u00e3o placas de Panorama morre ap\u00f3s perder controle e cair no Rio do Peixe - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479052929.jpg","datePublished":"2023-08-19T21:06:54+00:00","dateModified":"2026-04-28T08:23:32+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479052929.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/FB_IMG_1692479052929.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/motorista-com-caminhao-placas-de-panorama-morre-apos-perder-controle-e-cair-no-rio-do-peixe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Motorista com caminh\u00e3o placas de Panorama morre ap\u00f3s perder controle e cair no Rio do Peixe"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/75288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=75288"}],"version-history":[{"count":1,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/75288\/revisions"}],"predecessor-version":[{"id":75293,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/75288\/revisions\/75293"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/75289"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=75288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=75288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=75288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}