{"id":75152,"date":"2023-08-16T22:31:39","date_gmt":"2023-08-17T01:31:39","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=75152"},"modified":"2026-05-11T00:56:19","modified_gmt":"2026-05-11T03:56:19","slug":"video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/","title":{"rendered":"V\u00eddeo flagra briga com pancadaria entre alunos dentro de escola estadual"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<div id=\"chunk-fo56a\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"31\" data-block-id=\"3\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Alunos da Escola Estadual Professora Celestina de Campos Toledo Teixeira se envolveram em uma briga generalizada, na manh\u00e3 desta ter\u00e7a-feira (15), no distrito de Floresta do Sul, em\u00a0<a class=\"\" href=\"https:\/\/g1.globo.com\/sp\/presidente-prudente-regiao\/cidade\/presidente-prudente\/\">Presidente Prudente (SP)<\/a>.<\/p>\n<\/div>\n<\/div>\n<div class=\"wall protected-content\">\n<div id=\"chunk-5bvvb\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"68\" data-block-id=\"4\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Um v\u00eddeo, gravado na \u00e1rea de conviv\u00eancia da escola estadual, mostra o andamento da confus\u00e3o entre os alunos. Nas imagens, \u00e9 poss\u00edvel identificar o in\u00edcio das agress\u00f5es verbais e f\u00edsicas, entre dois estudantes, e, na sequ\u00eancia, o momento em que outros alunos come\u00e7am a trocar socos e chutes. Durante a filmagem, de 38 segundos, outros alunos observam a briga generalizada e zombam das agress\u00f5es, com gritos e palavr\u00f5es.<\/p>\n<\/div>\n<p><a href=\"https:\/\/g1.globo.com\/sp\/presidente-prudente-regiao\/video\/video-flagra-briga-generalizada-entre-alunos-de-escola-estadual-em-presidente-prudente-11869896.ghtml\">https:\/\/g1.globo.com\/sp\/presidente-prudente-regiao\/video\/video-flagra-briga-generalizada-entre-alunos-de-escola-estadual-em-presidente-prudente-11869896.ghtml<\/a><\/p>\n<\/div>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Fonte: G1<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Alunos da Escola Estadual Professora Celestina de Campos Toledo Teixeira se envolveram em uma briga generalizada, na manh\u00e3 desta ter\u00e7a-feira (15), no distrito de Floresta do Sul, em\u00a0Presidente Prudente (SP). Um v\u00eddeo, gravado na \u00e1rea de conviv\u00eancia da escola estadual, mostra o andamento da confus\u00e3o entre os alunos. Nas imagens, \u00e9 poss\u00edvel identificar o in\u00edcio [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":75153,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[42,66,24],"tags":[],"class_list":["post-75152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","category-policia","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>V\u00eddeo flagra briga com pancadaria entre alunos dentro de escola estadual - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V\u00eddeo flagra briga com pancadaria entre alunos dentro de escola estadual - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Alunos da Escola Estadual Professora Celestina de Campos Toledo Teixeira se envolveram em uma briga generalizada, na manh\u00e3 desta ter\u00e7a-feira (15), no distrito de Floresta do Sul, em\u00a0Presidente Prudente (SP). Um v\u00eddeo, gravado na \u00e1rea de conviv\u00eancia da escola estadual, mostra o andamento da confus\u00e3o entre os alunos. Nas imagens, \u00e9 poss\u00edvel identificar o in\u00edcio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-17T01:31:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T03:56:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/20230816_222947.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"V\u00eddeo flagra briga com pancadaria entre alunos dentro de escola estadual\",\"datePublished\":\"2023-08-17T01:31:39+00:00\",\"dateModified\":\"2026-05-11T03:56:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/\"},\"wordCount\":131,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/20230816_222947.jpg\",\"articleSection\":[\"Educa\u00e7\u00e3o\",\"Pol\u00edcia\",\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/\",\"name\":\"V\u00eddeo flagra briga com pancadaria entre alunos dentro de escola estadual - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/20230816_222947.jpg\",\"datePublished\":\"2023-08-17T01:31:39+00:00\",\"dateModified\":\"2026-05-11T03:56:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/20230816_222947.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/20230816_222947.jpg\",\"width\":1080,\"height\":1275},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00eddeo flagra briga com pancadaria entre alunos dentro de escola estadual\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V\u00eddeo flagra briga com pancadaria entre alunos dentro de escola estadual - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/","og_locale":"pt_BR","og_type":"article","og_title":"V\u00eddeo flagra briga com pancadaria entre alunos dentro de escola estadual - R\u00e1dio Life FM","og_description":"Alunos da Escola Estadual Professora Celestina de Campos Toledo Teixeira se envolveram em uma briga generalizada, na manh\u00e3 desta ter\u00e7a-feira (15), no distrito de Floresta do Sul, em\u00a0Presidente Prudente (SP). Um v\u00eddeo, gravado na \u00e1rea de conviv\u00eancia da escola estadual, mostra o andamento da confus\u00e3o entre os alunos. Nas imagens, \u00e9 poss\u00edvel identificar o in\u00edcio [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2023-08-17T01:31:39+00:00","article_modified_time":"2026-05-11T03:56:19+00:00","og_image":[{"width":1080,"height":1275,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/20230816_222947.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"V\u00eddeo flagra briga com pancadaria entre alunos dentro de escola estadual","datePublished":"2023-08-17T01:31:39+00:00","dateModified":"2026-05-11T03:56:19+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/"},"wordCount":131,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/20230816_222947.jpg","articleSection":["Educa\u00e7\u00e3o","Pol\u00edcia","Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/","url":"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/","name":"V\u00eddeo flagra briga com pancadaria entre alunos dentro de escola estadual - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/20230816_222947.jpg","datePublished":"2023-08-17T01:31:39+00:00","dateModified":"2026-05-11T03:56:19+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/20230816_222947.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/20230816_222947.jpg","width":1080,"height":1275},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/video-flagra-briga-com-pancadaria-entre-alunos-dentro-de-escola-estadual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"V\u00eddeo flagra briga com pancadaria entre alunos dentro de escola estadual"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/75152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=75152"}],"version-history":[{"count":2,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/75152\/revisions"}],"predecessor-version":[{"id":75155,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/75152\/revisions\/75155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/75153"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=75152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=75152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=75152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}