{"id":74724,"date":"2023-08-04T09:13:07","date_gmt":"2023-08-04T12:13:07","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=74724"},"modified":"2026-05-05T11:14:14","modified_gmt":"2026-05-05T14:14:14","slug":"policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/","title":{"rendered":"Policia Civil instaura inqu\u00e9rito para apurar atropelamento com v\u00edtima fatal em Junqueir\u00f3polis"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<div>A Pol\u00edcia Civil, por interm\u00e9dio da Delegacia de Pol\u00edcia de Junqueir\u00f3polis, instaurou nesta quinta-feira (3), apura\u00e7\u00e3o policial visando investigar um atropelamento ocorrido na Rua Curitiba, na noite de quarta-feira (2), onde um homem de 37 anos acabou falecendo.<\/div>\n<div>O suspeito autoria do delito, um homem de 24 anos, havia se evadido do local ap\u00f3s o acidente, por\u00e9m j\u00e1 havia sido identificado. O acusado se apresentou na Delegacia de Pol\u00edcia de Junqueir\u00f3polis na manh\u00e3 desta quinta-feira. \u00a0O homem alegou que teria ocorrido um acidente e que n\u00e3o socorreu a v\u00edtima por receio de ser agredido por familiares.<\/div>\n<div>O ve\u00edculo envolvido no evento foi apreendido pela Pol\u00edcia Civil e passar\u00e1 por per\u00edcia. Durante os trabalhos investigativos de campo, foi poss\u00edvel identificar ao menos duas testemunhas que poder\u00e3o auxiliar no esclarecimento da ocorr\u00eancia.<\/div>\n<div>A Pol\u00edcia Civil n\u00e3o descartar nenhuma hip\u00f3tese sobre o acontecido e, apura at\u00e9 mesmo, um eventual caso de homic\u00eddio doloso, que \u00e9 aquele em que h\u00e1 a inten\u00e7\u00e3o do autor. \u00a0Contudo, como n\u00e3o havia mais situa\u00e7\u00e3o flagrancial, o investigado ap\u00f3s ser ouvido, foi liberado.<\/div>\n<div><\/div>\n<div>Fonte: Comunica\u00e7\u00e3o Social<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil, por interm\u00e9dio da Delegacia de Pol\u00edcia de Junqueir\u00f3polis, instaurou nesta quinta-feira (3), apura\u00e7\u00e3o policial visando investigar um atropelamento ocorrido na Rua Curitiba, na noite de quarta-feira (2), onde um homem de 37 anos acabou falecendo. O suspeito autoria do delito, um homem de 24 anos, havia se evadido do local ap\u00f3s o [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":74725,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[66,24],"tags":[],"class_list":["post-74724","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Policia Civil instaura inqu\u00e9rito para apurar atropelamento com v\u00edtima fatal em Junqueir\u00f3polis - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Policia Civil instaura inqu\u00e9rito para apurar atropelamento com v\u00edtima fatal em Junqueir\u00f3polis - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"A Pol\u00edcia Civil, por interm\u00e9dio da Delegacia de Pol\u00edcia de Junqueir\u00f3polis, instaurou nesta quinta-feira (3), apura\u00e7\u00e3o policial visando investigar um atropelamento ocorrido na Rua Curitiba, na noite de quarta-feira (2), onde um homem de 37 anos acabou falecendo. O suspeito autoria do delito, um homem de 24 anos, havia se evadido do local ap\u00f3s o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-04T12:13:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T14:14:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-16.38.13.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"766\" \/>\n\t<meta property=\"og:image:height\" content=\"874\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Policia Civil instaura inqu\u00e9rito para apurar atropelamento com v\u00edtima fatal em Junqueir\u00f3polis\",\"datePublished\":\"2023-08-04T12:13:07+00:00\",\"dateModified\":\"2026-05-05T14:14:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/\"},\"wordCount\":213,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-16.38.13.jpeg\",\"articleSection\":[\"Pol\u00edcia\",\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/\",\"name\":\"Policia Civil instaura inqu\u00e9rito para apurar atropelamento com v\u00edtima fatal em Junqueir\u00f3polis - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-16.38.13.jpeg\",\"datePublished\":\"2023-08-04T12:13:07+00:00\",\"dateModified\":\"2026-05-05T14:14:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-16.38.13.jpeg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-16.38.13.jpeg\",\"width\":766,\"height\":874},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Policia Civil instaura inqu\u00e9rito para apurar atropelamento com v\u00edtima fatal em Junqueir\u00f3polis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Policia Civil instaura inqu\u00e9rito para apurar atropelamento com v\u00edtima fatal em Junqueir\u00f3polis - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/","og_locale":"pt_BR","og_type":"article","og_title":"Policia Civil instaura inqu\u00e9rito para apurar atropelamento com v\u00edtima fatal em Junqueir\u00f3polis - R\u00e1dio Life FM","og_description":"A Pol\u00edcia Civil, por interm\u00e9dio da Delegacia de Pol\u00edcia de Junqueir\u00f3polis, instaurou nesta quinta-feira (3), apura\u00e7\u00e3o policial visando investigar um atropelamento ocorrido na Rua Curitiba, na noite de quarta-feira (2), onde um homem de 37 anos acabou falecendo. O suspeito autoria do delito, um homem de 24 anos, havia se evadido do local ap\u00f3s o [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2023-08-04T12:13:07+00:00","article_modified_time":"2026-05-05T14:14:14+00:00","og_image":[{"width":766,"height":874,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-16.38.13.jpeg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Policia Civil instaura inqu\u00e9rito para apurar atropelamento com v\u00edtima fatal em Junqueir\u00f3polis","datePublished":"2023-08-04T12:13:07+00:00","dateModified":"2026-05-05T14:14:14+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/"},"wordCount":213,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-16.38.13.jpeg","articleSection":["Pol\u00edcia","Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/","url":"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/","name":"Policia Civil instaura inqu\u00e9rito para apurar atropelamento com v\u00edtima fatal em Junqueir\u00f3polis - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-16.38.13.jpeg","datePublished":"2023-08-04T12:13:07+00:00","dateModified":"2026-05-05T14:14:14+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-16.38.13.jpeg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-16.38.13.jpeg","width":766,"height":874},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/policia-civil-instaura-inquerito-para-apurar-atropelamento-com-vitima-fatal-em-junqueiropolis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Policia Civil instaura inqu\u00e9rito para apurar atropelamento com v\u00edtima fatal em Junqueir\u00f3polis"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/74724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=74724"}],"version-history":[{"count":1,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/74724\/revisions"}],"predecessor-version":[{"id":74726,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/74724\/revisions\/74726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/74725"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=74724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=74724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=74724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}