{"id":74536,"date":"2023-08-01T10:30:48","date_gmt":"2023-08-01T13:30:48","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=74536"},"modified":"2026-01-22T15:49:57","modified_gmt":"2026-01-22T18:49:57","slug":"medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/","title":{"rendered":"M\u00e9dico bate carro em barranco e capota na SP-501 em Flora Rica"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Um m\u00e9dico bateu o carro que dirigia em um barranco e capotou na manh\u00e3 desta ter\u00e7a-feira (1), na Rodovia J\u00falio Budiski, a SP-501, no trecho pertencente ao munic\u00edpio de Flora Rica.<\/p>\n<p>O acidente ocorreu nas imedia\u00e7\u00f5es da Fazenda Boa Esperan\u00e7a, altura do km 62, pr\u00f3ximo da ponte.<\/p>\n<p>Segundo as primeiras informa\u00e7\u00f5es obtidas pelo jornalismo Folha Regional, o m\u00e9dico seguia pela rodovia com destino \u00e0 Dracena em um GM Tracker, quando por motivos a serem apurados, acabou perdendo o controle da dire\u00e7\u00e3o, saindo da pista e vindo a capotar o ve\u00edculo.<\/p>\n<p>Apesar do susto e danos no ve\u00edculo, ele n\u00e3o aparentava ferimentos e permaneceu consciente, orientado e em p\u00e9.<\/p>\n<p>Ele recebeu aux\u00edlio de um policial militar da reserva que seguia pela rodovia e que presenciou e que por pouco n\u00e3o se envolveu no acidente.<\/p>\n<p>Equipes de socorro e da pol\u00edcia foram acionadas para o atendimento desta ocorr\u00eancia.<\/p>\n<p>Fonte: Folha Regional<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um m\u00e9dico bateu o carro que dirigia em um barranco e capotou na manh\u00e3 desta ter\u00e7a-feira (1), na Rodovia J\u00falio Budiski, a SP-501, no trecho pertencente ao munic\u00edpio de Flora Rica. O acidente ocorreu nas imedia\u00e7\u00f5es da Fazenda Boa Esperan\u00e7a, altura do km 62, pr\u00f3ximo da ponte. Segundo as primeiras informa\u00e7\u00f5es obtidas pelo jornalismo Folha [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":74537,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-74536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e9dico bate carro em barranco e capota na SP-501 em Flora Rica - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9dico bate carro em barranco e capota na SP-501 em Flora Rica - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Um m\u00e9dico bateu o carro que dirigia em um barranco e capotou na manh\u00e3 desta ter\u00e7a-feira (1), na Rodovia J\u00falio Budiski, a SP-501, no trecho pertencente ao munic\u00edpio de Flora Rica. O acidente ocorreu nas imedia\u00e7\u00f5es da Fazenda Boa Esperan\u00e7a, altura do km 62, pr\u00f3ximo da ponte. Segundo as primeiras informa\u00e7\u00f5es obtidas pelo jornalismo Folha [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-01T13:30:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-22T18:49:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/cats-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"M\u00e9dico bate carro em barranco e capota na SP-501 em Flora Rica\",\"datePublished\":\"2023-08-01T13:30:48+00:00\",\"dateModified\":\"2026-01-22T18:49:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/\"},\"wordCount\":176,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/cats-1.jpg\",\"articleSection\":[\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/\",\"name\":\"M\u00e9dico bate carro em barranco e capota na SP-501 em Flora Rica - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/cats-1.jpg\",\"datePublished\":\"2023-08-01T13:30:48+00:00\",\"dateModified\":\"2026-01-22T18:49:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/cats-1.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/cats-1.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9dico bate carro em barranco e capota na SP-501 em Flora Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9dico bate carro em barranco e capota na SP-501 em Flora Rica - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/","og_locale":"pt_BR","og_type":"article","og_title":"M\u00e9dico bate carro em barranco e capota na SP-501 em Flora Rica - R\u00e1dio Life FM","og_description":"Um m\u00e9dico bateu o carro que dirigia em um barranco e capotou na manh\u00e3 desta ter\u00e7a-feira (1), na Rodovia J\u00falio Budiski, a SP-501, no trecho pertencente ao munic\u00edpio de Flora Rica. O acidente ocorreu nas imedia\u00e7\u00f5es da Fazenda Boa Esperan\u00e7a, altura do km 62, pr\u00f3ximo da ponte. Segundo as primeiras informa\u00e7\u00f5es obtidas pelo jornalismo Folha [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2023-08-01T13:30:48+00:00","article_modified_time":"2026-01-22T18:49:57+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/cats-1.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"M\u00e9dico bate carro em barranco e capota na SP-501 em Flora Rica","datePublished":"2023-08-01T13:30:48+00:00","dateModified":"2026-01-22T18:49:57+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/"},"wordCount":176,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/cats-1.jpg","articleSection":["Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/","url":"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/","name":"M\u00e9dico bate carro em barranco e capota na SP-501 em Flora Rica - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/cats-1.jpg","datePublished":"2023-08-01T13:30:48+00:00","dateModified":"2026-01-22T18:49:57+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/cats-1.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/08\/cats-1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/medico-bate-carro-em-barranco-e-capota-na-sp-501-em-flora-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"M\u00e9dico bate carro em barranco e capota na SP-501 em Flora Rica"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/74536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=74536"}],"version-history":[{"count":1,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/74536\/revisions"}],"predecessor-version":[{"id":74538,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/74536\/revisions\/74538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/74537"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=74536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=74536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=74536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}