{"id":71893,"date":"2023-06-10T20:41:00","date_gmt":"2023-06-10T23:41:00","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=71893"},"modified":"2026-03-28T11:03:50","modified_gmt":"2026-03-28T14:03:50","slug":"morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/","title":{"rendered":"Morador de Varpa de 18 anos morre em acidente na vicinal que liga Quintana a Bor\u00e1"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<div class=\"content\">\n<div class=\"moz-reader-content reader-show-element\">\n<div id=\"readability-page-1\" class=\"page\">\n<div>\n<p>No in\u00edcio da tarde desta sexta-feira um jovem de 18 anos conduzindo um ve\u00edculo Palio trafegava pela vicinal que liga Bor\u00e1 a Quintana, neste mesmo sentido, quando nas imedia\u00e7\u00f5es da Usina Ib\u00e9ria ele perdeu o controle da dire\u00e7\u00e3o colidindo lateralmente contra uma carreta que seguia no sentido oposto.<\/p>\n<p>Ap\u00f3s a colis\u00e3o contra a carreta o ve\u00edculo Palio rodou e colidiu violentamente contra um caminh\u00e3o carregado com amendoim, que tamb\u00e9m seguia em dire\u00e7\u00e3o a Bor\u00e1.<\/p>\n<p>Com a viol\u00eancia dos impactos o motorista do Palio morreu no local. O Corpo de Bombeiros de Paragua\u00e7u Paulista foi acionado, mas pouco pode fazer. A Pol\u00edcia Militar de Bor\u00e1 tamb\u00e9m esteve no local para registro do boletim de ocorr\u00eancia.<\/p>\n<p>De acordo com informa\u00e7\u00f5es obtidas pelo Portal Mais Tup\u00e3! o motorista da carreta relatou que percebeu que o motorista do Palio teria desfalecido pouco antes da colis\u00e3o, o que indica que ele possa ter tido um mal s\u00fabito antes do impacto.<\/p>\n<p>A v\u00edtima fatal era morador em Varpa, Rafael Novaes, de 18 anos. Ele era trabalhador rural e n\u00e3o era habilitado. A Per\u00edcia T\u00e9cnica do Instituto de Criminal\u00edstica esteve no local para determinar as causas do acidente. Nenhum dos motoristas dos caminh\u00f5es envolvidos ficaram feridos.<\/p>\n<\/div>\n<p>Fonte: Mais Tup\u00e3<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>No in\u00edcio da tarde desta sexta-feira um jovem de 18 anos conduzindo um ve\u00edculo Palio trafegava pela vicinal que liga Bor\u00e1 a Quintana, neste mesmo sentido, quando nas imedia\u00e7\u00f5es da Usina Ib\u00e9ria ele perdeu o controle da dire\u00e7\u00e3o colidindo lateralmente contra uma carreta que seguia no sentido oposto. Ap\u00f3s a colis\u00e3o contra a carreta o [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":71894,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-71893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Morador de Varpa de 18 anos morre em acidente na vicinal que liga Quintana a Bor\u00e1 - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Morador de Varpa de 18 anos morre em acidente na vicinal que liga Quintana a Bor\u00e1 - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"No in\u00edcio da tarde desta sexta-feira um jovem de 18 anos conduzindo um ve\u00edculo Palio trafegava pela vicinal que liga Bor\u00e1 a Quintana, neste mesmo sentido, quando nas imedia\u00e7\u00f5es da Usina Ib\u00e9ria ele perdeu o controle da dire\u00e7\u00e3o colidindo lateralmente contra uma carreta que seguia no sentido oposto. Ap\u00f3s a colis\u00e3o contra a carreta o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-10T23:41:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-28T14:03:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/06\/mais.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"838\" \/>\n\t<meta property=\"og:image:height\" content=\"475\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Morador de Varpa de 18 anos morre em acidente na vicinal que liga Quintana a Bor\u00e1\",\"datePublished\":\"2023-06-10T23:41:00+00:00\",\"dateModified\":\"2026-03-28T14:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/\"},\"wordCount\":240,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/06\/mais.jpg\",\"articleSection\":[\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/\",\"name\":\"Morador de Varpa de 18 anos morre em acidente na vicinal que liga Quintana a Bor\u00e1 - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/06\/mais.jpg\",\"datePublished\":\"2023-06-10T23:41:00+00:00\",\"dateModified\":\"2026-03-28T14:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/06\/mais.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/06\/mais.jpg\",\"width\":838,\"height\":475},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Morador de Varpa de 18 anos morre em acidente na vicinal que liga Quintana a Bor\u00e1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Morador de Varpa de 18 anos morre em acidente na vicinal que liga Quintana a Bor\u00e1 - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/","og_locale":"pt_BR","og_type":"article","og_title":"Morador de Varpa de 18 anos morre em acidente na vicinal que liga Quintana a Bor\u00e1 - R\u00e1dio Life FM","og_description":"No in\u00edcio da tarde desta sexta-feira um jovem de 18 anos conduzindo um ve\u00edculo Palio trafegava pela vicinal que liga Bor\u00e1 a Quintana, neste mesmo sentido, quando nas imedia\u00e7\u00f5es da Usina Ib\u00e9ria ele perdeu o controle da dire\u00e7\u00e3o colidindo lateralmente contra uma carreta que seguia no sentido oposto. Ap\u00f3s a colis\u00e3o contra a carreta o [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2023-06-10T23:41:00+00:00","article_modified_time":"2026-03-28T14:03:50+00:00","og_image":[{"width":838,"height":475,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/06\/mais.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Morador de Varpa de 18 anos morre em acidente na vicinal que liga Quintana a Bor\u00e1","datePublished":"2023-06-10T23:41:00+00:00","dateModified":"2026-03-28T14:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/"},"wordCount":240,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/06\/mais.jpg","articleSection":["Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/","url":"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/","name":"Morador de Varpa de 18 anos morre em acidente na vicinal que liga Quintana a Bor\u00e1 - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/06\/mais.jpg","datePublished":"2023-06-10T23:41:00+00:00","dateModified":"2026-03-28T14:03:50+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/06\/mais.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/06\/mais.jpg","width":838,"height":475},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/morador-de-varpa-de-18-anos-morre-em-acidente-na-vicinal-que-liga-quintana-a-bora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Morador de Varpa de 18 anos morre em acidente na vicinal que liga Quintana a Bor\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/71893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=71893"}],"version-history":[{"count":2,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/71893\/revisions"}],"predecessor-version":[{"id":71896,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/71893\/revisions\/71896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/71894"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=71893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=71893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=71893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}