{"id":70519,"date":"2023-05-19T13:34:01","date_gmt":"2023-05-19T16:34:01","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=70519"},"modified":"2025-10-06T13:55:32","modified_gmt":"2025-10-06T16:55:32","slug":"novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/","title":{"rendered":"Novos radares entram em opera\u00e7\u00e3o a partir de quarta-feira dia 24 em \u00e1rea da EIXO SP"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Treze novos radares entrar\u00e3o em opera\u00e7\u00e3o a partir de quarta-feira (24) em seis rodovias administradas pela Eixo SP. A autoriza\u00e7\u00e3o de funcionamento ocorre ap\u00f3s homologa\u00e7\u00e3o dos equipamentos realizada pelo Departamento de Estradas de Rodagem (DER), \u00f3rg\u00e3o respons\u00e1vel pela aplica\u00e7\u00e3o das multas.<\/p>\n<p>A maior parte dos aparelhos que entrar\u00e3o em funcionamento est\u00e3o instalados na SP 310 \u2013 Rodovia Washington Lu\u00eds, no trecho entre o km 161+300, em Cordeir\u00f3polis, e o km 180+350, em Rio Claro. Neste trecho, ser\u00e3o cinco novos radares em opera\u00e7\u00e3o (veja rela\u00e7\u00e3o abaixo). Outras tr\u00eas rodovias ter\u00e3o dois equipamentos em funcionamento em cada uma.<\/p>\n<p>Na SP 304 \u2013 Rodovia Luiz de Queiroz, em Piracicaba, os radares est\u00e3o no km 169+320 e km 170+200. Na SP 225 \u2013 Rodovia Comandante Jo\u00e3o Ribeiro de Barros, os aparelhos est\u00e3o no km 180+050 e no km 181+700, no trecho urbano de Ja\u00fa. E na SP 261 \u2013 Rodovia C\u00e9sar Augusto Sgavioli, em Pederneiras, os equipamentos est\u00e3o instalados no km 151+600 e no km 152+100.<\/p>\n<p>Por fim, entrar\u00e3o em opera\u00e7\u00e3o na pr\u00f3xima quarta-feira os radares que est\u00e3o instalados na SP 191 \u2013 Rodovia Irineu Penteado, no km 82+620, pr\u00f3ximo a Ipe\u00fana, e na SP 425 \u2013 Rodovia Assis Chateaubriand, no km 437, pr\u00f3ximo ao trevo de acesso ao munic\u00edpio de Indiana. Outros equipamentos est\u00e3o aguardando homologa\u00e7\u00e3o do DER e o in\u00edcio de opera\u00e7\u00e3o deve ser anunciado em breve.<\/p>\n<p>Segundo a coordenadora de Seguran\u00e7a Vi\u00e1ria da Eixo SP, Viviane Riveli de Carvalho, a instala\u00e7\u00e3o e a opera\u00e7\u00e3o dos equipamentos atendem a uma determina\u00e7\u00e3o do contrato de concess\u00e3o, al\u00e9m de ser uma importante ferramenta para garantir a seguran\u00e7a do usu\u00e1rio por meio da fiscaliza\u00e7\u00e3o da velocidade m\u00e1xima permitida na rodovia.<\/p>\n<h4><strong>Localiza\u00e7\u00e3o dos novos radares<\/strong><\/h4>\n<p>SP 191 \u2013 km 082+620 (pista sentido leste e oeste) \u2013 Ipe\u00fana<\/p>\n<p>SP 225 \u2013 km 180+050 (pista sentido oeste) \u2013 Ja\u00fa<\/p>\n<p>SP 225 \u2013 km 181+700 (pista sentido oeste) \u2013 Ja\u00fa<\/p>\n<p>SP 261 \u2013 km 151+600 (pista sentido norte e sul) \u2013 Pederneiras<\/p>\n<p>SP 261 \u2013 km 152+100 (pista sentido norte e sul) \u2013 Pederneiras<\/p>\n<p>SP 304 \u2013 km 169+320 (pista sentido leste) \u2013 Piracicaba<\/p>\n<p>SP 304 \u2013 km 170+200 (pista sentido leste) \u2013 Piracicaba<\/p>\n<p>SP 310 \u2013 km 161+300 (pista sentido sul) \u2013 Cordeir\u00f3polis<\/p>\n<p>SP 310 \u2013 km 161+750 (pista sentido norte) \u2013 Cordeir\u00f3polis<\/p>\n<p>SP 310 \u2013 km 164+600 (pista sentido sul) \u2013 Santa Gertrudes<\/p>\n<p>SP 310 \u2013 km 176+400 (pista sentido sul) \u2013 Rio Claro<\/p>\n<p>SP 310 \u2013 km 180+350 (pista sentido norte) \u2013 Rio Claro<\/p>\n<p>SP 425 \u2013 km 437+000 (pista sentido norte) \u2013 Indiana<\/p>\n<h4><strong>\u00a0<\/strong><strong>Sobre a Eixo SP<\/strong><\/h4>\n<p>A Eixo SP Concession\u00e1ria de Rodovias administra mais de 1.221 km de estradas que passam por 62 munic\u00edpios da regi\u00e3o de Rio Claro, no centro do Estado, at\u00e9 Panorama, no extremo oeste, na divisa com o Mato Grosso do Sul. O maior contrato sob supervis\u00e3o da Artesp (Ag\u00eancia Reguladora de Transportes do Estado de S\u00e3o Paulo) ter\u00e1 investimentos na ordem de R$ 14 bilh\u00f5es em obras de amplia\u00e7\u00e3o, conserva\u00e7\u00e3o, al\u00e9m da moderniza\u00e7\u00e3o de servi\u00e7os ao usu\u00e1rio. Para mais informa\u00e7\u00f5es acesse:\u00a0<a href=\"https:\/\/www.eixosp.com.br\/\">www.eixosp.com.br<\/a>.<\/p>\n<p>Assessoria<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Treze novos radares entrar\u00e3o em opera\u00e7\u00e3o a partir de quarta-feira (24) em seis rodovias administradas pela Eixo SP. A autoriza\u00e7\u00e3o de funcionamento ocorre ap\u00f3s homologa\u00e7\u00e3o dos equipamentos realizada pelo Departamento de Estradas de Rodagem (DER), \u00f3rg\u00e3o respons\u00e1vel pela aplica\u00e7\u00e3o das multas. A maior parte dos aparelhos que entrar\u00e3o em funcionamento est\u00e3o instalados na SP 310 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":70521,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-70519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Novos radares entram em opera\u00e7\u00e3o a partir de quarta-feira dia 24 em \u00e1rea da EIXO SP - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novos radares entram em opera\u00e7\u00e3o a partir de quarta-feira dia 24 em \u00e1rea da EIXO SP - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Treze novos radares entrar\u00e3o em opera\u00e7\u00e3o a partir de quarta-feira (24) em seis rodovias administradas pela Eixo SP. A autoriza\u00e7\u00e3o de funcionamento ocorre ap\u00f3s homologa\u00e7\u00e3o dos equipamentos realizada pelo Departamento de Estradas de Rodagem (DER), \u00f3rg\u00e3o respons\u00e1vel pela aplica\u00e7\u00e3o das multas. A maior parte dos aparelhos que entrar\u00e3o em funcionamento est\u00e3o instalados na SP 310 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-19T16:34:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-06T16:55:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/SP-310-Washington-Luis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1805\" \/>\n\t<meta property=\"og:image:height\" content=\"1107\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"joaograndao\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"joaograndao\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/\"},\"author\":{\"name\":\"joaograndao\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6876e1240feffe6e1b63fd5cb85abf28\"},\"headline\":\"Novos radares entram em opera\u00e7\u00e3o a partir de quarta-feira dia 24 em \u00e1rea da EIXO SP\",\"datePublished\":\"2023-05-19T16:34:01+00:00\",\"dateModified\":\"2025-10-06T16:55:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/\"},\"wordCount\":509,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/SP-310-Washington-Luis.jpg\",\"articleSection\":[\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/\",\"name\":\"Novos radares entram em opera\u00e7\u00e3o a partir de quarta-feira dia 24 em \u00e1rea da EIXO SP - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/SP-310-Washington-Luis.jpg\",\"datePublished\":\"2023-05-19T16:34:01+00:00\",\"dateModified\":\"2025-10-06T16:55:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/SP-310-Washington-Luis.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/SP-310-Washington-Luis.jpg\",\"width\":1805,\"height\":1107,\"caption\":\"Equipamentos instalados em seis rodovias administradas pela Eixo SP tiveram funcionamento homologado pelo DER\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novos radares entram em opera\u00e7\u00e3o a partir de quarta-feira dia 24 em \u00e1rea da EIXO SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6876e1240feffe6e1b63fd5cb85abf28\",\"name\":\"joaograndao\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d5b1a3cf357ed9c50404e256a1294083aa8ab5d2a994001567302786016cb32c?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d5b1a3cf357ed9c50404e256a1294083aa8ab5d2a994001567302786016cb32c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d5b1a3cf357ed9c50404e256a1294083aa8ab5d2a994001567302786016cb32c?s=96&d=mm&r=g\",\"caption\":\"joaograndao\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novos radares entram em opera\u00e7\u00e3o a partir de quarta-feira dia 24 em \u00e1rea da EIXO SP - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Novos radares entram em opera\u00e7\u00e3o a partir de quarta-feira dia 24 em \u00e1rea da EIXO SP - R\u00e1dio Life FM","og_description":"Treze novos radares entrar\u00e3o em opera\u00e7\u00e3o a partir de quarta-feira (24) em seis rodovias administradas pela Eixo SP. A autoriza\u00e7\u00e3o de funcionamento ocorre ap\u00f3s homologa\u00e7\u00e3o dos equipamentos realizada pelo Departamento de Estradas de Rodagem (DER), \u00f3rg\u00e3o respons\u00e1vel pela aplica\u00e7\u00e3o das multas. A maior parte dos aparelhos que entrar\u00e3o em funcionamento est\u00e3o instalados na SP 310 [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2023-05-19T16:34:01+00:00","article_modified_time":"2025-10-06T16:55:32+00:00","og_image":[{"width":1805,"height":1107,"url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/SP-310-Washington-Luis.jpg","type":"image\/jpeg"}],"author":"joaograndao","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"joaograndao","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/"},"author":{"name":"joaograndao","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6876e1240feffe6e1b63fd5cb85abf28"},"headline":"Novos radares entram em opera\u00e7\u00e3o a partir de quarta-feira dia 24 em \u00e1rea da EIXO SP","datePublished":"2023-05-19T16:34:01+00:00","dateModified":"2025-10-06T16:55:32+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/"},"wordCount":509,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/SP-310-Washington-Luis.jpg","articleSection":["Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/","url":"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/","name":"Novos radares entram em opera\u00e7\u00e3o a partir de quarta-feira dia 24 em \u00e1rea da EIXO SP - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/SP-310-Washington-Luis.jpg","datePublished":"2023-05-19T16:34:01+00:00","dateModified":"2025-10-06T16:55:32+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/SP-310-Washington-Luis.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/SP-310-Washington-Luis.jpg","width":1805,"height":1107,"caption":"Equipamentos instalados em seis rodovias administradas pela Eixo SP tiveram funcionamento homologado pelo DER"},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/novos-radares-entram-em-operacao-a-partir-de-quarta-feira-dia-24-em-area-da-eixo-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Novos radares entram em opera\u00e7\u00e3o a partir de quarta-feira dia 24 em \u00e1rea da EIXO SP"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6876e1240feffe6e1b63fd5cb85abf28","name":"joaograndao","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d5b1a3cf357ed9c50404e256a1294083aa8ab5d2a994001567302786016cb32c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5b1a3cf357ed9c50404e256a1294083aa8ab5d2a994001567302786016cb32c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5b1a3cf357ed9c50404e256a1294083aa8ab5d2a994001567302786016cb32c?s=96&d=mm&r=g","caption":"joaograndao"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/70519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=70519"}],"version-history":[{"count":2,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/70519\/revisions"}],"predecessor-version":[{"id":70522,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/70519\/revisions\/70522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/70521"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=70519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=70519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=70519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}