{"id":69944,"date":"2023-05-11T08:35:07","date_gmt":"2023-05-11T11:35:07","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=69944"},"modified":"2026-05-12T22:04:47","modified_gmt":"2026-05-13T01:04:47","slug":"mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/","title":{"rendered":"Mais de 770 tabletes de maconha s\u00e3o apreendidos escondidos em pneus de carreta"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Uma opera\u00e7\u00e3o conjunta da Pol\u00edcia Federal e da Pol\u00edcia Militar Rodovi\u00e1ria prendeu um homem, de 23 anos, e apreendeu mais de 770 tabletes de maconha, escondidos em pneus, no km 81 da Rodovia Brigadeiro Eduardo Gomes (SP-457), em\u00a0<b><a style=\"font-style: inherit\" href=\"https:\/\/g1.globo.com\/sp\/presidente-prudente-regiao\/cidade\/rancharia\/\">Rancharia (SP)<\/a><\/b>, nesta quarta-feira (10).<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Conforme a Pol\u00edcia Federal, uma carreta do Paraguai foi abordada e, \u201cdiante de informa\u00e7\u00f5es desencontradas e contradit\u00f3rias do motorista, os policiais resolveram vistoriar minuciosamente o caminh\u00e3o\u201d.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Durante a vistoria,\u00a0<b><strong style=\"font-style: inherit\">771 tabletes de maconha foram localizados dentro de 12 pneus que estavam com os eixos suspensos<\/strong><\/b>.<\/p>\n<p>Ainda segundo a PF, o motorista disse que pegou o caminh\u00e3o \u201cj\u00e1 carregado com a droga\u201d, em\u00a0<b><a style=\"font-style: inherit\" href=\"https:\/\/g1.globo.com\/pr\/oeste-sudoeste\/cidade\/foz-do-iguacu\/\">Foz do Igua\u00e7u (PR)<\/a><\/b>\u00a0e ainda citou que \u201cdeixaria a droga\u201d em\u00a0<b><a style=\"font-style: inherit\" href=\"https:\/\/g1.globo.com\/mg\/triangulo-mineiro\/cidade\/uberlandia\/\">Uberl\u00e2ndia (MG)<\/a><\/b>.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">O homem, que carregava uma identidade do Paraguai, foi preso em flagrante por tr\u00e1fico de drogas. Ele foi conduzido \u00e0 Delegacia de Pol\u00edcia Federal, em\u00a0<b><a style=\"font-style: inherit\" href=\"https:\/\/g1.globo.com\/sp\/presidente-prudente-regiao\/cidade\/presidente-prudente\/\">Presidente Prudente (SP)<\/a><\/b>, e ficar\u00e1 \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">A droga deve ser passar por pesagem, portanto, ainda n\u00e3o existe uma estimativa da quantia, em quilos, apreendida.<\/p>\n<div class='flex flex-wrap items-center -mx-1'>\r\n<a class='thumbnail gallery p-1 w-1\/2 md:w-1\/4' href='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/p1.jpg'><img class='border border-white' src='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/p1-200x200.jpg' alt='P1' \/><\/a><a class='thumbnail gallery p-1 w-1\/2 md:w-1\/4' href='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/p2.jpg'><img class='border border-white' src='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/p2-200x200.jpg' alt='P2' \/><\/a><\/div>\n<p>Fonte: G1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma opera\u00e7\u00e3o conjunta da Pol\u00edcia Federal e da Pol\u00edcia Militar Rodovi\u00e1ria prendeu um homem, de 23 anos, e apreendeu mais de 770 tabletes de maconha, escondidos em pneus, no km 81 da Rodovia Brigadeiro Eduardo Gomes (SP-457), em\u00a0Rancharia (SP), nesta quarta-feira (10). Conforme a Pol\u00edcia Federal, uma carreta do Paraguai foi abordada e, \u201cdiante de [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":69945,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[66,24],"tags":[],"class_list":["post-69944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mais de 770 tabletes de maconha s\u00e3o apreendidos escondidos em pneus de carreta - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mais de 770 tabletes de maconha s\u00e3o apreendidos escondidos em pneus de carreta - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Uma opera\u00e7\u00e3o conjunta da Pol\u00edcia Federal e da Pol\u00edcia Militar Rodovi\u00e1ria prendeu um homem, de 23 anos, e apreendeu mais de 770 tabletes de maconha, escondidos em pneus, no km 81 da Rodovia Brigadeiro Eduardo Gomes (SP-457), em\u00a0Rancharia (SP), nesta quarta-feira (10). Conforme a Pol\u00edcia Federal, uma carreta do Paraguai foi abordada e, \u201cdiante de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-11T11:35:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T01:04:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/mac.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"984\" \/>\n\t<meta property=\"og:image:height\" content=\"738\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Mais de 770 tabletes de maconha s\u00e3o apreendidos escondidos em pneus de carreta\",\"datePublished\":\"2023-05-11T11:35:07+00:00\",\"dateModified\":\"2026-05-13T01:04:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/\"},\"wordCount\":199,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/mac.jpg\",\"articleSection\":[\"Pol\u00edcia\",\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/\",\"name\":\"Mais de 770 tabletes de maconha s\u00e3o apreendidos escondidos em pneus de carreta - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/mac.jpg\",\"datePublished\":\"2023-05-11T11:35:07+00:00\",\"dateModified\":\"2026-05-13T01:04:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/mac.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/mac.jpg\",\"width\":984,\"height\":738,\"caption\":\"A\u00e7\u00e3o conjunta das pol\u00edcias Federal e Rodovi\u00e1ria foi registrada nesta quarta-feira (10), em Rancharia (SP).\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mais de 770 tabletes de maconha s\u00e3o apreendidos escondidos em pneus de carreta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mais de 770 tabletes de maconha s\u00e3o apreendidos escondidos em pneus de carreta - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/","og_locale":"pt_BR","og_type":"article","og_title":"Mais de 770 tabletes de maconha s\u00e3o apreendidos escondidos em pneus de carreta - R\u00e1dio Life FM","og_description":"Uma opera\u00e7\u00e3o conjunta da Pol\u00edcia Federal e da Pol\u00edcia Militar Rodovi\u00e1ria prendeu um homem, de 23 anos, e apreendeu mais de 770 tabletes de maconha, escondidos em pneus, no km 81 da Rodovia Brigadeiro Eduardo Gomes (SP-457), em\u00a0Rancharia (SP), nesta quarta-feira (10). Conforme a Pol\u00edcia Federal, uma carreta do Paraguai foi abordada e, \u201cdiante de [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2023-05-11T11:35:07+00:00","article_modified_time":"2026-05-13T01:04:47+00:00","og_image":[{"width":984,"height":738,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/mac.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Mais de 770 tabletes de maconha s\u00e3o apreendidos escondidos em pneus de carreta","datePublished":"2023-05-11T11:35:07+00:00","dateModified":"2026-05-13T01:04:47+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/"},"wordCount":199,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/mac.jpg","articleSection":["Pol\u00edcia","Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/","url":"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/","name":"Mais de 770 tabletes de maconha s\u00e3o apreendidos escondidos em pneus de carreta - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/mac.jpg","datePublished":"2023-05-11T11:35:07+00:00","dateModified":"2026-05-13T01:04:47+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/mac.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/05\/mac.jpg","width":984,"height":738,"caption":"A\u00e7\u00e3o conjunta das pol\u00edcias Federal e Rodovi\u00e1ria foi registrada nesta quarta-feira (10), em Rancharia (SP)."},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/mais-de-770-tabletes-de-maconha-sao-apreendidos-escondidos-em-pneus-de-carreta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Mais de 770 tabletes de maconha s\u00e3o apreendidos escondidos em pneus de carreta"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/69944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=69944"}],"version-history":[{"count":4,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/69944\/revisions"}],"predecessor-version":[{"id":69951,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/69944\/revisions\/69951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/69945"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=69944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=69944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=69944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}