{"id":66738,"date":"2023-03-19T20:09:10","date_gmt":"2023-03-19T23:09:10","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=66738"},"modified":"2025-10-08T23:49:04","modified_gmt":"2025-10-09T02:49:04","slug":"muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/","title":{"rendered":"Muro desaba sobre tr\u00eas casas em Osvaldo Cruz; Defesa Civil alertou antes e ningu\u00e9m se feriu"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<div class=\"texto-descricao\">\n<p>A Defesa Civil de Osvaldo Cruz\u00a0 informa que houve neste domingo (19) um desabamento de um muro sobre tr\u00eas casas no Conjunto Habitacional Alberto Lang. Felizmente n\u00e3o houve v\u00edtimas, gra\u00e7as ao trabalho de acompanhamento realizado dias antes do fato e onde fam\u00edlias foram alertadas para o risco.<\/p>\n<p>O muro que desabou estava localizado na Rua Moacir Salvadeo altura do n\u00famero 182 e as casas afetadas est\u00e3o localizadas na Rua Professora Solange Albino, ambos no mesmo Conjunto Alberto Lang.<\/p>\n<p>As fam\u00edlias afetadas j\u00e1 haviam sido orientadas a sair de suas casas pela pr\u00f3pria Defesa Civil desde a \u00faltima sexta-feira, 17. Uma equipe t\u00e9cnica, liderada pelo arquiteto Guilherme Vinicius Zonato de Oliveira, com t\u00e9cnicos do setor de Obras e Engenharia da Prefeitura\u00a0e outros brigadistas, esteve em algumas resid\u00eancias localizadas na Rua Solange Mauro Albino, no Bairro Alberto Lang.<\/p>\n<p>Devido aos riscos estruturais identificados, a equipe interditou algumas resid\u00eancias e realojou os moradores, evitando assim uma poss\u00edvel trag\u00e9dia. Desde ent\u00e3o, a Defesa Civil monitorou a \u00e1rea e tomou todas as provid\u00eancias necess\u00e1rias para garantir a seguran\u00e7a das fam\u00edlias afetadas.<\/p>\n<p>Agora, a Defesa Civil trabalha para identificar a causa do desabamento, que pode estar relacionada a problemas na infraestrutura do bairro, como obras malfeitas. O setor de Assist\u00eancia Social do Munic\u00edpio se encarregou do abrigamento das tr\u00eas fam\u00edlias desalojadas.<\/p>\n<p>A equipe da Defesa Civil, em conjunto com o Executivo Municipal, vai se reunir para definir as pr\u00f3ximas a\u00e7\u00f5es que ser\u00e3o tomadas para apoiar as fam\u00edlias afetadas. As fam\u00edlias da casa parcialmente interditada j\u00e1 foi alocada em um hotel, enquanto a outra fam\u00edlia est\u00e1 hospedada na casa de um parente.<\/p>\n<p>A Defesa Civil pede \u00e0 popula\u00e7\u00e3o que fique atenta \u00e0s orienta\u00e7\u00f5es e evite transitar pela \u00e1rea afetada. Qualquer informa\u00e7\u00e3o adicional ser\u00e1 divulgada pela Defesa Civil de Osvaldo Cruz.<\/p>\n<div class='flex flex-wrap items-center -mx-1'>\r\n<a class='thumbnail gallery p-1 w-1\/2 md:w-1\/4' href='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142001jpg167924852564174c8d457df.jpg'><img class='border border-white' src='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142001jpg167924852564174c8d457df-200x200.jpg' alt='Whatsapp Image 20230319 At 142001jpg167924852564174c8d457df' \/><\/a><a class='thumbnail gallery p-1 w-1\/2 md:w-1\/4' href='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142005jpg167924847864174c5e6f275.jpg'><img class='border border-white' src='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142005jpg167924847864174c5e6f275-200x200.jpg' alt='Whatsapp Image 20230319 At 142005jpg167924847864174c5e6f275' \/><\/a><a class='thumbnail gallery p-1 w-1\/2 md:w-1\/4' href='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142007jpeg167924842064174c2459532-1.jpeg'><img class='border border-white' src='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142007jpeg167924842064174c2459532-1-200x200.jpeg' alt='Whatsapp Image 20230319 At 142007jpeg167924842064174c2459532' \/><\/a><\/div>\n<div class=\"clearfix\">Fonte: OCNET<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Defesa Civil de Osvaldo Cruz\u00a0 informa que houve neste domingo (19) um desabamento de um muro sobre tr\u00eas casas no Conjunto Habitacional Alberto Lang. Felizmente n\u00e3o houve v\u00edtimas, gra\u00e7as ao trabalho de acompanhamento realizado dias antes do fato e onde fam\u00edlias foram alertadas para o risco. O muro que desabou estava localizado na Rua [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":66739,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-66738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Muro desaba sobre tr\u00eas casas em Osvaldo Cruz; Defesa Civil alertou antes e ningu\u00e9m se feriu - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Muro desaba sobre tr\u00eas casas em Osvaldo Cruz; Defesa Civil alertou antes e ningu\u00e9m se feriu - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"A Defesa Civil de Osvaldo Cruz\u00a0 informa que houve neste domingo (19) um desabamento de um muro sobre tr\u00eas casas no Conjunto Habitacional Alberto Lang. Felizmente n\u00e3o houve v\u00edtimas, gra\u00e7as ao trabalho de acompanhamento realizado dias antes do fato e onde fam\u00edlias foram alertadas para o risco. O muro que desabou estava localizado na Rua [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-19T23:09:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T02:49:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142007jpeg167924842064174c2459532.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"337\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Muro desaba sobre tr\u00eas casas em Osvaldo Cruz; Defesa Civil alertou antes e ningu\u00e9m se feriu\",\"datePublished\":\"2023-03-19T23:09:10+00:00\",\"dateModified\":\"2025-10-09T02:49:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/\"},\"wordCount\":347,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142007jpeg167924842064174c2459532.jpeg\",\"articleSection\":[\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/\",\"name\":\"Muro desaba sobre tr\u00eas casas em Osvaldo Cruz; Defesa Civil alertou antes e ningu\u00e9m se feriu - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142007jpeg167924842064174c2459532.jpeg\",\"datePublished\":\"2023-03-19T23:09:10+00:00\",\"dateModified\":\"2025-10-09T02:49:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142007jpeg167924842064174c2459532.jpeg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142007jpeg167924842064174c2459532.jpeg\",\"width\":600,\"height\":337,\"caption\":\"A\u00e7\u00e3o da Defesa Civil na sexta-feira evitou trag\u00e9dia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Muro desaba sobre tr\u00eas casas em Osvaldo Cruz; Defesa Civil alertou antes e ningu\u00e9m se feriu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Muro desaba sobre tr\u00eas casas em Osvaldo Cruz; Defesa Civil alertou antes e ningu\u00e9m se feriu - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/","og_locale":"pt_BR","og_type":"article","og_title":"Muro desaba sobre tr\u00eas casas em Osvaldo Cruz; Defesa Civil alertou antes e ningu\u00e9m se feriu - R\u00e1dio Life FM","og_description":"A Defesa Civil de Osvaldo Cruz\u00a0 informa que houve neste domingo (19) um desabamento de um muro sobre tr\u00eas casas no Conjunto Habitacional Alberto Lang. Felizmente n\u00e3o houve v\u00edtimas, gra\u00e7as ao trabalho de acompanhamento realizado dias antes do fato e onde fam\u00edlias foram alertadas para o risco. O muro que desabou estava localizado na Rua [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2023-03-19T23:09:10+00:00","article_modified_time":"2025-10-09T02:49:04+00:00","og_image":[{"width":600,"height":337,"url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142007jpeg167924842064174c2459532.jpeg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Muro desaba sobre tr\u00eas casas em Osvaldo Cruz; Defesa Civil alertou antes e ningu\u00e9m se feriu","datePublished":"2023-03-19T23:09:10+00:00","dateModified":"2025-10-09T02:49:04+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/"},"wordCount":347,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142007jpeg167924842064174c2459532.jpeg","articleSection":["Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/","url":"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/","name":"Muro desaba sobre tr\u00eas casas em Osvaldo Cruz; Defesa Civil alertou antes e ningu\u00e9m se feriu - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142007jpeg167924842064174c2459532.jpeg","datePublished":"2023-03-19T23:09:10+00:00","dateModified":"2025-10-09T02:49:04+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142007jpeg167924842064174c2459532.jpeg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/03\/whatsapp-image-20230319-at-142007jpeg167924842064174c2459532.jpeg","width":600,"height":337,"caption":"A\u00e7\u00e3o da Defesa Civil na sexta-feira evitou trag\u00e9dia"},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/muro-desaba-sobre-tres-casas-em-osvaldo-cruz-defesa-civil-alertou-antes-e-ninguem-se-feriu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Muro desaba sobre tr\u00eas casas em Osvaldo Cruz; Defesa Civil alertou antes e ningu\u00e9m se feriu"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/66738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=66738"}],"version-history":[{"count":2,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/66738\/revisions"}],"predecessor-version":[{"id":66744,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/66738\/revisions\/66744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/66739"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=66738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=66738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=66738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}