{"id":65262,"date":"2023-02-14T20:11:12","date_gmt":"2023-02-14T23:11:12","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=65262"},"modified":"2026-05-08T19:40:55","modified_gmt":"2026-05-08T22:40:55","slug":"traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/","title":{"rendered":"Traficante em liberdade condicional volta a ser preso durante opera\u00e7\u00e3o policial em Rin\u00f3polis"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>A Pol\u00edcia Civil prendeu nesta ter\u00e7a-feira (14) um homem, de 42 anos, suspeito de tr\u00e1fico de drogas, em\u00a0<b><a style=\"font-style: inherit\" href=\"https:\/\/g1.globo.com\/sp\/presidente-prudente-regiao\/cidade\/rinopolis\/\">Rin\u00f3polis (SP)<\/a><\/b>.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">As investiga\u00e7\u00f5es indicaram que o suspeito, que recentemente havia sido colocado em liberdade, dava continuidade \u00e0 venda de entorpecentes e identificaram dois im\u00f3veis onde ele comercializava drogas.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Com isso, os policiais cumpriram o mandado judicial de busca nas resid\u00eancias previamente identificadas.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">No Jardim Cana\u00e3, os policiais encontraram o suspeito e durante as buscas apreenderam um tablete de maconha, uma por\u00e7\u00e3o de coca\u00edna, dinheiro e contas de energia e \u00e1gua de uma outra resid\u00eancia localizada na Cohab M\u00e1rio Covas. Neste outro local, tamb\u00e9m recolheram coca\u00edna, maconha e crack, j\u00e1 embalados na forma pr\u00f3pria para o com\u00e9rcio, al\u00e9m de dinheiro e material para acondicionar as drogas.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">O preso foi autuado em flagrante pelo crime de tr\u00e1fico de drogas e ser\u00e1 apresentado \u00e0 Justi\u00e7a em audi\u00eancia de cust\u00f3dia.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">Ainda segundo a Pol\u00edcia Civil, ele j\u00e1 havia sido preso em outras duas oportunidades tamb\u00e9m por tr\u00e1fico de drogas e antes do flagrante nesta ter\u00e7a-feira (14) encontrava-se em liberdade condicional.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">No total, a opera\u00e7\u00e3o, que contou com o envolvimento de policiais de Rin\u00f3polis e o apoio de outras unidades vinculadas \u00e0 Delegacia Seccional de\u00a0<b><a style=\"font-style: inherit\" href=\"https:\/\/g1.globo.com\/sp\/bauru-marilia\/cidade\/tupa\/\">Tup\u00e3 (SP)<\/a><\/b>, resultou na apreens\u00e3o de R$ 315 em dinheiro e cerca de 300 gramas de drogas.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: G1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil prendeu nesta ter\u00e7a-feira (14) um homem, de 42 anos, suspeito de tr\u00e1fico de drogas, em\u00a0Rin\u00f3polis (SP). As investiga\u00e7\u00f5es indicaram que o suspeito, que recentemente havia sido colocado em liberdade, dava continuidade \u00e0 venda de entorpecentes e identificaram dois im\u00f3veis onde ele comercializava drogas. Com isso, os policiais cumpriram o mandado judicial de [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":65263,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-65262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiao"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Traficante em liberdade condicional volta a ser preso durante opera\u00e7\u00e3o policial em Rin\u00f3polis - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traficante em liberdade condicional volta a ser preso durante opera\u00e7\u00e3o policial em Rin\u00f3polis - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"A Pol\u00edcia Civil prendeu nesta ter\u00e7a-feira (14) um homem, de 42 anos, suspeito de tr\u00e1fico de drogas, em\u00a0Rin\u00f3polis (SP). As investiga\u00e7\u00f5es indicaram que o suspeito, que recentemente havia sido colocado em liberdade, dava continuidade \u00e0 venda de entorpecentes e identificaram dois im\u00f3veis onde ele comercializava drogas. Com isso, os policiais cumpriram o mandado judicial de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-14T23:11:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T22:40:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/02\/pol-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"984\" \/>\n\t<meta property=\"og:image:height\" content=\"886\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Traficante em liberdade condicional volta a ser preso durante opera\u00e7\u00e3o policial em Rin\u00f3polis\",\"datePublished\":\"2023-02-14T23:11:12+00:00\",\"dateModified\":\"2026-05-08T22:40:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/\"},\"wordCount\":254,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/02\/pol-1.jpg\",\"articleSection\":[\"Regi\u00e3o\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/\",\"name\":\"Traficante em liberdade condicional volta a ser preso durante opera\u00e7\u00e3o policial em Rin\u00f3polis - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/02\/pol-1.jpg\",\"datePublished\":\"2023-02-14T23:11:12+00:00\",\"dateModified\":\"2026-05-08T22:40:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/02\/pol-1.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/02\/pol-1.jpg\",\"width\":984,\"height\":886,\"caption\":\"Pol\u00edcia Civil cumpriu mandado judicial de busca, nesta ter\u00e7a-feira (14), em resid\u00eancias no Jardim Cana\u00e3 e na Cohab M\u00e1rio Covas, e apreendeu por\u00e7\u00f5es de coca\u00edna, crack e maconha.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Traficante em liberdade condicional volta a ser preso durante opera\u00e7\u00e3o policial em Rin\u00f3polis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Traficante em liberdade condicional volta a ser preso durante opera\u00e7\u00e3o policial em Rin\u00f3polis - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/","og_locale":"pt_BR","og_type":"article","og_title":"Traficante em liberdade condicional volta a ser preso durante opera\u00e7\u00e3o policial em Rin\u00f3polis - R\u00e1dio Life FM","og_description":"A Pol\u00edcia Civil prendeu nesta ter\u00e7a-feira (14) um homem, de 42 anos, suspeito de tr\u00e1fico de drogas, em\u00a0Rin\u00f3polis (SP). As investiga\u00e7\u00f5es indicaram que o suspeito, que recentemente havia sido colocado em liberdade, dava continuidade \u00e0 venda de entorpecentes e identificaram dois im\u00f3veis onde ele comercializava drogas. Com isso, os policiais cumpriram o mandado judicial de [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2023-02-14T23:11:12+00:00","article_modified_time":"2026-05-08T22:40:55+00:00","og_image":[{"width":984,"height":886,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/02\/pol-1.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Traficante em liberdade condicional volta a ser preso durante opera\u00e7\u00e3o policial em Rin\u00f3polis","datePublished":"2023-02-14T23:11:12+00:00","dateModified":"2026-05-08T22:40:55+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/"},"wordCount":254,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/02\/pol-1.jpg","articleSection":["Regi\u00e3o"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/","url":"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/","name":"Traficante em liberdade condicional volta a ser preso durante opera\u00e7\u00e3o policial em Rin\u00f3polis - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/02\/pol-1.jpg","datePublished":"2023-02-14T23:11:12+00:00","dateModified":"2026-05-08T22:40:55+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/02\/pol-1.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2023\/02\/pol-1.jpg","width":984,"height":886,"caption":"Pol\u00edcia Civil cumpriu mandado judicial de busca, nesta ter\u00e7a-feira (14), em resid\u00eancias no Jardim Cana\u00e3 e na Cohab M\u00e1rio Covas, e apreendeu por\u00e7\u00f5es de coca\u00edna, crack e maconha."},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/traficante-em-liberdade-condicional-volta-a-ser-preso-durante-operacao-policial-em-rinopolis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Traficante em liberdade condicional volta a ser preso durante opera\u00e7\u00e3o policial em Rin\u00f3polis"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/65262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=65262"}],"version-history":[{"count":4,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/65262\/revisions"}],"predecessor-version":[{"id":65267,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/65262\/revisions\/65267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/65263"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=65262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=65262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=65262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}