{"id":50946,"date":"2022-03-17T17:25:28","date_gmt":"2022-03-17T20:25:28","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=50946"},"modified":"2026-05-07T02:57:16","modified_gmt":"2026-05-07T05:57:16","slug":"uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/","title":{"rendered":"Uso de m\u00e1scara em locais fechados deixa de ser obrigat\u00f3rio em SP"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>O governador de S\u00e3o Paulo, Jo\u00e3o Doria, anunciou nesta quinta-feira (17) a flexibiliza\u00e7\u00e3o do uso de m\u00e1scaras contra Covid-19 na maior parte dos ambientes fechados. As exce\u00e7\u00f5es ficar\u00e3o por parte do transporte p\u00fablico, seus respectivos locais de acesso \u2014 como esta\u00e7\u00f5es de Metr\u00f4 \u2014 os locais com servi\u00e7os de sa\u00fade.<\/p>\n<p>O novo decreto ser\u00e1 publicado em edi\u00e7\u00e3o extra do Di\u00e1rio Oficial do Estado nesta quinta e ter\u00e1 efeito imediato. No dia 9 de mar\u00e7o, Doria j\u00e1 havia flexibilizado o uso da prote\u00e7\u00e3o em ambientes abertos. Com a melhora consistente dos indicadores da pandemia mesmo duas semanas depois das aglomera\u00e7\u00f5es do Carnaval, o estado decidiu avan\u00e7ar na libera\u00e7\u00e3o.<\/p>\n<p>A medida foi baseada em an\u00e1lises t\u00e9cnicas do Comit\u00ea Cient\u00edfico do Coronav\u00edrus de S\u00e3o Paulo, que tamb\u00e9m avaliaram o \u00edndice de vacina\u00e7\u00e3o com duas doses no estado. Segundo dados da gest\u00e3o Doria, mais de 90% da popula\u00e7\u00e3o eleg\u00edvel (acima de 5 anos) para receber as doses das vacinas foi imunizada em S\u00e3o Paulo.<\/p>\n<p>Fonte: R7<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador de S\u00e3o Paulo, Jo\u00e3o Doria, anunciou nesta quinta-feira (17) a flexibiliza\u00e7\u00e3o do uso de m\u00e1scaras contra Covid-19 na maior parte dos ambientes fechados. As exce\u00e7\u00f5es ficar\u00e3o por parte do transporte p\u00fablico, seus respectivos locais de acesso \u2014 como esta\u00e7\u00f5es de Metr\u00f4 \u2014 os locais com servi\u00e7os de sa\u00fade. O novo decreto ser\u00e1 publicado [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":50947,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-50946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uso de m\u00e1scara em locais fechados deixa de ser obrigat\u00f3rio em SP - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uso de m\u00e1scara em locais fechados deixa de ser obrigat\u00f3rio em SP - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"O governador de S\u00e3o Paulo, Jo\u00e3o Doria, anunciou nesta quinta-feira (17) a flexibiliza\u00e7\u00e3o do uso de m\u00e1scaras contra Covid-19 na maior parte dos ambientes fechados. As exce\u00e7\u00f5es ficar\u00e3o por parte do transporte p\u00fablico, seus respectivos locais de acesso \u2014 como esta\u00e7\u00f5es de Metr\u00f4 \u2014 os locais com servi\u00e7os de sa\u00fade. O novo decreto ser\u00e1 publicado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-17T20:25:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T05:57:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/covid-mascara-algomeracao-03032022181853797.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"771\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Uso de m\u00e1scara em locais fechados deixa de ser obrigat\u00f3rio em SP\",\"datePublished\":\"2022-03-17T20:25:28+00:00\",\"dateModified\":\"2026-05-07T05:57:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/\"},\"wordCount\":198,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/covid-mascara-algomeracao-03032022181853797.jpeg\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/\",\"name\":\"Uso de m\u00e1scara em locais fechados deixa de ser obrigat\u00f3rio em SP - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/covid-mascara-algomeracao-03032022181853797.jpeg\",\"datePublished\":\"2022-03-17T20:25:28+00:00\",\"dateModified\":\"2026-05-07T05:57:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/covid-mascara-algomeracao-03032022181853797.jpeg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/covid-mascara-algomeracao-03032022181853797.jpeg\",\"width\":771,\"height\":420,\"caption\":\"Decis\u00e3o tem validade imediata a partir desta quinta-feira (17). No transporte p\u00fablico e em servi\u00e7os de sa\u00fade o uso continua obrigat\u00f3rio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uso de m\u00e1scara em locais fechados deixa de ser obrigat\u00f3rio em SP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uso de m\u00e1scara em locais fechados deixa de ser obrigat\u00f3rio em SP - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/","og_locale":"pt_BR","og_type":"article","og_title":"Uso de m\u00e1scara em locais fechados deixa de ser obrigat\u00f3rio em SP - R\u00e1dio Life FM","og_description":"O governador de S\u00e3o Paulo, Jo\u00e3o Doria, anunciou nesta quinta-feira (17) a flexibiliza\u00e7\u00e3o do uso de m\u00e1scaras contra Covid-19 na maior parte dos ambientes fechados. As exce\u00e7\u00f5es ficar\u00e3o por parte do transporte p\u00fablico, seus respectivos locais de acesso \u2014 como esta\u00e7\u00f5es de Metr\u00f4 \u2014 os locais com servi\u00e7os de sa\u00fade. O novo decreto ser\u00e1 publicado [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2022-03-17T20:25:28+00:00","article_modified_time":"2026-05-07T05:57:16+00:00","og_image":[{"width":771,"height":420,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/covid-mascara-algomeracao-03032022181853797.jpeg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Uso de m\u00e1scara em locais fechados deixa de ser obrigat\u00f3rio em SP","datePublished":"2022-03-17T20:25:28+00:00","dateModified":"2026-05-07T05:57:16+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/"},"wordCount":198,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/covid-mascara-algomeracao-03032022181853797.jpeg","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/","url":"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/","name":"Uso de m\u00e1scara em locais fechados deixa de ser obrigat\u00f3rio em SP - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/covid-mascara-algomeracao-03032022181853797.jpeg","datePublished":"2022-03-17T20:25:28+00:00","dateModified":"2026-05-07T05:57:16+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/covid-mascara-algomeracao-03032022181853797.jpeg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/covid-mascara-algomeracao-03032022181853797.jpeg","width":771,"height":420,"caption":"Decis\u00e3o tem validade imediata a partir desta quinta-feira (17). No transporte p\u00fablico e em servi\u00e7os de sa\u00fade o uso continua obrigat\u00f3rio"},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/uso-de-mascara-em-locais-fechados-deixa-de-ser-obrigatorio-em-sp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Uso de m\u00e1scara em locais fechados deixa de ser obrigat\u00f3rio em SP"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/50946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=50946"}],"version-history":[{"count":4,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/50946\/revisions"}],"predecessor-version":[{"id":50951,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/50946\/revisions\/50951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/50947"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=50946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=50946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=50946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}