{"id":50083,"date":"2022-03-03T18:00:17","date_gmt":"2022-03-03T21:00:17","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=50083"},"modified":"2026-04-21T14:03:29","modified_gmt":"2026-04-21T17:03:29","slug":"_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/","title":{"rendered":"\u00b4Sa\u00fade \u00e9 o que interessa&#8221; traz a Dra. Amanda Machado (RJ), para falar sobre Sa\u00fade P\u00fablica"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>&nbsp;<\/p>\n<p>Nessa quarta-feira (02), a convidada do programa \u2018Sa\u00fade \u00e9 o que interessa&#8221;, com o Dr. Guilherme Bonadirman, foi a Dra. Amanda Machado.<\/p>\n<p>&nbsp;<\/p>\n<p>Diretamente do Rio de Janeiro, a m\u00e9dica residente de infectologia da UERJ, trouxe o tema:<\/p>\n<p>\u201cO que todos devem saber sobre o SUS\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50085\" src=\"https:\/\/static.radiolifefm.com.br\/wp-content\/uploads\/sites\/2\/2022\/03\/Screenshot_1.png\" alt=\"\" width=\"608\" height=\"340\" srcset=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Screenshot_1.png 1076w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Screenshot_1-300x168.png 300w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Screenshot_1-1024x573.png 1024w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Screenshot_1-768x430.png 768w\" sizes=\"auto, (max-width: 608px) 100vw, 608px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Quem acompanhou o bate-papo p\u00f4de se informar sobre o SUS, um dos maiores sistemas de sa\u00fade p\u00fablica do mundo, sua abrang\u00eancia, princ\u00edpios, diretrizes e entender quais s\u00e3o os nossos direitos e deveres enquanto usu\u00e1rios do sistema.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-50084\" src=\"https:\/\/static.radiolifefm.com.br\/wp-content\/uploads\/sites\/2\/2022\/03\/Screenshot_3.png\" alt=\"\" width=\"605\" height=\"340\" srcset=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Screenshot_3.png 1076w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Screenshot_3-300x169.png 300w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Screenshot_3-1024x576.png 1024w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Screenshot_3-768x432.png 768w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Tivemos uma verdadeira aula!<\/p>\n<p>&nbsp;<\/p>\n<p>Se voc\u00ea n\u00e3o assistiu \u00e0 transmiss\u00e3o ao vivo, acesse o link e confira o bate-papo na \u00edntegra:<\/p>\n<p><!-- Embedded with Magic Embeds - https:\/\/magicembeds.com --><\/p>\n<div class=\"wef-measure\" style=\"max-width: 450px;\"><\/div>\n<div class=\"fb-video\" data-href=\"https:\/\/www.facebook.com\/radiolifefm\/videos\/751271942517824\" data-allowfullscreen=\"true\" data-autoplay=\"false\" data-width=\"450\" data-show-text=\"false\" data-show-captions=\"true\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Nessa quarta-feira (02), a convidada do programa \u2018Sa\u00fade \u00e9 o que interessa&#8221;, com o Dr. Guilherme Bonadirman, foi a Dra. Amanda Machado. &nbsp; Diretamente do Rio de Janeiro, a m\u00e9dica residente de infectologia da UERJ, trouxe o tema: \u201cO que todos devem saber sobre o SUS\u201d. &nbsp; &nbsp; Quem acompanhou o bate-papo p\u00f4de se [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":50086,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[128],"tags":[],"class_list":["post-50083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-e-o-que-interessa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00b4Sa\u00fade \u00e9 o que interessa&quot; traz a Dra. Amanda Machado (RJ), para falar sobre Sa\u00fade P\u00fablica - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00b4Sa\u00fade \u00e9 o que interessa&quot; traz a Dra. Amanda Machado (RJ), para falar sobre Sa\u00fade P\u00fablica - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Nessa quarta-feira (02), a convidada do programa \u2018Sa\u00fade \u00e9 o que interessa&#8221;, com o Dr. Guilherme Bonadirman, foi a Dra. Amanda Machado. &nbsp; Diretamente do Rio de Janeiro, a m\u00e9dica residente de infectologia da UERJ, trouxe o tema: \u201cO que todos devem saber sobre o SUS\u201d. &nbsp; &nbsp; Quem acompanhou o bate-papo p\u00f4de se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-03T21:00:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T17:03:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Dr.-Guilherme-02-03-2022-e1646341156433.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1492\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mayraferrari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mayraferrari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/\"},\"author\":{\"name\":\"mayraferrari\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/d37940c51f50a0c5db4e065bb527a35d\"},\"headline\":\"\u00b4Sa\u00fade \u00e9 o que interessa&#8221; traz a Dra. Amanda Machado (RJ), para falar sobre Sa\u00fade P\u00fablica\",\"datePublished\":\"2022-03-03T21:00:17+00:00\",\"dateModified\":\"2026-04-21T17:03:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/\"},\"wordCount\":141,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Dr.-Guilherme-02-03-2022-e1646341156433.jpeg\",\"articleSection\":[\"Sa\u00fade \u00e9 o que interessa\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/\",\"name\":\"\u00b4Sa\u00fade \u00e9 o que interessa\\\" traz a Dra. Amanda Machado (RJ), para falar sobre Sa\u00fade P\u00fablica - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Dr.-Guilherme-02-03-2022-e1646341156433.jpeg\",\"datePublished\":\"2022-03-03T21:00:17+00:00\",\"dateModified\":\"2026-04-21T17:03:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Dr.-Guilherme-02-03-2022-e1646341156433.jpeg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Dr.-Guilherme-02-03-2022-e1646341156433.jpeg\",\"width\":1492,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00b4Sa\u00fade \u00e9 o que interessa&#8221; traz a Dra. Amanda Machado (RJ), para falar sobre Sa\u00fade P\u00fablica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/d37940c51f50a0c5db4e065bb527a35d\",\"name\":\"mayraferrari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/69374fafea2eae004e87f555bcb8bb6e24c5d501c2ffec6bbedf0a8f25427b93?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/69374fafea2eae004e87f555bcb8bb6e24c5d501c2ffec6bbedf0a8f25427b93?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/69374fafea2eae004e87f555bcb8bb6e24c5d501c2ffec6bbedf0a8f25427b93?s=96&d=mm&r=g\",\"caption\":\"mayraferrari\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00b4Sa\u00fade \u00e9 o que interessa\" traz a Dra. Amanda Machado (RJ), para falar sobre Sa\u00fade P\u00fablica - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/","og_locale":"pt_BR","og_type":"article","og_title":"\u00b4Sa\u00fade \u00e9 o que interessa\" traz a Dra. Amanda Machado (RJ), para falar sobre Sa\u00fade P\u00fablica - R\u00e1dio Life FM","og_description":"&nbsp; Nessa quarta-feira (02), a convidada do programa \u2018Sa\u00fade \u00e9 o que interessa&#8221;, com o Dr. Guilherme Bonadirman, foi a Dra. Amanda Machado. &nbsp; Diretamente do Rio de Janeiro, a m\u00e9dica residente de infectologia da UERJ, trouxe o tema: \u201cO que todos devem saber sobre o SUS\u201d. &nbsp; &nbsp; Quem acompanhou o bate-papo p\u00f4de se [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2022-03-03T21:00:17+00:00","article_modified_time":"2026-04-21T17:03:29+00:00","og_image":[{"width":1492,"height":788,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Dr.-Guilherme-02-03-2022-e1646341156433.jpeg","type":"image\/jpeg"}],"author":"mayraferrari","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mayraferrari","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/"},"author":{"name":"mayraferrari","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/d37940c51f50a0c5db4e065bb527a35d"},"headline":"\u00b4Sa\u00fade \u00e9 o que interessa&#8221; traz a Dra. Amanda Machado (RJ), para falar sobre Sa\u00fade P\u00fablica","datePublished":"2022-03-03T21:00:17+00:00","dateModified":"2026-04-21T17:03:29+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/"},"wordCount":141,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Dr.-Guilherme-02-03-2022-e1646341156433.jpeg","articleSection":["Sa\u00fade \u00e9 o que interessa"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/","url":"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/","name":"\u00b4Sa\u00fade \u00e9 o que interessa\" traz a Dra. Amanda Machado (RJ), para falar sobre Sa\u00fade P\u00fablica - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Dr.-Guilherme-02-03-2022-e1646341156433.jpeg","datePublished":"2022-03-03T21:00:17+00:00","dateModified":"2026-04-21T17:03:29+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Dr.-Guilherme-02-03-2022-e1646341156433.jpeg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2022\/03\/Dr.-Guilherme-02-03-2022-e1646341156433.jpeg","width":1492,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/_saude-e-o-que-interessa-traz-a-dra-amanda-machado-rj-para-falar-sobre-saude-publica_\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"\u00b4Sa\u00fade \u00e9 o que interessa&#8221; traz a Dra. Amanda Machado (RJ), para falar sobre Sa\u00fade P\u00fablica"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/d37940c51f50a0c5db4e065bb527a35d","name":"mayraferrari","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/69374fafea2eae004e87f555bcb8bb6e24c5d501c2ffec6bbedf0a8f25427b93?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/69374fafea2eae004e87f555bcb8bb6e24c5d501c2ffec6bbedf0a8f25427b93?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/69374fafea2eae004e87f555bcb8bb6e24c5d501c2ffec6bbedf0a8f25427b93?s=96&d=mm&r=g","caption":"mayraferrari"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/50083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=50083"}],"version-history":[{"count":2,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/50083\/revisions"}],"predecessor-version":[{"id":50088,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/50083\/revisions\/50088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/50086"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=50083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=50083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=50083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}