{"id":44185,"date":"2021-10-15T20:23:46","date_gmt":"2021-10-15T23:23:46","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=44185"},"modified":"2026-04-08T21:16:26","modified_gmt":"2026-04-09T00:16:26","slug":"prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/","title":{"rendered":"Prefeitura de Adamantina informa sobre a realiza\u00e7\u00e3o dos exames COVID-19 RT-PCR"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Considerando o aumento de casos de COVID-19 que o munic\u00edpio de Adamantina vem tendo nas \u00faltimas semanas em compara\u00e7\u00e3o a outras cidades do Estado;<\/p>\n<p>&nbsp;<\/p>\n<p>Considerando que atualmente o munic\u00edpio \u00e9 respons\u00e1vel pela realiza\u00e7\u00e3o dos exames para detec\u00e7\u00e3o do V\u00edrus SARS-COV2 (COVID-19), que \u00e9 realizado atrav\u00e9s da metodologia de imuno fluoresc\u00eancia do Ant\u00edgeno e que atrav\u00e9s deste exame n\u00e3o \u00e9 poss\u00edvel saber qual o tipo de v\u00edrus est\u00e1 circulando no munic\u00edpio;<\/p>\n<p>&nbsp;<\/p>\n<p>Em conversa com o Departamento Regional de Sa\u00fade Mar\u00edlia e com os respons\u00e1veis pelo Instituto Adolfo Lutz, a partir de amanh\u00e3 (16\/10), os exames coletados em Adamantina estar\u00e3o sendo enviados para an\u00e1lise nesta renomada Institui\u00e7\u00e3o, para realiza\u00e7\u00e3o do Exame de RT-PCR (padr\u00e3o ouro) para detec\u00e7\u00e3o da presen\u00e7a do v\u00edrus e poss\u00edvel sequenciamento gen\u00e9tico.<\/p>\n<p>&nbsp;<\/p>\n<p>Desta forma, a partir de amanh\u00e3 os resultados n\u00e3o estar\u00e3o mais saindo no mesmo dia e sim em um intervalo de 72 a 96h ap\u00f3s a coleta.<\/p>\n<p>&nbsp;<\/p>\n<p>Sendo assim, a secretaria de sa\u00fade refor\u00e7a a orienta\u00e7\u00e3o de que todos aqueles que apresentarem sintomas devem procurar o servi\u00e7o de sa\u00fade, respeitarem as orienta\u00e7\u00f5es dos profissionais de sa\u00fade quanto a medidas de isolamento e distanciamento social, uso de m\u00e1scaras, \u00e1lcool em gel e demais com o objetivo de n\u00e3o infringirem as leis e nem colocar em risco a vida de outros.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: Assessoria de Imprensa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Considerando o aumento de casos de COVID-19 que o munic\u00edpio de Adamantina vem tendo nas \u00faltimas semanas em compara\u00e7\u00e3o a outras cidades do Estado; &nbsp; Considerando que atualmente o munic\u00edpio \u00e9 respons\u00e1vel pela realiza\u00e7\u00e3o dos exames para detec\u00e7\u00e3o do V\u00edrus SARS-COV2 (COVID-19), que \u00e9 realizado atrav\u00e9s da metodologia de imuno fluoresc\u00eancia do Ant\u00edgeno e que [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":44186,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-44185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prefeitura de Adamantina informa sobre a realiza\u00e7\u00e3o dos exames COVID-19 RT-PCR - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeitura de Adamantina informa sobre a realiza\u00e7\u00e3o dos exames COVID-19 RT-PCR - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Considerando o aumento de casos de COVID-19 que o munic\u00edpio de Adamantina vem tendo nas \u00faltimas semanas em compara\u00e7\u00e3o a outras cidades do Estado; &nbsp; Considerando que atualmente o munic\u00edpio \u00e9 respons\u00e1vel pela realiza\u00e7\u00e3o dos exames para detec\u00e7\u00e3o do V\u00edrus SARS-COV2 (COVID-19), que \u00e9 realizado atrav\u00e9s da metodologia de imuno fluoresc\u00eancia do Ant\u00edgeno e que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-15T23:23:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-09T00:16:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/10\/rt-pcr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Prefeitura de Adamantina informa sobre a realiza\u00e7\u00e3o dos exames COVID-19 RT-PCR\",\"datePublished\":\"2021-10-15T23:23:46+00:00\",\"dateModified\":\"2026-04-09T00:16:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/\"},\"wordCount\":269,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/10\/rt-pcr.jpg\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/\",\"name\":\"Prefeitura de Adamantina informa sobre a realiza\u00e7\u00e3o dos exames COVID-19 RT-PCR - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/10\/rt-pcr.jpg\",\"datePublished\":\"2021-10-15T23:23:46+00:00\",\"dateModified\":\"2026-04-09T00:16:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/10\/rt-pcr.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/10\/rt-pcr.jpg\",\"width\":600,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeitura de Adamantina informa sobre a realiza\u00e7\u00e3o dos exames COVID-19 RT-PCR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeitura de Adamantina informa sobre a realiza\u00e7\u00e3o dos exames COVID-19 RT-PCR - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeitura de Adamantina informa sobre a realiza\u00e7\u00e3o dos exames COVID-19 RT-PCR - R\u00e1dio Life FM","og_description":"Considerando o aumento de casos de COVID-19 que o munic\u00edpio de Adamantina vem tendo nas \u00faltimas semanas em compara\u00e7\u00e3o a outras cidades do Estado; &nbsp; Considerando que atualmente o munic\u00edpio \u00e9 respons\u00e1vel pela realiza\u00e7\u00e3o dos exames para detec\u00e7\u00e3o do V\u00edrus SARS-COV2 (COVID-19), que \u00e9 realizado atrav\u00e9s da metodologia de imuno fluoresc\u00eancia do Ant\u00edgeno e que [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2021-10-15T23:23:46+00:00","article_modified_time":"2026-04-09T00:16:26+00:00","og_image":[{"width":600,"height":350,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/10\/rt-pcr.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Prefeitura de Adamantina informa sobre a realiza\u00e7\u00e3o dos exames COVID-19 RT-PCR","datePublished":"2021-10-15T23:23:46+00:00","dateModified":"2026-04-09T00:16:26+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/"},"wordCount":269,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/10\/rt-pcr.jpg","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/","url":"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/","name":"Prefeitura de Adamantina informa sobre a realiza\u00e7\u00e3o dos exames COVID-19 RT-PCR - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/10\/rt-pcr.jpg","datePublished":"2021-10-15T23:23:46+00:00","dateModified":"2026-04-09T00:16:26+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/10\/rt-pcr.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/10\/rt-pcr.jpg","width":600,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/prefeitura-de-adamantina-informa-sobre-a-realizacao-dos-exames-covid-19-rt-pcr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Prefeitura de Adamantina informa sobre a realiza\u00e7\u00e3o dos exames COVID-19 RT-PCR"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/44185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=44185"}],"version-history":[{"count":2,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/44185\/revisions"}],"predecessor-version":[{"id":44188,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/44185\/revisions\/44188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/44186"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=44185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=44185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=44185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}