{"id":43442,"date":"2021-09-30T09:25:53","date_gmt":"2021-09-30T12:25:53","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=43442"},"modified":"2026-05-12T22:46:55","modified_gmt":"2026-05-13T01:46:55","slug":"santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/","title":{"rendered":"Santa Casa de Pacaembu encerra atendimento e Prefeitura assume funcionamento do pronto-socorro"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Depois de estar envolvida em um esc\u00e2ndalo de repercuss\u00e3o nacional, cuja investiga\u00e7\u00e3o apura desvios na \u00e1rea da sa\u00fade, a organiza\u00e7\u00e3o social de sa\u00fade (OSS) Santa Casa de Pacaembu deixou de atuar na presta\u00e7\u00e3o de servi\u00e7os hospitalares na cidade. Na pr\u00e1tica, a Santa Casa de Pacaembu parou com os atendimentos aos moradores.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.sigamais.com\/noticias\/policia\/em-operacao-contra-desvios-na-saude-pc-e-mp-fazem-buscas-e-prisao-em-pacaembu-florida-e-dracena\/\"><strong>H\u00e1 um ano, em 29 de setembro do ano passado,<\/strong><\/a>\u00a0foi desencadeada pelo Grupo de Atua\u00e7\u00e3o Especial de Combate ao Crime Organizado (Gaeco) do Minist\u00e9rio P\u00fablico do Estado de S\u00e3o Paulo (MPSP) e Pol\u00edcia Civil paulista a opera\u00e7\u00e3o \u201cRaio X\u201d, visando desmantelar grupo criminoso especializado em desviar dinheiro destinado \u00e0 sa\u00fade mediante celebra\u00e7\u00e3o de contratos de gest\u00e3o entre munic\u00edpios e OSS.<\/p>\n<p>&nbsp;<\/p>\n<p>Uma das institui\u00e7\u00f5es envolvidas no esc\u00e2ndalo \u00e9 a OSS Santa Casa de Pacaembu, que h\u00e1 um ano sofreu mandados de buscas e apreens\u00e3o, depois de dois anos de investiga\u00e7\u00f5es que rastrearam gigantesco e sofisticado esquema de corrup\u00e7\u00e3o envolvendo agentes p\u00fablicos e o desvio de milh\u00f5es de reais em preju\u00edzo da sa\u00fade.<\/p>\n<p>&nbsp;<\/p>\n<p>Conforme as investiga\u00e7\u00f5es, a institui\u00e7\u00e3o pacaembuense fazia a gest\u00e3o de hospitais p\u00fablicos, UPAS, AMES e outros servi\u00e7os de sa\u00fade no Estado de S\u00e3o Paulo, e em um hospital no Par\u00e1, e\u00a0<a href=\"https:\/\/www.sigamais.com\/noticias\/policia\/como-organizacao-social-santa-casa-de-pacaembu-geriu-r-11-bilhao-em-contratos-de-saude\/\"><strong>teria movimentado cerca R$ 1,1 bilh\u00e3o em contratos de sa\u00fade<\/strong><\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Crise local e alternativas no atendimento aos moradores de Pacaembu<\/strong><\/p>\n<p>Sob investiga\u00e7\u00e3o, sem as certid\u00f5es negativas exigidas em lei desde 27 de agosto e com as contas banc\u00e1rias bloqueadas, a OSS Santa Casa de Pacaembu ficou impedida receber os recursos p\u00fablicos tanto do SUS quanto da Prefeitura local, para a presta\u00e7\u00e3o dos servi\u00e7os em sa\u00fade e assim tocar suas atividades, n\u00e3o restando outra alternativa sen\u00e3o fechar suas portas.<\/p>\n<p>&nbsp;<\/p>\n<p>A decis\u00e3o da OSS foi comunicada \u00e0 Prefeitura. Por determina\u00e7\u00e3o do prefeito Jo\u00e3o Francisco Mugnai Neves foi iniciada uma for\u00e7a tarefa e estabelecido um amplo di\u00e1logo aberto com a comunidade, suas lideran\u00e7as e os demais poderes, em especial com a C\u00e2mara Municipal, para que a popula\u00e7\u00e3o n\u00e3o ficasse desassistida diante do encerramento dos atendimentos hospitalares pela Santa Casa local.<\/p>\n<p>&nbsp;<\/p>\n<p>At\u00e9 ent\u00e3o, nesse contexto, e com recursos pr\u00f3prios, a Prefeitura pagava \u00e0 OSS pela presta\u00e7\u00e3o dos servi\u00e7os de pronto-atendimento. J\u00e1 o custeio pelas interna\u00e7\u00f5es e outros procedimentos m\u00e9dicos recebiam recursos do SUS.<\/p>\n<p>&nbsp;<\/p>\n<p>Diante dos novos desdobramentos e com a posi\u00e7\u00e3o da OSS de encerrar suas atividades, a Prefeitura decidiu por assumir a gest\u00e3o do pronto-socorro, com execu\u00e7\u00e3o direta, o que come\u00e7ou a ocorrer nesta ter\u00e7a-feira (28).<\/p>\n<p>&nbsp;<\/p>\n<p>Ao SIGA MAIS, na manh\u00e3 desta quarta-feira (29), o prefeito Jo\u00e3o Francisco contou que assinou um decreto municipal declarando as instala\u00e7\u00f5es f\u00edsicas da Santa Casa como de utilidade p\u00fablica municipal. O documento permite o ingresso e utiliza\u00e7\u00e3o do espa\u00e7o pelo poder p\u00fablico, para manter o funcionamento do pronto-socorro no mesmo local.<\/p>\n<p>&nbsp;<\/p>\n<p>O prefeito disse tamb\u00e9m sobre a edi\u00e7\u00e3o de um segundo decreto, de situa\u00e7\u00e3o de emerg\u00eancia, dando seguran\u00e7a jur\u00eddica para a tomada de decis\u00f5es, ado\u00e7\u00e3o de medidas, aloca\u00e7\u00e3o de recursos e despesas, e ainda contrata\u00e7\u00f5es complementares de profissionais para a gest\u00e3o direta do pronto-socorro. A medida permitiu, por exemplo, a contrata\u00e7\u00e3o de m\u00e9dicos e enfermeiros por meio de um cons\u00f3rcio de sa\u00fade regional, formado por munic\u00edpios da Nova Alta Paulista. Os demais trabalhadores foram mobilizados do pr\u00f3prio quadro da Prefeitura.<\/p>\n<p>&nbsp;<\/p>\n<p>De acordo com o prefeito, os atendimentos aos moradores continuar\u00e3o temporariamente sendo realizados no mesmo espa\u00e7o, com porta aberta, 24 horas, todos os dias, dentro da capacidade de opera\u00e7\u00e3o do lugar. A popula\u00e7\u00e3o ser\u00e1 assistida e os casos de maior complexidade ter\u00e3o os pacientes estabilizados e transferidos por ambul\u00e2ncia \u00e0 Santa Casa de Adamantina. \u201cInfelizmente chegou a essa situa\u00e7\u00e3o. Mas agimos para n\u00e3o deixar a popula\u00e7\u00e3o desassistida\u201d, destacou o gestor municipal.<\/p>\n<p>&nbsp;<\/p>\n<p>Para o transporte de pacientes as ambul\u00e2ncias da Prefeitura de Pacaembu ficar\u00e3o \u00e0 disposi\u00e7\u00e3o e em prontid\u00e3o. O prefeito disse que uma nova ambul\u00e2ncia foi adquirida, com recursos da pr\u00f3pria municipalidade, para refor\u00e7ar a frota.<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m do pronto-socorro, a OSS Santa Casa de Pacaembu tamb\u00e9m fazia a gest\u00e3o do Centro de Aten\u00e7\u00e3o Psicossocial (CAPS), Resid\u00eancia Terap\u00eautica (RT) e Posto de Sa\u00fade da Fam\u00edlia (PSF), que agora ficam sob gest\u00e3o direta do Munic\u00edpio.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Principal investigado da opera\u00e7\u00e3o Raio X \u00e9 condenado a 104 anos de pris\u00e3o<\/strong><\/p>\n<p>Em agosto deste ano, a 1\u00aa Vara da Comarca de Pen\u00e1polis condenou oito pessoas acusadas de desviar, entre 2018 e 2020, cerca de R$ 500 milh\u00f5es em verbas da \u00e1rea da sa\u00fade.\u00a0<a href=\"https:\/\/www.sigamais.com\/noticias\/policia\/principal-investigado-da-operacao-raio-x-e-condenado-a-104-anos-de-prisao\/\"><strong>O m\u00e9dico anestesista Cleudson Garcia Montali, apontado\u00a0\u00a0como l\u00edder da quadrilha, foi sentenciado a 104 anos, dois meses e 20 dias de reclus\u00e3o, no regime inicial fechado<\/strong><\/a>. Ele tamb\u00e9m dever\u00e1 pagar indeniza\u00e7\u00e3o ao munic\u00edpio de Pen\u00e1polis no valor de R$ 947.960. Outras sete pessoas foram condenadas.<\/p>\n<p>&nbsp;<\/p>\n<p>Por meio da Irmandade da Santa Casa de Miseric\u00f3rdia de Birigui e Irmandade da Santa Casa de Miseric\u00f3rdia de Pacaembu, Cleudson Montali celebrou contratos de gest\u00e3o mediante licita\u00e7\u00f5es fraudulentas com o poder p\u00fablico para administrar a sa\u00fade de diversos munic\u00edpios e desviando parte do dinheiro repassado por for\u00e7a do contrato de gest\u00e3o \u00e0s referidas OSS.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: Siga Mais<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depois de estar envolvida em um esc\u00e2ndalo de repercuss\u00e3o nacional, cuja investiga\u00e7\u00e3o apura desvios na \u00e1rea da sa\u00fade, a organiza\u00e7\u00e3o social de sa\u00fade (OSS) Santa Casa de Pacaembu deixou de atuar na presta\u00e7\u00e3o de servi\u00e7os hospitalares na cidade. Na pr\u00e1tica, a Santa Casa de Pacaembu parou com os atendimentos aos moradores. &nbsp; H\u00e1 um ano, [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":43443,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[24,35],"tags":[],"class_list":["post-43442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiao","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santa Casa de Pacaembu encerra atendimento e Prefeitura assume funcionamento do pronto-socorro - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santa Casa de Pacaembu encerra atendimento e Prefeitura assume funcionamento do pronto-socorro - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Depois de estar envolvida em um esc\u00e2ndalo de repercuss\u00e3o nacional, cuja investiga\u00e7\u00e3o apura desvios na \u00e1rea da sa\u00fade, a organiza\u00e7\u00e3o social de sa\u00fade (OSS) Santa Casa de Pacaembu deixou de atuar na presta\u00e7\u00e3o de servi\u00e7os hospitalares na cidade. Na pr\u00e1tica, a Santa Casa de Pacaembu parou com os atendimentos aos moradores. &nbsp; H\u00e1 um ano, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-30T12:25:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T01:46:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/09\/dta-casa-pacaembu-o-pacaembuensejpg16329421566154b84c39ae4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"337\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Santa Casa de Pacaembu encerra atendimento e Prefeitura assume funcionamento do pronto-socorro\",\"datePublished\":\"2021-09-30T12:25:53+00:00\",\"dateModified\":\"2026-05-13T01:46:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/\"},\"wordCount\":963,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/09\/dta-casa-pacaembu-o-pacaembuensejpg16329421566154b84c39ae4.jpg\",\"articleSection\":[\"Regi\u00e3o\",\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/\",\"name\":\"Santa Casa de Pacaembu encerra atendimento e Prefeitura assume funcionamento do pronto-socorro - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/09\/dta-casa-pacaembu-o-pacaembuensejpg16329421566154b84c39ae4.jpg\",\"datePublished\":\"2021-09-30T12:25:53+00:00\",\"dateModified\":\"2026-05-13T01:46:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/09\/dta-casa-pacaembu-o-pacaembuensejpg16329421566154b84c39ae4.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/09\/dta-casa-pacaembu-o-pacaembuensejpg16329421566154b84c39ae4.jpg\",\"width\":600,\"height\":337,\"caption\":\"Casos que demandem interna\u00e7\u00f5es ser\u00e3o encaminhados a Adamantina.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santa Casa de Pacaembu encerra atendimento e Prefeitura assume funcionamento do pronto-socorro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santa Casa de Pacaembu encerra atendimento e Prefeitura assume funcionamento do pronto-socorro - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/","og_locale":"pt_BR","og_type":"article","og_title":"Santa Casa de Pacaembu encerra atendimento e Prefeitura assume funcionamento do pronto-socorro - R\u00e1dio Life FM","og_description":"Depois de estar envolvida em um esc\u00e2ndalo de repercuss\u00e3o nacional, cuja investiga\u00e7\u00e3o apura desvios na \u00e1rea da sa\u00fade, a organiza\u00e7\u00e3o social de sa\u00fade (OSS) Santa Casa de Pacaembu deixou de atuar na presta\u00e7\u00e3o de servi\u00e7os hospitalares na cidade. Na pr\u00e1tica, a Santa Casa de Pacaembu parou com os atendimentos aos moradores. &nbsp; H\u00e1 um ano, [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2021-09-30T12:25:53+00:00","article_modified_time":"2026-05-13T01:46:55+00:00","og_image":[{"width":600,"height":337,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/09\/dta-casa-pacaembu-o-pacaembuensejpg16329421566154b84c39ae4.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Santa Casa de Pacaembu encerra atendimento e Prefeitura assume funcionamento do pronto-socorro","datePublished":"2021-09-30T12:25:53+00:00","dateModified":"2026-05-13T01:46:55+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/"},"wordCount":963,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/09\/dta-casa-pacaembu-o-pacaembuensejpg16329421566154b84c39ae4.jpg","articleSection":["Regi\u00e3o","Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/","url":"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/","name":"Santa Casa de Pacaembu encerra atendimento e Prefeitura assume funcionamento do pronto-socorro - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/09\/dta-casa-pacaembu-o-pacaembuensejpg16329421566154b84c39ae4.jpg","datePublished":"2021-09-30T12:25:53+00:00","dateModified":"2026-05-13T01:46:55+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/09\/dta-casa-pacaembu-o-pacaembuensejpg16329421566154b84c39ae4.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/09\/dta-casa-pacaembu-o-pacaembuensejpg16329421566154b84c39ae4.jpg","width":600,"height":337,"caption":"Casos que demandem interna\u00e7\u00f5es ser\u00e3o encaminhados a Adamantina."},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/santa-casa-de-pacaembu-encerra-atendimento-e-prefeitura-assume-funcionamento-do-pronto-socorro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Santa Casa de Pacaembu encerra atendimento e Prefeitura assume funcionamento do pronto-socorro"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/43442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=43442"}],"version-history":[{"count":1,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/43442\/revisions"}],"predecessor-version":[{"id":43444,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/43442\/revisions\/43444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/43443"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=43442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=43442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=43442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}