{"id":41992,"date":"2021-08-23T16:29:16","date_gmt":"2021-08-23T19:29:16","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=41992"},"modified":"2026-05-08T03:35:19","modified_gmt":"2026-05-08T06:35:19","slug":"secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/","title":{"rendered":"Secretaria de Sa\u00fade de Adamantina inicia vacina\u00e7\u00e3o para pessoas que tem entre 12 e 15 anos com comorbidades a partir de amanh\u00e3 (24)"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>A Prefeitura de Adamantina, por meio da Secretaria de Sa\u00fade, seguindo as recomenda\u00e7\u00f5es da Secretaria de Estado, atrav\u00e9s do Informe T\u00e9cnico n.\u00ba 20, sobre a campanha de imuniza\u00e7\u00e3o contra COVID-19, inicia a partir de amanh\u00e3 (24), a vacina\u00e7\u00e3o de pessoas entre 12 e 15 anos com defici\u00eancia, comorbidades, gestantes e pu\u00e9rperas.<\/p>\n<p>&nbsp;<\/p>\n<p>A vacina\u00e7\u00e3o deste p\u00fablico est\u00e1 condicionada \u00e0 presen\u00e7a de um adulto respons\u00e1vel, podendo esse proceder com a autoriza\u00e7\u00e3o verbal no ato de vacina\u00e7\u00e3o.<\/p>\n<p>&nbsp;<\/p>\n<p>No caso da impossibilidade do comparecimento dos pais\/respons\u00e1vel, \u00e9 necess\u00e1rio preencher a autoriza\u00e7\u00e3o que estar\u00e1 dispon\u00edvel em todas as unidades b\u00e1sicas de sa\u00fade do munic\u00edpio e no site da Prefeitura de Adamantina e entregar no Centro Integrado de Sa\u00fade (CIS) na hora que o adolescente for imunizado, conforme consta no art.142 do Estatuto da Crian\u00e7a e do Adolescente.<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m deste documento, \u00e9 preciso apresentar atestado m\u00e9dico comprovando a comorbidade referida. O mesmo tamb\u00e9m dever\u00e1 ser retirado na unidade b\u00e1sica de sa\u00fade onde o adolescente \u00e9 atendido.<\/p>\n<p>&nbsp;<\/p>\n<p>O adolescente que ser\u00e1 imunizado deve portar o RG e o CPF e fazer o cadastro no site\u00a0<a href=\"http:\/\/www.vacinaja.sp.gov.br\/\">www.vacinaja.sp.gov.br<\/a>. A vacina\u00e7\u00e3o acontece das 13h30 \u00e0s 19h.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: Assessoria de Imprensa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Adamantina, por meio da Secretaria de Sa\u00fade, seguindo as recomenda\u00e7\u00f5es da Secretaria de Estado, atrav\u00e9s do Informe T\u00e9cnico n.\u00ba 20, sobre a campanha de imuniza\u00e7\u00e3o contra COVID-19, inicia a partir de amanh\u00e3 (24), a vacina\u00e7\u00e3o de pessoas entre 12 e 15 anos com defici\u00eancia, comorbidades, gestantes e pu\u00e9rperas. &nbsp; A vacina\u00e7\u00e3o deste [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":39259,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-41992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Secretaria de Sa\u00fade de Adamantina inicia vacina\u00e7\u00e3o para pessoas que tem entre 12 e 15 anos com comorbidades a partir de amanh\u00e3 (24) - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Secretaria de Sa\u00fade de Adamantina inicia vacina\u00e7\u00e3o para pessoas que tem entre 12 e 15 anos com comorbidades a partir de amanh\u00e3 (24) - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura de Adamantina, por meio da Secretaria de Sa\u00fade, seguindo as recomenda\u00e7\u00f5es da Secretaria de Estado, atrav\u00e9s do Informe T\u00e9cnico n.\u00ba 20, sobre a campanha de imuniza\u00e7\u00e3o contra COVID-19, inicia a partir de amanh\u00e3 (24), a vacina\u00e7\u00e3o de pessoas entre 12 e 15 anos com defici\u00eancia, comorbidades, gestantes e pu\u00e9rperas. &nbsp; A vacina\u00e7\u00e3o deste [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-23T19:29:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T06:35:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Secretaria de Sa\u00fade de Adamantina inicia vacina\u00e7\u00e3o para pessoas que tem entre 12 e 15 anos com comorbidades a partir de amanh\u00e3 (24)\",\"datePublished\":\"2021-08-23T19:29:16+00:00\",\"dateModified\":\"2026-05-08T06:35:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/\"},\"wordCount\":243,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/\",\"name\":\"Secretaria de Sa\u00fade de Adamantina inicia vacina\u00e7\u00e3o para pessoas que tem entre 12 e 15 anos com comorbidades a partir de amanh\u00e3 (24) - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg\",\"datePublished\":\"2021-08-23T19:29:16+00:00\",\"dateModified\":\"2026-05-08T06:35:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Secretaria de Sa\u00fade de Adamantina inicia vacina\u00e7\u00e3o para pessoas que tem entre 12 e 15 anos com comorbidades a partir de amanh\u00e3 (24)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Secretaria de Sa\u00fade de Adamantina inicia vacina\u00e7\u00e3o para pessoas que tem entre 12 e 15 anos com comorbidades a partir de amanh\u00e3 (24) - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/","og_locale":"pt_BR","og_type":"article","og_title":"Secretaria de Sa\u00fade de Adamantina inicia vacina\u00e7\u00e3o para pessoas que tem entre 12 e 15 anos com comorbidades a partir de amanh\u00e3 (24) - R\u00e1dio Life FM","og_description":"A Prefeitura de Adamantina, por meio da Secretaria de Sa\u00fade, seguindo as recomenda\u00e7\u00f5es da Secretaria de Estado, atrav\u00e9s do Informe T\u00e9cnico n.\u00ba 20, sobre a campanha de imuniza\u00e7\u00e3o contra COVID-19, inicia a partir de amanh\u00e3 (24), a vacina\u00e7\u00e3o de pessoas entre 12 e 15 anos com defici\u00eancia, comorbidades, gestantes e pu\u00e9rperas. &nbsp; A vacina\u00e7\u00e3o deste [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2021-08-23T19:29:16+00:00","article_modified_time":"2026-05-08T06:35:19+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Secretaria de Sa\u00fade de Adamantina inicia vacina\u00e7\u00e3o para pessoas que tem entre 12 e 15 anos com comorbidades a partir de amanh\u00e3 (24)","datePublished":"2021-08-23T19:29:16+00:00","dateModified":"2026-05-08T06:35:19+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/"},"wordCount":243,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/","url":"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/","name":"Secretaria de Sa\u00fade de Adamantina inicia vacina\u00e7\u00e3o para pessoas que tem entre 12 e 15 anos com comorbidades a partir de amanh\u00e3 (24) - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg","datePublished":"2021-08-23T19:29:16+00:00","dateModified":"2026-05-08T06:35:19+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/secretaria-de-saude-de-adamantina-inicia-vacinacao-para-pessoas-que-tem-entre-12-e-15-anos-com-comorbidades-a-partir-de-amanha-24adamantina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Secretaria de Sa\u00fade de Adamantina inicia vacina\u00e7\u00e3o para pessoas que tem entre 12 e 15 anos com comorbidades a partir de amanh\u00e3 (24)"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/41992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=41992"}],"version-history":[{"count":2,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/41992\/revisions"}],"predecessor-version":[{"id":41994,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/41992\/revisions\/41994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/39259"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=41992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=41992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=41992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}