{"id":41326,"date":"2021-08-03T14:39:12","date_gmt":"2021-08-03T17:39:12","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=41326"},"modified":"2026-05-01T19:32:49","modified_gmt":"2026-05-01T22:32:49","slug":"pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/","title":{"rendered":"Pessoas com 23 anos podem tomar a 1\u00ba dose contra a covid-19"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Imuniza\u00e7\u00e3o ser\u00e1 nesta quarta-feira (4) no CIS das 13h30 \u00e0s 19h<\/p>\n<p>&nbsp;<\/p>\n<p>A Secretaria de Sa\u00fade de Adamantina informa que est\u00e1 aberta a vacina\u00e7\u00e3o contra a covid-19 para pessoas com 23 anos a partir desta quarta-feira (4). A estimativa \u00e9 que\u00a0 536 pessoas recebam\u00a0a primeira dose da vacina.<\/p>\n<p>&nbsp;<\/p>\n<p>A imuniza\u00e7\u00e3o acontece no CIS (Centro Integrado de Sa\u00fade) das 13h30 \u00e0s 19h.<\/p>\n<p>&nbsp;<\/p>\n<p>Pessoas com mais de 23 anos, e segunda dose \u2013 previamente agendados, tamb\u00e9m podem ser vacinados.<\/p>\n<p>Nesta segunda-feira (2), foram vacinadas contra a covid-19 em Adamantina \u2013 primeira e segunda dose, 403 pessoas pertencentes a todos os grupos e faixas et\u00e1rias autorizadas para serem imunizadas.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: Assessoria de Imprensa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imuniza\u00e7\u00e3o ser\u00e1 nesta quarta-feira (4) no CIS das 13h30 \u00e0s 19h &nbsp; A Secretaria de Sa\u00fade de Adamantina informa que est\u00e1 aberta a vacina\u00e7\u00e3o contra a covid-19 para pessoas com 23 anos a partir desta quarta-feira (4). A estimativa \u00e9 que\u00a0 536 pessoas recebam\u00a0a primeira dose da vacina. &nbsp; A imuniza\u00e7\u00e3o acontece no CIS (Centro [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":39259,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-41326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pessoas com 23 anos podem tomar a 1\u00ba dose contra a covid-19 - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pessoas com 23 anos podem tomar a 1\u00ba dose contra a covid-19 - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Imuniza\u00e7\u00e3o ser\u00e1 nesta quarta-feira (4) no CIS das 13h30 \u00e0s 19h &nbsp; A Secretaria de Sa\u00fade de Adamantina informa que est\u00e1 aberta a vacina\u00e7\u00e3o contra a covid-19 para pessoas com 23 anos a partir desta quarta-feira (4). A estimativa \u00e9 que\u00a0 536 pessoas recebam\u00a0a primeira dose da vacina. &nbsp; A imuniza\u00e7\u00e3o acontece no CIS (Centro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-03T17:39:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-01T22:32:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Pessoas com 23 anos podem tomar a 1\u00ba dose contra a covid-19\",\"datePublished\":\"2021-08-03T17:39:12+00:00\",\"dateModified\":\"2026-05-01T22:32:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/\"},\"wordCount\":121,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/\",\"name\":\"Pessoas com 23 anos podem tomar a 1\u00ba dose contra a covid-19 - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg\",\"datePublished\":\"2021-08-03T17:39:12+00:00\",\"dateModified\":\"2026-05-01T22:32:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pessoas com 23 anos podem tomar a 1\u00ba dose contra a covid-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pessoas com 23 anos podem tomar a 1\u00ba dose contra a covid-19 - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/","og_locale":"pt_BR","og_type":"article","og_title":"Pessoas com 23 anos podem tomar a 1\u00ba dose contra a covid-19 - R\u00e1dio Life FM","og_description":"Imuniza\u00e7\u00e3o ser\u00e1 nesta quarta-feira (4) no CIS das 13h30 \u00e0s 19h &nbsp; A Secretaria de Sa\u00fade de Adamantina informa que est\u00e1 aberta a vacina\u00e7\u00e3o contra a covid-19 para pessoas com 23 anos a partir desta quarta-feira (4). A estimativa \u00e9 que\u00a0 536 pessoas recebam\u00a0a primeira dose da vacina. &nbsp; A imuniza\u00e7\u00e3o acontece no CIS (Centro [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2021-08-03T17:39:12+00:00","article_modified_time":"2026-05-01T22:32:49+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Pessoas com 23 anos podem tomar a 1\u00ba dose contra a covid-19","datePublished":"2021-08-03T17:39:12+00:00","dateModified":"2026-05-01T22:32:49+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/"},"wordCount":121,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/","url":"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/","name":"Pessoas com 23 anos podem tomar a 1\u00ba dose contra a covid-19 - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg","datePublished":"2021-08-03T17:39:12+00:00","dateModified":"2026-05-01T22:32:49+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/pessoas-com-23-anos-podem-tomar-a-1o-dose-contra-a-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Pessoas com 23 anos podem tomar a 1\u00ba dose contra a covid-19"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/41326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=41326"}],"version-history":[{"count":2,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/41326\/revisions"}],"predecessor-version":[{"id":41328,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/41326\/revisions\/41328"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/39259"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=41326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=41326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=41326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}