{"id":41282,"date":"2021-08-02T10:19:06","date_gmt":"2021-08-02T13:19:06","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=41282"},"modified":"2026-04-12T00:55:59","modified_gmt":"2026-04-12T03:55:59","slug":"sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/","title":{"rendered":"SP recebe insumos para fabrica\u00e7\u00e3o de mais 4 milh\u00f5es de doses da vacina do Butantan"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>O secret\u00e1rio da Sa\u00fade de S\u00e3o Paulo, Jean Gorinchteyn, a coordenadora do Plano Estadual de Imuniza\u00e7\u00e3o, Regiane de Paula, e o superintendente do Butantan, Reinaldo Sato, acompanharam na noite deste domingo (1\u00ba), a chegada de um lote de 2 mil litros de Insumo Farmac\u00eautico Ativo (IFA) que ir\u00e3o viabilizar a produ\u00e7\u00e3o de cerca de quatro milh\u00f5es de doses da vacina contra o novo coronav\u00edrus, destinadas ao Programa Nacional de Imuniza\u00e7\u00f5es (PNI).<\/p>\n<p>&nbsp;<\/p>\n<p>A nova remessa chegou no Aeroporto Internacional de Guarulhos \u00e0s 21 horas em um voo da companhia Turkish Airlines, que saiu de Pequim (China) e fez escala em Istambul (Turquia) antes de pousar em S\u00e3o Paulo.<\/p>\n<p>&nbsp;<\/p>\n<p>A mat\u00e9ria-prima, enviada pela biofarmac\u00eautica Sinovac, parceira do Butantan, passar\u00e1 pelos processos de envase, rotulagem, embalagem e por um r\u00edgido processo de controle de qualidade antes de serem disponibilizadas para a popula\u00e7\u00e3o por interm\u00e9dio do Minist\u00e9rio da Sa\u00fade.<\/p>\n<p>&nbsp;<\/p>\n<p>At\u00e9 o momento, o Butantan j\u00e1 disponibilizou 62,8 milh\u00f5es de doses do imunizante ao Minist\u00e9rio da Sa\u00fade desde 17 de janeiro deste ano, quando o uso emergencial do imunizante foi aprovado pela Ag\u00eancia Nacional de Vigil\u00e2ncia Sanit\u00e1ria (Anvisa).<\/p>\n<p>&nbsp;<\/p>\n<p>Desde o dia 14 de julho at\u00e9 hoje, foram entregues um total de 9,7 milh\u00f5es de doses da vacina, que s\u00e3o referentes \u00e0 produ\u00e7\u00e3o de um lote de doses processadas a partir dos 6 mil litros de Ingrediente Farmac\u00eautico Ativo (IFA), recebidos no dia 26 de junho.<\/p>\n<p>&nbsp;<\/p>\n<p>Na madrugada do dia 13 de julho, o instituto recebeu carga recorde de 12 mil litros de mat\u00e9ria-prima para produzir e entregar outras 20 milh\u00f5es de doses.<\/p>\n<p>&nbsp;<\/p>\n<p>As vacinas liberadas hoje fazem parte do segundo contrato firmado com o Minist\u00e9rio da Sa\u00fade, de 54 milh\u00f5es de vacinas. O primeiro, de 46 milh\u00f5es, foi conclu\u00eddo em 12 de maio.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: Portal do Governo de SP<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O secret\u00e1rio da Sa\u00fade de S\u00e3o Paulo, Jean Gorinchteyn, a coordenadora do Plano Estadual de Imuniza\u00e7\u00e3o, Regiane de Paula, e o superintendente do Butantan, Reinaldo Sato, acompanharam na noite deste domingo (1\u00ba), a chegada de um lote de 2 mil litros de Insumo Farmac\u00eautico Ativo (IFA) que ir\u00e3o viabilizar a produ\u00e7\u00e3o de cerca de quatro [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":41283,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-41282","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SP recebe insumos para fabrica\u00e7\u00e3o de mais 4 milh\u00f5es de doses da vacina do Butantan - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SP recebe insumos para fabrica\u00e7\u00e3o de mais 4 milh\u00f5es de doses da vacina do Butantan - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"O secret\u00e1rio da Sa\u00fade de S\u00e3o Paulo, Jean Gorinchteyn, a coordenadora do Plano Estadual de Imuniza\u00e7\u00e3o, Regiane de Paula, e o superintendente do Butantan, Reinaldo Sato, acompanharam na noite deste domingo (1\u00ba), a chegada de um lote de 2 mil litros de Insumo Farmac\u00eautico Ativo (IFA) que ir\u00e3o viabilizar a produ\u00e7\u00e3o de cerca de quatro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-02T13:19:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-12T03:55:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/08\/51351311051_63d47f727e_k.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"SP recebe insumos para fabrica\u00e7\u00e3o de mais 4 milh\u00f5es de doses da vacina do Butantan\",\"datePublished\":\"2021-08-02T13:19:06+00:00\",\"dateModified\":\"2026-04-12T03:55:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/\"},\"wordCount\":336,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/08\/51351311051_63d47f727e_k.jpg\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/\",\"name\":\"SP recebe insumos para fabrica\u00e7\u00e3o de mais 4 milh\u00f5es de doses da vacina do Butantan - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/08\/51351311051_63d47f727e_k.jpg\",\"datePublished\":\"2021-08-02T13:19:06+00:00\",\"dateModified\":\"2026-04-12T03:55:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/08\/51351311051_63d47f727e_k.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/08\/51351311051_63d47f727e_k.jpg\",\"width\":750,\"height\":375,\"caption\":\"Voo com 2 mil litros de IFA chegou de Pequim na noite deste domingo (1\u00ba) no Aeroporto Internacional de Guarulhos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SP recebe insumos para fabrica\u00e7\u00e3o de mais 4 milh\u00f5es de doses da vacina do Butantan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SP recebe insumos para fabrica\u00e7\u00e3o de mais 4 milh\u00f5es de doses da vacina do Butantan - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/","og_locale":"pt_BR","og_type":"article","og_title":"SP recebe insumos para fabrica\u00e7\u00e3o de mais 4 milh\u00f5es de doses da vacina do Butantan - R\u00e1dio Life FM","og_description":"O secret\u00e1rio da Sa\u00fade de S\u00e3o Paulo, Jean Gorinchteyn, a coordenadora do Plano Estadual de Imuniza\u00e7\u00e3o, Regiane de Paula, e o superintendente do Butantan, Reinaldo Sato, acompanharam na noite deste domingo (1\u00ba), a chegada de um lote de 2 mil litros de Insumo Farmac\u00eautico Ativo (IFA) que ir\u00e3o viabilizar a produ\u00e7\u00e3o de cerca de quatro [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2021-08-02T13:19:06+00:00","article_modified_time":"2026-04-12T03:55:59+00:00","og_image":[{"width":750,"height":375,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/08\/51351311051_63d47f727e_k.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"SP recebe insumos para fabrica\u00e7\u00e3o de mais 4 milh\u00f5es de doses da vacina do Butantan","datePublished":"2021-08-02T13:19:06+00:00","dateModified":"2026-04-12T03:55:59+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/"},"wordCount":336,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/08\/51351311051_63d47f727e_k.jpg","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/","url":"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/","name":"SP recebe insumos para fabrica\u00e7\u00e3o de mais 4 milh\u00f5es de doses da vacina do Butantan - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/08\/51351311051_63d47f727e_k.jpg","datePublished":"2021-08-02T13:19:06+00:00","dateModified":"2026-04-12T03:55:59+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/08\/51351311051_63d47f727e_k.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/08\/51351311051_63d47f727e_k.jpg","width":750,"height":375,"caption":"Voo com 2 mil litros de IFA chegou de Pequim na noite deste domingo (1\u00ba) no Aeroporto Internacional de Guarulhos"},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/sp-recebe-insumos-para-fabricacao-de-mais-4-milhoes-de-doses-da-vacina-do-butantan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"SP recebe insumos para fabrica\u00e7\u00e3o de mais 4 milh\u00f5es de doses da vacina do Butantan"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/41282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=41282"}],"version-history":[{"count":1,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/41282\/revisions"}],"predecessor-version":[{"id":41284,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/41282\/revisions\/41284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/41283"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=41282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=41282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=41282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}