{"id":40680,"date":"2021-07-14T16:39:03","date_gmt":"2021-07-14T19:39:03","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=40680"},"modified":"2025-11-07T17:26:16","modified_gmt":"2025-11-07T20:26:16","slug":"publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/","title":{"rendered":"P\u00fablico que tem 32 anos come\u00e7a a ser imunizado em Adamantina a partir de amanh\u00e3 (15)"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>A Prefeitura de Adamantina, por meio da Secretaria de Sa\u00fade, informa que a partir desta quinta-feira (15) a primeira dose da vacina contra a COVID-19 ser\u00e1 aplicada em pessoas que t\u00eam 32 anos.<\/p>\n<p>A estimativa \u00e9 que o munic\u00edpio tenha aproximadamente 450 habitantes com a faixa et\u00e1ria.<\/p>\n<p>&nbsp;<\/p>\n<p>Quem teve a aplica\u00e7\u00e3o da segunda dose previamente agendada tamb\u00e9m devem procurar o Centro Integrado de Sa\u00fade (CIS) para que o esquema vacinal fique completo.<\/p>\n<p>&nbsp;<\/p>\n<p>A imuniza\u00e7\u00e3o \u00e9 realizada no CIS das 14 \u00e0s 20h. A pasta tomou essa medida com o objetivo de garantir acesso \u00e0 vacina \u00e0 popula\u00e7\u00e3o da faixa et\u00e1ria que trabalha durante o dia. A vacina\u00e7\u00e3o dos grupos que t\u00eam de 33 a 59 anos continua e ocorre das 14h \u00e0s 20h.<\/p>\n<p>&nbsp;<\/p>\n<p>Aqueles que desejarem podem ir a p\u00e9 at\u00e9 o CIS e a pasta recomenda que o pr\u00e9-cadastro no site\u00a0<a href=\"http:\/\/www.vacinaja.sp.gov.br\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.vacinaja.sp.gov.br\/&amp;source=gmail&amp;ust=1626377860094000&amp;usg=AFQjCNF0TVQBtUr1l2YGc_ip997US7CUSg\">www.vacinaja.sp.gov.br<\/a>\u00a0seja feito, pois assim o processo de vacina\u00e7\u00e3o ter\u00e1 maior agilidade.<\/p>\n<p>&nbsp;<\/p>\n<p>Na \u00faltima ter\u00e7a-feira (13) foram vacinadas 168 pessoas com a primeira dose e 558 com a segunda dose, totalizando 726 mun\u00edcipes.<\/p>\n<p>A secretaria de sa\u00fade ressalta que independentemente do tipo de imunobiol\u00f3gico, o importante \u00e9 ser imunizado, pois assim o munic\u00edpio vai parar de sofrer com as consequ\u00eancias da pandemia.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Campanha Vacina contra Fome<\/strong><\/p>\n<p>Aqueles que quiserem contribuir de forma volunt\u00e1ria com a Campanha Vacina contra a Fome podem entregar no CIS um quilo de alimento n\u00e3o perec\u00edvel.<\/p>\n<p>Fonte: Assessoria de Imprensa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Adamantina, por meio da Secretaria de Sa\u00fade, informa que a partir desta quinta-feira (15) a primeira dose da vacina contra a COVID-19 ser\u00e1 aplicada em pessoas que t\u00eam 32 anos. A estimativa \u00e9 que o munic\u00edpio tenha aproximadamente 450 habitantes com a faixa et\u00e1ria. &nbsp; Quem teve a aplica\u00e7\u00e3o da segunda dose [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":39259,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-40680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>P\u00fablico que tem 32 anos come\u00e7a a ser imunizado em Adamantina a partir de amanh\u00e3 (15) - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P\u00fablico que tem 32 anos come\u00e7a a ser imunizado em Adamantina a partir de amanh\u00e3 (15) - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura de Adamantina, por meio da Secretaria de Sa\u00fade, informa que a partir desta quinta-feira (15) a primeira dose da vacina contra a COVID-19 ser\u00e1 aplicada em pessoas que t\u00eam 32 anos. A estimativa \u00e9 que o munic\u00edpio tenha aproximadamente 450 habitantes com a faixa et\u00e1ria. &nbsp; Quem teve a aplica\u00e7\u00e3o da segunda dose [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-14T19:39:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-07T20:26:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"P\u00fablico que tem 32 anos come\u00e7a a ser imunizado em Adamantina a partir de amanh\u00e3 (15)\",\"datePublished\":\"2021-07-14T19:39:03+00:00\",\"dateModified\":\"2025-11-07T20:26:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/\"},\"wordCount\":269,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/\",\"name\":\"P\u00fablico que tem 32 anos come\u00e7a a ser imunizado em Adamantina a partir de amanh\u00e3 (15) - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg\",\"datePublished\":\"2021-07-14T19:39:03+00:00\",\"dateModified\":\"2025-11-07T20:26:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"P\u00fablico que tem 32 anos come\u00e7a a ser imunizado em Adamantina a partir de amanh\u00e3 (15)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"P\u00fablico que tem 32 anos come\u00e7a a ser imunizado em Adamantina a partir de amanh\u00e3 (15) - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/","og_locale":"pt_BR","og_type":"article","og_title":"P\u00fablico que tem 32 anos come\u00e7a a ser imunizado em Adamantina a partir de amanh\u00e3 (15) - R\u00e1dio Life FM","og_description":"A Prefeitura de Adamantina, por meio da Secretaria de Sa\u00fade, informa que a partir desta quinta-feira (15) a primeira dose da vacina contra a COVID-19 ser\u00e1 aplicada em pessoas que t\u00eam 32 anos. A estimativa \u00e9 que o munic\u00edpio tenha aproximadamente 450 habitantes com a faixa et\u00e1ria. &nbsp; Quem teve a aplica\u00e7\u00e3o da segunda dose [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2021-07-14T19:39:03+00:00","article_modified_time":"2025-11-07T20:26:16+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"P\u00fablico que tem 32 anos come\u00e7a a ser imunizado em Adamantina a partir de amanh\u00e3 (15)","datePublished":"2021-07-14T19:39:03+00:00","dateModified":"2025-11-07T20:26:16+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/"},"wordCount":269,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/","url":"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/","name":"P\u00fablico que tem 32 anos come\u00e7a a ser imunizado em Adamantina a partir de amanh\u00e3 (15) - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg","datePublished":"2021-07-14T19:39:03+00:00","dateModified":"2025-11-07T20:26:16+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/vacina-1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/publico-que-tem-32-anos-comeca-a-ser-imunizado-em-adamantina-a-partir-de-amanha-15\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"P\u00fablico que tem 32 anos come\u00e7a a ser imunizado em Adamantina a partir de amanh\u00e3 (15)"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/40680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=40680"}],"version-history":[{"count":4,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/40680\/revisions"}],"predecessor-version":[{"id":40684,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/40680\/revisions\/40684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/39259"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=40680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=40680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=40680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}