{"id":39775,"date":"2021-06-13T18:57:11","date_gmt":"2021-06-13T21:57:11","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=39775"},"modified":"2026-04-27T13:42:48","modified_gmt":"2026-04-27T16:42:48","slug":"39775-2adamantinaadamantina","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/","title":{"rendered":"SP apresenta novo calend\u00e1rio para vacinar toda a popula\u00e7\u00e3o adulta at\u00e9 15 de setembro"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p style=\"font-weight: 400\">O governador Jo\u00e3o Doria anunciou neste domingo (13) que toda a popula\u00e7\u00e3o adulta dos 645 munic\u00edpios de S\u00e3o Paulo dever\u00e1 estar vacinada contra a Covid-19 at\u00e9 15 de setembro, antecipando em 33 dias a estimativa de conclus\u00e3o do cronograma anterior. Com o novo calend\u00e1rio, pessoas com idade a partir de 40 anos poder\u00e3o se vacinar contra o coronav\u00edrus ainda neste m\u00eas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400\">&#8220;Pessoas na faixa et\u00e1ria de 40 a 59 anos que seriam vacinadas apenas no m\u00eas de julho agora ser\u00e3o vacinadas em junho. Isso \u00e9 fruto de trabalho planejamento e log\u00edstica do sistema de sa\u00fade p\u00fablica de S\u00e3o Paulo. \u00c9 uma vit\u00f3ria do trabalho e da ci\u00eancia, de respeito \u00e0 sa\u00fade e \u00e0 vida e senso de urg\u00eancia para proteger vidas. A vacina vai vencer o v\u00edrus, a sa\u00fade vai vencer o negacionismo e n\u00f3s, aqui em S\u00e3o Paulo, estamos ao lado da ci\u00eancia, da sa\u00fade e da vida&#8221;, declarou o governador.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400\">Trata-se do maior avan\u00e7o j\u00e1 definido na campanha de vacina\u00e7\u00e3o contra o coronav\u00edrus em S\u00e3o Paulo, com doses garantidas para in\u00edcio da imuniza\u00e7\u00e3o dos adultos de 40 a 59 anos ainda em junho. Somente neste m\u00eas, a previs\u00e3o do PEI (Programa Estadual de Imuniza\u00e7\u00e3o) \u00e9 que 7,45 milh\u00f5es de adultos do Estado de S\u00e3o Paulo recebam a primeira dose at\u00e9 o final deste m\u00eas.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400\">O novo p\u00fablico de 40 a 59 anos agrupa quatro grupos previamente definidos &#8211; antes, estavam previstas subdivis\u00f5es em grupos de cinco anos para cada nova expans\u00e3o da campanha.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400\">&#8220;Hoje \u00e9 um dia muito especial. Estamos demonstrando aqui o quanto o estado de S\u00e3o Paulo e o Programa Estadual de Imuniza\u00e7\u00e3o t\u00eam sido rigorosos planejando as estrat\u00e9gias de vacina\u00e7\u00e3o e, assim, pudemos antecipar o nosso calend\u00e1rio de vacina\u00e7\u00e3o&#8221;, afirmou Regiane de Paula, Coordenadora do PEI.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400\">A partir da pr\u00f3xima quarta-feira (16), as doses poder\u00e3o ser aplicadas em qualquer pessoa na faixa de 50 a 59 anos. Pelo cronograma anterior, esta data estava definida para as pessoas com idade entre 55 e 59 anos, e agora o alcance foi expandido.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400\">A partir do dia 23 de junho, S\u00e3o Paulo vai vacinar a popula\u00e7\u00e3o com idade entre 43 e 49 anos. No dia 30 de junho \u00faltima quarta-feira deste m\u00eas, come\u00e7a a imuniza\u00e7\u00e3o dos que t\u00eam entre 40 a 42 anos.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400\">No dia 15 de julho, a campanha ser\u00e1 estendida para a popula\u00e7\u00e3o de 35 a 39 anos. Depois, no dia 30 de julho, as pessoas com idade entre 30 e 34 anos tamb\u00e9m poder\u00e3o ser vacinadas contra a COVID-19. A partir de 16 de agosto, a vacina\u00e7\u00e3o se estende para os adultos mais jovens, com idade entre 25 a 29 anos. Por fim, a partir de 1 de setembro, todos os adultos a partir de 18 anos poder\u00e3o iniciar a imuniza\u00e7\u00e3o contra o coronav\u00edrus, com t\u00e9rmino previsto de aplica\u00e7\u00e3o da primeira dose para o dia 15 de setembro.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400\">A amplia\u00e7\u00e3o dos p\u00fablicos-alvo e a proje\u00e7\u00e3o do novo calend\u00e1rio se baseiam nas estimativas de entregas do Minist\u00e9rio da Sa\u00fade. Com a chegada ao Brasil dos novos imunizantes da Pfizer e da Janssen e mais entregas das vacinas do Butantan e da Fiocruz \/ Astrazeneca, S\u00e3o Paulo recalculou o cronograma e est\u00e1 intensificando a log\u00edstica e distribui\u00e7\u00e3o dos imunizantes para os 645 munic\u00edpios.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400\">O ritmo de vacina\u00e7\u00e3o poder\u00e1 ser quatro vezes mais intenso que o verificado na fase inicial da campanha. Para efeito comparativo, a marca de vacina\u00e7\u00e3o de 7,5 milh\u00f5es de pessoas com a primeira dose das vacinas do Butantan ou Fiocruz foi atingida em 29 de abril, 15 semanas ap\u00f3s o in\u00edcio da campanha.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400\">Com as novas remessas, ser\u00e1 poss\u00edvel vacinar a mesma quantidade de pessoas em cerca de 25% deste tempo &#8211; o novo cronograma prev\u00ea alcan\u00e7ar estes p\u00fablicos em 28 dias.<\/p>\n<figure id=\"attachment_39776\" aria-describedby=\"caption-attachment-39776\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-39776\" src=\"https:\/\/static.radiolifefm.com.br\/wp-content\/uploads\/sites\/2\/2021\/06\/512445181465b375c4d06cjpg162360516760c63faf79427.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/06\/512445181465b375c4d06cjpg162360516760c63faf79427.jpg 800w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/06\/512445181465b375c4d06cjpg162360516760c63faf79427-300x200.jpg 300w, https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/06\/512445181465b375c4d06cjpg162360516760c63faf79427-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-39776\" class=\"wp-caption-text\">Novo calend\u00e1rio com a previs\u00e3o atualizada de vacina\u00e7\u00e3o foi divulgado neste domingo (13).<\/figcaption><\/figure>\n<p>Fonte: Siga Mais<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador Jo\u00e3o Doria anunciou neste domingo (13) que toda a popula\u00e7\u00e3o adulta dos 645 munic\u00edpios de S\u00e3o Paulo dever\u00e1 estar vacinada contra a Covid-19 at\u00e9 15 de setembro, antecipando em 33 dias a estimativa de conclus\u00e3o do cronograma anterior. Com o novo calend\u00e1rio, pessoas com idade a partir de 40 anos poder\u00e3o se vacinar [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":39777,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-39775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SP apresenta novo calend\u00e1rio para vacinar toda a popula\u00e7\u00e3o adulta at\u00e9 15 de setembro - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SP apresenta novo calend\u00e1rio para vacinar toda a popula\u00e7\u00e3o adulta at\u00e9 15 de setembro - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"O governador Jo\u00e3o Doria anunciou neste domingo (13) que toda a popula\u00e7\u00e3o adulta dos 645 munic\u00edpios de S\u00e3o Paulo dever\u00e1 estar vacinada contra a Covid-19 at\u00e9 15 de setembro, antecipando em 33 dias a estimativa de conclus\u00e3o do cronograma anterior. Com o novo calend\u00e1rio, pessoas com idade a partir de 40 anos poder\u00e3o se vacinar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-13T21:57:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-27T16:42:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/06\/vacjpg162360488360c63e9338c20.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"SP apresenta novo calend\u00e1rio para vacinar toda a popula\u00e7\u00e3o adulta at\u00e9 15 de setembro\",\"datePublished\":\"2021-06-13T21:57:11+00:00\",\"dateModified\":\"2026-04-27T16:42:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/\"},\"wordCount\":703,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/06\/vacjpg162360488360c63e9338c20.jpg\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/\",\"name\":\"SP apresenta novo calend\u00e1rio para vacinar toda a popula\u00e7\u00e3o adulta at\u00e9 15 de setembro - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/06\/vacjpg162360488360c63e9338c20.jpg\",\"datePublished\":\"2021-06-13T21:57:11+00:00\",\"dateModified\":\"2026-04-27T16:42:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/06\/vacjpg162360488360c63e9338c20.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/06\/vacjpg162360488360c63e9338c20.jpg\",\"width\":600,\"height\":338,\"caption\":\"Novo calend\u00e1rio com a previs\u00e3o atualizada de vacina\u00e7\u00e3o foi divulgado neste domingo (13).\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SP apresenta novo calend\u00e1rio para vacinar toda a popula\u00e7\u00e3o adulta at\u00e9 15 de setembro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SP apresenta novo calend\u00e1rio para vacinar toda a popula\u00e7\u00e3o adulta at\u00e9 15 de setembro - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/","og_locale":"pt_BR","og_type":"article","og_title":"SP apresenta novo calend\u00e1rio para vacinar toda a popula\u00e7\u00e3o adulta at\u00e9 15 de setembro - R\u00e1dio Life FM","og_description":"O governador Jo\u00e3o Doria anunciou neste domingo (13) que toda a popula\u00e7\u00e3o adulta dos 645 munic\u00edpios de S\u00e3o Paulo dever\u00e1 estar vacinada contra a Covid-19 at\u00e9 15 de setembro, antecipando em 33 dias a estimativa de conclus\u00e3o do cronograma anterior. Com o novo calend\u00e1rio, pessoas com idade a partir de 40 anos poder\u00e3o se vacinar [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2021-06-13T21:57:11+00:00","article_modified_time":"2026-04-27T16:42:48+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/06\/vacjpg162360488360c63e9338c20.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"SP apresenta novo calend\u00e1rio para vacinar toda a popula\u00e7\u00e3o adulta at\u00e9 15 de setembro","datePublished":"2021-06-13T21:57:11+00:00","dateModified":"2026-04-27T16:42:48+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/"},"wordCount":703,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/06\/vacjpg162360488360c63e9338c20.jpg","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/","url":"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/","name":"SP apresenta novo calend\u00e1rio para vacinar toda a popula\u00e7\u00e3o adulta at\u00e9 15 de setembro - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/06\/vacjpg162360488360c63e9338c20.jpg","datePublished":"2021-06-13T21:57:11+00:00","dateModified":"2026-04-27T16:42:48+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/06\/vacjpg162360488360c63e9338c20.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/06\/vacjpg162360488360c63e9338c20.jpg","width":600,"height":338,"caption":"Novo calend\u00e1rio com a previs\u00e3o atualizada de vacina\u00e7\u00e3o foi divulgado neste domingo (13)."},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/39775-2adamantinaadamantina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"SP apresenta novo calend\u00e1rio para vacinar toda a popula\u00e7\u00e3o adulta at\u00e9 15 de setembro"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/39775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=39775"}],"version-history":[{"count":10,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/39775\/revisions"}],"predecessor-version":[{"id":39787,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/39775\/revisions\/39787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/39777"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=39775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=39775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=39775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}