{"id":38844,"date":"2021-05-17T09:10:35","date_gmt":"2021-05-17T12:10:35","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=38844"},"modified":"2026-04-04T22:22:16","modified_gmt":"2026-04-05T01:22:16","slug":"113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/","title":{"rendered":"113 pessoas n\u00e3o compareceram para tomar a 2\u00aa dose da vacina contra a Covid-19 em Adamantina"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>A reportagem do Folha Regional solicitou \u00e0 Secretaria Municipal de Sa\u00fade n\u00fameros relacionados ao n\u00e3o comparecimento de adamantinenses para receberem a 2\u00aa dose da vacina contra a Covid19 entre os p\u00fablicos j\u00e1 vacinados no munic\u00edpio.<\/p>\n<p>&nbsp;<\/p>\n<p>Os dados passados, de acordo com o sistema de informa\u00e7\u00e3o VACIVIDA, at\u00e9 o momento, 113 pessoas est\u00e3o atrasadas.<\/p>\n<p>&nbsp;<\/p>\n<p>Entre estes existem 53 idosos que n\u00e3o receberam a 2\u00aa dose da CoronaVac, al\u00e9m de 50 trabalhadores da Sa\u00fade, dos quais, 27 CoronaVac\/ Butatan e 24 da Astrazeneca\/ Oxford\/Fiocruz, e, ainda, 7 trabalhadores da Educa\u00e7\u00e3o pendentes com a CoronaVac.<\/p>\n<p>&nbsp;<\/p>\n<p>Ao questionar sobre, mesmo passado o prazo indicado para o recebimento da 2\u00aa dose as pessoas ainda podem tomar o complemento do imunizante, a Secretaria informou que \u201co importante \u00e9 completar o esquema vacinal, tomando as duas doses do imunizante. Lembrando que a 2\u00aa dose deve ser com o mesmo imunizante recebido na primeira dose.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>A respeito do destino dado para as doses recebidas para os pendentes destes grupos, a Sa\u00fade explicou que s\u00e3o sempre em grade fechadas ou vem para 1\u00ba dose e depois vem para a 2\u00aa dose. \u201cA orienta\u00e7\u00e3o do PNI \u00e9 para n\u00e3o guardar as doses para n\u00e3o haver o risco de perder as doses devido a validade curta do imunizante\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>A Secretaria Municipal de Sa\u00fade esclareceu tamb\u00e9m que a 2\u00aa dose foi aprazada para 21 dias da 1\u00aa dose, visto que a 2\u00aa dose poder\u00e1 ser realizada at\u00e9 28 dias da 1\u00ba dose. \u201cCaso alguma ocorr\u00eancia impe\u00e7a a pessoa de retornar no prazo determinado, \u00e9 imprescind\u00edvel que a 2\u00aa dose seja administrada assim que poss\u00edvel\u201d. Ao receber a 2\u00aa dose a popula\u00e7\u00e3o ser\u00e1 comunicada atrav\u00e9s da imprensa e tamb\u00e9m nas unidades de sa\u00fade.<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: Adamantina Net<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A reportagem do Folha Regional solicitou \u00e0 Secretaria Municipal de Sa\u00fade n\u00fameros relacionados ao n\u00e3o comparecimento de adamantinenses para receberem a 2\u00aa dose da vacina contra a Covid19 entre os p\u00fablicos j\u00e1 vacinados no munic\u00edpio. &nbsp; Os dados passados, de acordo com o sistema de informa\u00e7\u00e3o VACIVIDA, at\u00e9 o momento, 113 pessoas est\u00e3o atrasadas. &nbsp; [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":38845,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-38844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>113 pessoas n\u00e3o compareceram para tomar a 2\u00aa dose da vacina contra a Covid-19 em Adamantina - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"113 pessoas n\u00e3o compareceram para tomar a 2\u00aa dose da vacina contra a Covid-19 em Adamantina - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"A reportagem do Folha Regional solicitou \u00e0 Secretaria Municipal de Sa\u00fade n\u00fameros relacionados ao n\u00e3o comparecimento de adamantinenses para receberem a 2\u00aa dose da vacina contra a Covid19 entre os p\u00fablicos j\u00e1 vacinados no munic\u00edpio. &nbsp; Os dados passados, de acordo com o sistema de informa\u00e7\u00e3o VACIVIDA, at\u00e9 o momento, 113 pessoas est\u00e3o atrasadas. &nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-17T12:10:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-05T01:22:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/F49.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"113 pessoas n\u00e3o compareceram para tomar a 2\u00aa dose da vacina contra a Covid-19 em Adamantina\",\"datePublished\":\"2021-05-17T12:10:35+00:00\",\"dateModified\":\"2026-04-05T01:22:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/\"},\"wordCount\":307,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/F49.jpg\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/\",\"name\":\"113 pessoas n\u00e3o compareceram para tomar a 2\u00aa dose da vacina contra a Covid-19 em Adamantina - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/F49.jpg\",\"datePublished\":\"2021-05-17T12:10:35+00:00\",\"dateModified\":\"2026-04-05T01:22:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/F49.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/F49.jpg\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"113 pessoas n\u00e3o compareceram para tomar a 2\u00aa dose da vacina contra a Covid-19 em Adamantina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"113 pessoas n\u00e3o compareceram para tomar a 2\u00aa dose da vacina contra a Covid-19 em Adamantina - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/","og_locale":"pt_BR","og_type":"article","og_title":"113 pessoas n\u00e3o compareceram para tomar a 2\u00aa dose da vacina contra a Covid-19 em Adamantina - R\u00e1dio Life FM","og_description":"A reportagem do Folha Regional solicitou \u00e0 Secretaria Municipal de Sa\u00fade n\u00fameros relacionados ao n\u00e3o comparecimento de adamantinenses para receberem a 2\u00aa dose da vacina contra a Covid19 entre os p\u00fablicos j\u00e1 vacinados no munic\u00edpio. &nbsp; Os dados passados, de acordo com o sistema de informa\u00e7\u00e3o VACIVIDA, at\u00e9 o momento, 113 pessoas est\u00e3o atrasadas. &nbsp; [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2021-05-17T12:10:35+00:00","article_modified_time":"2026-04-05T01:22:16+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/F49.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"113 pessoas n\u00e3o compareceram para tomar a 2\u00aa dose da vacina contra a Covid-19 em Adamantina","datePublished":"2021-05-17T12:10:35+00:00","dateModified":"2026-04-05T01:22:16+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/"},"wordCount":307,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/F49.jpg","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/","url":"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/","name":"113 pessoas n\u00e3o compareceram para tomar a 2\u00aa dose da vacina contra a Covid-19 em Adamantina - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/F49.jpg","datePublished":"2021-05-17T12:10:35+00:00","dateModified":"2026-04-05T01:22:16+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/F49.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/05\/F49.jpg","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/113-pessoas-nao-compareceram-para-tomar-a-2a-dose-da-vacina-contra-a-covid-19-em-adamantina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"113 pessoas n\u00e3o compareceram para tomar a 2\u00aa dose da vacina contra a Covid-19 em Adamantina"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/38844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=38844"}],"version-history":[{"count":3,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/38844\/revisions"}],"predecessor-version":[{"id":38848,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/38844\/revisions\/38848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/38845"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=38844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=38844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=38844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}