{"id":35010,"date":"2021-02-18T22:24:23","date_gmt":"2021-02-19T01:24:23","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=35010"},"modified":"2026-05-10T09:57:37","modified_gmt":"2026-05-10T12:57:37","slug":"equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/","title":{"rendered":"Equipe da Santa Casa de Adamantina, cansados mas n\u00e3o desanimados. A luta est\u00e1 cada vez maior"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>Em meio a tantas postagens \u00a0em redes sociais sobre trag\u00e9dias, acidentes, entre outras, uma mensagem chama a aten\u00e7\u00e3o e viraliza nas redes sociais em Adamantina.<\/p>\n<p>&nbsp;<\/p>\n<p>A jovem Carolina Ridania, publica uma foto que estampa a realidade dos profissionais da sa\u00fade da Santa Casa de Adamantina, com um texto muito bonito.<\/p>\n<p>&nbsp;<\/p>\n<p>Santa Casa de Adamantina , 18\/02\/2021 \u00e0s 16:30h equipe do isolamento Covid descansando sentados no ch\u00e3o entregues ? N\u00e3o &#8230; esperando para tomar banho para a terceira emerg\u00eancia do dia , enquanto recebem for\u00e7a espiritual , essa guerra que parecia acabar est\u00e1 s\u00f3 come\u00e7ando .<\/p>\n<p>&nbsp;<\/p>\n<p>Me sinto orgulhosa em ver essa equipe assim totalmente entregue , literalmente entregue &#8230;no ch\u00e3o , mas que em poucos instantes levantam colocam uma nova roupa e seguem para a batalha contra esse inimigo invis\u00edvel que est\u00e1 destruindo nossas vidas.<\/p>\n<p>&nbsp;<\/p>\n<p>Orgulho e honra de ter voc\u00eas &#8230;<\/p>\n<p>&nbsp;<\/p>\n<p>N\u00f3s tamb\u00e9m sentimos orgulho de cada profissional que esta a frente desse trabalho, e agradecemos por tudo o que cada um de voc\u00eas tem feito por cada paciente que chega at\u00e9 voc\u00eas.<\/p>\n<p>&nbsp;<\/p>\n<p>E pedimos a popula\u00e7\u00e3o, que tenha consci\u00eancia de seus atos, respeitem as regras do isolamento social, saia de casa se realmente for necess\u00e1rio, evite festas e aglomera\u00e7\u00f5es.<\/p>\n<p>&nbsp;<\/p>\n<p>Esses profissionais que zelam por nossas vidas, tamb\u00e9m tem fam\u00edlias, e precisam zelar por si e por seus familiares.<\/p>\n<p>&nbsp;<\/p>\n<p>Reda\u00e7\u00e3o: R\u00e1dio Life FM \u2013 Com informa\u00e7\u00f5es da postagem \u00a0via Facebook d\u00ea Carolina Ridania.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em meio a tantas postagens \u00a0em redes sociais sobre trag\u00e9dias, acidentes, entre outras, uma mensagem chama a aten\u00e7\u00e3o e viraliza nas redes sociais em Adamantina. &nbsp; A jovem Carolina Ridania, publica uma foto que estampa a realidade dos profissionais da sa\u00fade da Santa Casa de Adamantina, com um texto muito bonito. &nbsp; Santa Casa de [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":35011,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21,35],"tags":[],"class_list":["post-35010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-adamantina","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Equipe da Santa Casa de Adamantina, cansados mas n\u00e3o desanimados. A luta est\u00e1 cada vez maior - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equipe da Santa Casa de Adamantina, cansados mas n\u00e3o desanimados. A luta est\u00e1 cada vez maior - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Em meio a tantas postagens \u00a0em redes sociais sobre trag\u00e9dias, acidentes, entre outras, uma mensagem chama a aten\u00e7\u00e3o e viraliza nas redes sociais em Adamantina. &nbsp; A jovem Carolina Ridania, publica uma foto que estampa a realidade dos profissionais da sa\u00fade da Santa Casa de Adamantina, com um texto muito bonito. &nbsp; Santa Casa de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-19T01:24:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-10T12:57:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/02\/152258286_3680200075379520_2795660896008638357_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"958\" \/>\n\t<meta property=\"og:image:height\" content=\"958\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Equipe da Santa Casa de Adamantina, cansados mas n\u00e3o desanimados. A luta est\u00e1 cada vez maior\",\"datePublished\":\"2021-02-19T01:24:23+00:00\",\"dateModified\":\"2026-05-10T12:57:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/\"},\"wordCount\":273,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/02\/152258286_3680200075379520_2795660896008638357_n.jpg\",\"articleSection\":[\"Adamantina\",\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/\",\"name\":\"Equipe da Santa Casa de Adamantina, cansados mas n\u00e3o desanimados. A luta est\u00e1 cada vez maior - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/02\/152258286_3680200075379520_2795660896008638357_n.jpg\",\"datePublished\":\"2021-02-19T01:24:23+00:00\",\"dateModified\":\"2026-05-10T12:57:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/02\/152258286_3680200075379520_2795660896008638357_n.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/02\/152258286_3680200075379520_2795660896008638357_n.jpg\",\"width\":958,\"height\":958},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Equipe da Santa Casa de Adamantina, cansados mas n\u00e3o desanimados. A luta est\u00e1 cada vez maior\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Equipe da Santa Casa de Adamantina, cansados mas n\u00e3o desanimados. A luta est\u00e1 cada vez maior - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/","og_locale":"pt_BR","og_type":"article","og_title":"Equipe da Santa Casa de Adamantina, cansados mas n\u00e3o desanimados. A luta est\u00e1 cada vez maior - R\u00e1dio Life FM","og_description":"Em meio a tantas postagens \u00a0em redes sociais sobre trag\u00e9dias, acidentes, entre outras, uma mensagem chama a aten\u00e7\u00e3o e viraliza nas redes sociais em Adamantina. &nbsp; A jovem Carolina Ridania, publica uma foto que estampa a realidade dos profissionais da sa\u00fade da Santa Casa de Adamantina, com um texto muito bonito. &nbsp; Santa Casa de [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2021-02-19T01:24:23+00:00","article_modified_time":"2026-05-10T12:57:37+00:00","og_image":[{"width":958,"height":958,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/02\/152258286_3680200075379520_2795660896008638357_n.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Equipe da Santa Casa de Adamantina, cansados mas n\u00e3o desanimados. A luta est\u00e1 cada vez maior","datePublished":"2021-02-19T01:24:23+00:00","dateModified":"2026-05-10T12:57:37+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/"},"wordCount":273,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/02\/152258286_3680200075379520_2795660896008638357_n.jpg","articleSection":["Adamantina","Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/","url":"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/","name":"Equipe da Santa Casa de Adamantina, cansados mas n\u00e3o desanimados. A luta est\u00e1 cada vez maior - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/02\/152258286_3680200075379520_2795660896008638357_n.jpg","datePublished":"2021-02-19T01:24:23+00:00","dateModified":"2026-05-10T12:57:37+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/02\/152258286_3680200075379520_2795660896008638357_n.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2021\/02\/152258286_3680200075379520_2795660896008638357_n.jpg","width":958,"height":958},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/equipe-da-santa-casa-de-adamantina-cansados-mas-nao-desanimados-a-luta-esta-cada-vez-maior\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Equipe da Santa Casa de Adamantina, cansados mas n\u00e3o desanimados. A luta est\u00e1 cada vez maior"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/35010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=35010"}],"version-history":[{"count":2,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/35010\/revisions"}],"predecessor-version":[{"id":35013,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/35010\/revisions\/35013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/35011"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=35010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=35010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=35010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}