{"id":30612,"date":"2020-11-26T10:22:50","date_gmt":"2020-11-26T13:22:50","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=30612"},"modified":"2026-02-06T22:14:39","modified_gmt":"2026-02-07T01:14:39","slug":"fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/","title":{"rendered":"Fiocruz produzir\u00e1 vacina contra Covid-19 desenvolvida pela Universidade de Oxford"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>O Brasil est\u00e1 cada vez mais perto de uma resposta sobre a distribui\u00e7\u00e3o de uma vacina contra a Covid-19, em larga escala. Nesta semana, resultados preliminares dos estudos cl\u00ednicos de fase 3 da vacina desenvolvida pela Universidade de Oxford confirmam a expectativa de especialistas.<\/p>\n<p>&nbsp;<\/p>\n<p>Segundo a presidente da <a href=\"https:\/\/portal.fiocruz.br\/\">Fiocruz<\/a>, N\u00edsia Trindade Lima, \u201ccom uma efic\u00e1cia demonstrada de 90% e um esquema vacinal que permitir\u00e1 otimizar as doses a serem produzidas, esta vacina deixa de ser uma candidata promissora para ser uma vacina que ser\u00e1 produzida pela Fiocruz e uma resposta \u00e0 sa\u00fade p\u00fablica brasileira.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p>Outro ponto relevante desses resultados \u00e9 que, dos 11.636 volunt\u00e1rios que passaram por an\u00e1lise nos dados, somente 30 testaram positivo para a doen\u00e7a transmitida pelo novo coronav\u00edrus, mesmo ap\u00f3s a vacina. Al\u00e9m disso, nenhum deles precisou ser hospitalizado ou teve rea\u00e7\u00f5es graves.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Fonte: <a href=\"https:\/\/brasil61.com\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford-bras202757?email=jornalismo1079@gmail.com&amp;utm_source=newsletter&amp;utm_medium=newsletter&amp;utm_campaign=newsletter\">Brasil 61<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil est\u00e1 cada vez mais perto de uma resposta sobre a distribui\u00e7\u00e3o de uma vacina contra a Covid-19, em larga escala. Nesta semana, resultados preliminares dos estudos cl\u00ednicos de fase 3 da vacina desenvolvida pela Universidade de Oxford confirmam a expectativa de especialistas. &nbsp; Segundo a presidente da Fiocruz, N\u00edsia Trindade Lima, \u201ccom uma [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":30613,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-30612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fiocruz produzir\u00e1 vacina contra Covid-19 desenvolvida pela Universidade de Oxford - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiocruz produzir\u00e1 vacina contra Covid-19 desenvolvida pela Universidade de Oxford - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"O Brasil est\u00e1 cada vez mais perto de uma resposta sobre a distribui\u00e7\u00e3o de uma vacina contra a Covid-19, em larga escala. Nesta semana, resultados preliminares dos estudos cl\u00ednicos de fase 3 da vacina desenvolvida pela Universidade de Oxford confirmam a expectativa de especialistas. &nbsp; Segundo a presidente da Fiocruz, N\u00edsia Trindade Lima, \u201ccom uma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-26T13:22:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-07T01:14:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/11\/21_07_2020_vacina_covid_sp-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"754\" \/>\n\t<meta property=\"og:image:height\" content=\"503\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"Fiocruz produzir\u00e1 vacina contra Covid-19 desenvolvida pela Universidade de Oxford\",\"datePublished\":\"2020-11-26T13:22:50+00:00\",\"dateModified\":\"2026-02-07T01:14:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/\"},\"wordCount\":161,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/11\/21_07_2020_vacina_covid_sp-4.jpg\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/\",\"name\":\"Fiocruz produzir\u00e1 vacina contra Covid-19 desenvolvida pela Universidade de Oxford - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/11\/21_07_2020_vacina_covid_sp-4.jpg\",\"datePublished\":\"2020-11-26T13:22:50+00:00\",\"dateModified\":\"2026-02-07T01:14:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/11\/21_07_2020_vacina_covid_sp-4.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/11\/21_07_2020_vacina_covid_sp-4.jpg\",\"width\":754,\"height\":503,\"caption\":\"Dos 11.636 volunt\u00e1rios que passaram por an\u00e1lise nos dados, somente 30 testaram positivo para a doen\u00e7a transmitida pelo novo coronav\u00edrus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiocruz produzir\u00e1 vacina contra Covid-19 desenvolvida pela Universidade de Oxford\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiocruz produzir\u00e1 vacina contra Covid-19 desenvolvida pela Universidade de Oxford - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/","og_locale":"pt_BR","og_type":"article","og_title":"Fiocruz produzir\u00e1 vacina contra Covid-19 desenvolvida pela Universidade de Oxford - R\u00e1dio Life FM","og_description":"O Brasil est\u00e1 cada vez mais perto de uma resposta sobre a distribui\u00e7\u00e3o de uma vacina contra a Covid-19, em larga escala. Nesta semana, resultados preliminares dos estudos cl\u00ednicos de fase 3 da vacina desenvolvida pela Universidade de Oxford confirmam a expectativa de especialistas. &nbsp; Segundo a presidente da Fiocruz, N\u00edsia Trindade Lima, \u201ccom uma [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2020-11-26T13:22:50+00:00","article_modified_time":"2026-02-07T01:14:39+00:00","og_image":[{"width":754,"height":503,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/11\/21_07_2020_vacina_covid_sp-4.jpg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"Fiocruz produzir\u00e1 vacina contra Covid-19 desenvolvida pela Universidade de Oxford","datePublished":"2020-11-26T13:22:50+00:00","dateModified":"2026-02-07T01:14:39+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/"},"wordCount":161,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/11\/21_07_2020_vacina_covid_sp-4.jpg","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/","url":"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/","name":"Fiocruz produzir\u00e1 vacina contra Covid-19 desenvolvida pela Universidade de Oxford - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/11\/21_07_2020_vacina_covid_sp-4.jpg","datePublished":"2020-11-26T13:22:50+00:00","dateModified":"2026-02-07T01:14:39+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/11\/21_07_2020_vacina_covid_sp-4.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/11\/21_07_2020_vacina_covid_sp-4.jpg","width":754,"height":503,"caption":"Dos 11.636 volunt\u00e1rios que passaram por an\u00e1lise nos dados, somente 30 testaram positivo para a doen\u00e7a transmitida pelo novo coronav\u00edrus"},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/fiocruz-produzira-vacina-contra-covid-19-desenvolvida-pela-universidade-de-oxford\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Fiocruz produzir\u00e1 vacina contra Covid-19 desenvolvida pela Universidade de Oxford"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/30612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=30612"}],"version-history":[{"count":3,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/30612\/revisions"}],"predecessor-version":[{"id":30616,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/30612\/revisions\/30616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/30613"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=30612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=30612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=30612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}