{"id":25915,"date":"2020-08-31T13:59:10","date_gmt":"2020-08-31T16:59:10","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=25915"},"modified":"2026-04-24T02:30:10","modified_gmt":"2026-04-24T05:30:10","slug":"criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/","title":{"rendered":"Crian\u00e7as sem sintomas podem carregar coronav\u00edrus por semanas"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"37\" data-block-id=\"2\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">\u00c0 medida que escolas em v\u00e1rias partes do mundo est\u00e3o reabrindo, um estudo americano sobre o potencial de transmiss\u00e3o do coronav\u00edrus\u00a0<a href=\"https:\/\/g1.globo.com\/bemestar\/coronavirus\/noticia\/2020\/03\/24\/coronavirus-covid-19-sars-cov-2-e-mais-veja-a-explicacao-para-16-termos-usados-na-pandemia.ghtml\">Sars-Cov-2<\/a>\u00a0entre crian\u00e7as apresenta resultados preocupantes, capazes de influenciar o\u00a0<a href=\"https:\/\/g1.globo.com\/bemestar\/coronavirus\/noticia\/2020\/08\/30\/os-argumentos-de-quem-e-contra-a-favor-ou-esta-em-duvida-sobre-retomar-aulas-no-brasil-durante-a-pandemia.ghtml\">debate sobre a volta \u00e0s aulas<\/a>.<br \/>\nSegundo as pesquisadoras do Hospital Nacional Infantil de Washington, crian\u00e7as infectadas podem transmitir a doen\u00e7a durante semanas, mesmo que n\u00e3o apresentem sintomas.<br \/>\nO resultado corrobora o que j\u00e1 havia sido apontado em um estudo anterior, em que pesquisadores em Boston mostraram que crian\u00e7as e jovens tinham cargas virais surpreendentemente altas.<br \/>\nO novo estudo, publicado em 28 de agosto no site da revista m\u00e9dica Jama Pediatrics, foi conduzido por Roberta L. DeBiasi e Meghan Delaney. Elas analisaram dados de 91 crian\u00e7as em 22 hospitais da <a href=\"https:\/\/g1.globo.com\/tudo-sobre\/coreia-do-sul\/\">Coreia do Sul<\/a>.<br \/>\n<em>&#8220;Ao contr\u00e1rio do sistema de sa\u00fade dos EUA, quem testa positivo para Covid-19 na Coreia do Sul permanece no hospital at\u00e9 ter se recuperado completamente da infec\u00e7\u00e3o&#8221;<\/em>, explica DeBiasi.<br \/>\nDe acordo com o estudo, 22% das crian\u00e7as n\u00e3o desenvolveram sintomas durante toda a infec\u00e7\u00e3o; 20% come\u00e7aram assintom\u00e1ticas, mas mais tarde desenvolveram sintomas; e 58% tiveram sintomas desde o primeiro teste positivo.<br \/>\nO estudo tamb\u00e9m mostrou grandes diferen\u00e7as no per\u00edodo de tempo em que as crian\u00e7as permaneceram sintom\u00e1ticas, variando de tr\u00eas dias a tr\u00eas semanas. Um quinto dos pacientes assintom\u00e1ticos e aproximadamente metade dos pacientes sintom\u00e1ticos ainda estava transmitindo o v\u00edrus tr\u00eas semanas ap\u00f3s a infec\u00e7\u00e3o inicial. Isso n\u00e3o reflete diretamente, por\u00e9m, seu n\u00edvel de contagiosidade.<\/p>\n<\/div>\n<div class=\"wall protected-content\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"54\" data-block-id=\"8\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">\n<p><strong><em>Alta carga viral<\/em><\/strong><br \/>\nOs pesquisadores em Boston, por sua vez, encontraram cargas virais surpreendentemente altas entre os pacientes mais jovens. Para o estudo, eles colheram amostras de secre\u00e7\u00e3o do nariz e da garganta de 49 pacientes com menos de 21 anos de idade. O estudo encontrou <a style=\"font-size: 16px\" href=\"https:\/\/g1.globo.com\/bemestar\/coronavirus\/noticia\/2020\/08\/20\/criancas-com-covid-tem-carga-viral-superior-a-de-adultos-na-uti-em-estudo-dos-eua.ghtml\">muito mais presen\u00e7a do v\u00edrus entre eles do que entre adultos sendo tratados em unidades de terapia intensiva para Covid-19<\/a><span style=\"font-size: 16px\">.<\/span><\/p>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"63\" data-block-id=\"12\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Ainda de acordo com o estudo de Boston, publicado em 1\u00ba de agosto no peri\u00f3dico cient\u00edfico The Journal of Pediatrics, os cientistas encontraram muito menos receptores ECA-2 entre as crian\u00e7as menores do que entre os jovens e adultos. Acredita-se que esses receptores sejam a porta de entrada para a Covid-19 nas c\u00e9lulas do corpo.<br \/>\nO papel das crian\u00e7as e dos jovens na propaga\u00e7\u00e3o do coronav\u00edrus tem sido muito debatido desde que as primeiras infec\u00e7\u00f5es foram registradas.<br \/>\nUma coisa \u00e9 certa: crian\u00e7as e jovens podem infectar outras pessoas. Tamb\u00e9m \u00e9 certo que as crian\u00e7as e os jovens infectados muitas vezes mostram poucos ou nenhuns sinais de estarem doentes. E tamb\u00e9m est\u00e1 claro \u2013 embora a maioria das pessoas prefira n\u00e3o falar sobre isso \u2013 que crian\u00e7as e jovens tamb\u00e9m podem morrer ou sofrer com sequelas duradouras resultantes de uma infec\u00e7\u00e3o por Covid-19.<br \/>\nIsso n\u00e3o significa automaticamente que todas as crian\u00e7as e jovens s\u00e3o potenciais origens de novos focos da doen\u00e7a, impulsionando as taxas de infec\u00e7\u00e3o ao seu redor. Ainda assim, crian\u00e7as e jovens \u2013 atrav\u00e9s do jardim de inf\u00e2ncia, escola, amigos e esportes \u2013 frequentemente t\u00eam muito mais intera\u00e7\u00e3o social do que os adultos.<br \/>\nOs \u00faltimos meses tamb\u00e9m mostraram que os jovens s\u00e3o t\u00e3o propensos quanto os adultos a ignorar o distanciamento social e as regras de higiene se n\u00e3o forem obrigados a fazer o contr\u00e1rio.<\/p>\n<\/div>\n<div class=\"content-ads content-ads--reveal\" data-block-type=\"ads\" data-block-id=\"16\">\n<div id=\"banner_materia__ad79fd18-1638-46af-8f68-8494bbf89c24\" class=\"tag-manager-publicidade-container mc-has-reveal mc-has-ad-lazyload tag-manager-publicidade-banner_materia__ad79fd18-1638-46af-8f68-8494bbf89c24 tag-manager-publicidade-container--carregado tag-manager-publicidade-container--visivel\" data-id=\"banner_materia__ad79fd18-1638-46af-8f68-8494bbf89c24\" data-google-query-id=\"CIKGz_vzxesCFVwwuQYd17cLnQ\" data-cid=\"138322046953\" data-lid=\"5464649011\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"32\" data-block-id=\"19\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><em><strong>Jovens como propagadores<\/strong><\/em><\/p>\n<p>Na <a style=\"font-size: 16px\" href=\"https:\/\/g1.globo.com\/tudo-sobre\/alemanha\/\">Alemanha<\/a><span style=\"font-size: 16px\">, por exemplo, onde a epidemia \u00e9 considerada sob controle, turistas voltando de f\u00e9rias de ver\u00e3o, al\u00e9m de festas e eventos lotados, levaram os \u00edndices de infec\u00e7\u00e3o aos n\u00edveis mais altos desde abril. Grande parte dos que testaram positivo recentemente s\u00e3o jovens \u2013 a idade m\u00e9dia de infectados \u00e9 a mais baixa no pa\u00eds desde o in\u00edcio da pandemia.<br \/>\n<\/span>Apesar das altas cargas virais e da capacidade de transmitir o v\u00edrus durante semanas \u2013 mesmo que uma crian\u00e7a seja assintom\u00e1tica \u2013 especialistas dizem que os jovens ainda podem agir decisivamente para deter a propaga\u00e7\u00e3o da infec\u00e7\u00e3o.<br \/>\nNo final das f\u00e9rias de ver\u00e3o europeias, as infec\u00e7\u00f5es aumentaram em toda a Alemanha e em muitos outros pa\u00edses. Entretanto, os jardins de inf\u00e2ncia, escolas e outras institui\u00e7\u00f5es de ensino est\u00e3o abrindo suas portas, n\u00e3o apenas para dar al\u00edvio aos pais, mas tamb\u00e9m em prol do bem-estar das crian\u00e7as.<br \/>\n<a href=\"https:\/\/g1.globo.com\/bemestar\/coronavirus\/noticia\/2020\/07\/21\/combinar-distanciamento-social-mascaras-e-higiene-das-maos-e-melhor-estrategia-para-combater-covid-19-mostra-estudo.ghtml\">M\u00e1scaras obrigat\u00f3rias, distanciamento f\u00edsico, regras de higiene <\/a>e grupos de estudo fixos podem reduzir o risco de propaga\u00e7\u00e3o. Esse \u00e9 o consenso, mas a forma de lidar com tais quest\u00f5es, assim como a frequ\u00eancia com que as aulas devem ser realizadas on-line ou presencialmente, permanece aberta \u00e0 interpreta\u00e7\u00e3o em muitos pa\u00edses.A fim de detectar potenciais grupos de infec\u00e7\u00e3o e evitar o fechamento de escolas em larga escala, as infec\u00e7\u00f5es entre crian\u00e7as e jovens assintom\u00e1ticos devem ser detectadas precocemente, e a crian\u00e7a isolada, segundo especialistas.Estes \u00faltimos estudos americanos sem d\u00favida levar\u00e3o a uma reavalia\u00e7\u00e3o da necessidade de testar regularmente os professores, mas tamb\u00e9m da quest\u00e3o de saber se os testes devem ser realizados apenas nos alunos que apresentam infec\u00e7\u00f5es respirat\u00f3rias agudas ou em uma porcentagem mais ampla de crian\u00e7as.<\/p>\n<div class=\"block-podcast\"><em><strong>Por G1<\/strong><\/em><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 medida que escolas em v\u00e1rias partes do mundo est\u00e3o reabrindo, um estudo americano sobre o potencial de transmiss\u00e3o do coronav\u00edrus\u00a0Sars-Cov-2\u00a0entre crian\u00e7as apresenta resultados preocupantes, capazes de influenciar o\u00a0debate sobre a volta \u00e0s aulas. Segundo as pesquisadoras do Hospital Nacional Infantil de Washington, crian\u00e7as infectadas podem transmitir a doen\u00e7a durante semanas, mesmo que n\u00e3o apresentem [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":25916,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-25915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Crian\u00e7as sem sintomas podem carregar coronav\u00edrus por semanas - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crian\u00e7as sem sintomas podem carregar coronav\u00edrus por semanas - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"\u00c0 medida que escolas em v\u00e1rias partes do mundo est\u00e3o reabrindo, um estudo americano sobre o potencial de transmiss\u00e3o do coronav\u00edrus\u00a0Sars-Cov-2\u00a0entre crian\u00e7as apresenta resultados preocupantes, capazes de influenciar o\u00a0debate sobre a volta \u00e0s aulas. Segundo as pesquisadoras do Hospital Nacional Infantil de Washington, crian\u00e7as infectadas podem transmitir a doen\u00e7a durante semanas, mesmo que n\u00e3o apresentem [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-31T16:59:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-24T05:30:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/08\/unnamed-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"262\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"palomaborzan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"palomaborzan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/\"},\"author\":{\"name\":\"palomaborzan\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/58af3e98e78c224fbe3e142e87d53f9d\"},\"headline\":\"Crian\u00e7as sem sintomas podem carregar coronav\u00edrus por semanas\",\"datePublished\":\"2020-08-31T16:59:10+00:00\",\"dateModified\":\"2026-04-24T05:30:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/\"},\"wordCount\":913,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/08\/unnamed-1.jpg\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/\",\"name\":\"Crian\u00e7as sem sintomas podem carregar coronav\u00edrus por semanas - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/08\/unnamed-1.jpg\",\"datePublished\":\"2020-08-31T16:59:10+00:00\",\"dateModified\":\"2026-04-24T05:30:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/08\/unnamed-1.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/08\/unnamed-1.jpg\",\"width\":512,\"height\":262,\"caption\":\"Dois estudos americanos mostram que menores n\u00e3o apenas apresentam uma carga surpreendentemente alta do Sars-Cov-2, como podem transmitir a doen\u00e7a por semanas, mesmo sem sintomas.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crian\u00e7as sem sintomas podem carregar coronav\u00edrus por semanas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/58af3e98e78c224fbe3e142e87d53f9d\",\"name\":\"palomaborzan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/495dd4d309288e9e8b97792861022a1857603be0c564711b6748b454e0a374dd?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/495dd4d309288e9e8b97792861022a1857603be0c564711b6748b454e0a374dd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/495dd4d309288e9e8b97792861022a1857603be0c564711b6748b454e0a374dd?s=96&d=mm&r=g\",\"caption\":\"palomaborzan\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crian\u00e7as sem sintomas podem carregar coronav\u00edrus por semanas - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/","og_locale":"pt_BR","og_type":"article","og_title":"Crian\u00e7as sem sintomas podem carregar coronav\u00edrus por semanas - R\u00e1dio Life FM","og_description":"\u00c0 medida que escolas em v\u00e1rias partes do mundo est\u00e3o reabrindo, um estudo americano sobre o potencial de transmiss\u00e3o do coronav\u00edrus\u00a0Sars-Cov-2\u00a0entre crian\u00e7as apresenta resultados preocupantes, capazes de influenciar o\u00a0debate sobre a volta \u00e0s aulas. Segundo as pesquisadoras do Hospital Nacional Infantil de Washington, crian\u00e7as infectadas podem transmitir a doen\u00e7a durante semanas, mesmo que n\u00e3o apresentem [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2020-08-31T16:59:10+00:00","article_modified_time":"2026-04-24T05:30:10+00:00","og_image":[{"width":512,"height":262,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/08\/unnamed-1.jpg","type":"image\/jpeg"}],"author":"palomaborzan","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"palomaborzan","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/"},"author":{"name":"palomaborzan","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/58af3e98e78c224fbe3e142e87d53f9d"},"headline":"Crian\u00e7as sem sintomas podem carregar coronav\u00edrus por semanas","datePublished":"2020-08-31T16:59:10+00:00","dateModified":"2026-04-24T05:30:10+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/"},"wordCount":913,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/08\/unnamed-1.jpg","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/","url":"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/","name":"Crian\u00e7as sem sintomas podem carregar coronav\u00edrus por semanas - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/08\/unnamed-1.jpg","datePublished":"2020-08-31T16:59:10+00:00","dateModified":"2026-04-24T05:30:10+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/08\/unnamed-1.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/08\/unnamed-1.jpg","width":512,"height":262,"caption":"Dois estudos americanos mostram que menores n\u00e3o apenas apresentam uma carga surpreendentemente alta do Sars-Cov-2, como podem transmitir a doen\u00e7a por semanas, mesmo sem sintomas."},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/criancas-sem-sintomas-podem-carregar-coronavirus-por-semanas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Crian\u00e7as sem sintomas podem carregar coronav\u00edrus por semanas"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/58af3e98e78c224fbe3e142e87d53f9d","name":"palomaborzan","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/495dd4d309288e9e8b97792861022a1857603be0c564711b6748b454e0a374dd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/495dd4d309288e9e8b97792861022a1857603be0c564711b6748b454e0a374dd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/495dd4d309288e9e8b97792861022a1857603be0c564711b6748b454e0a374dd?s=96&d=mm&r=g","caption":"palomaborzan"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/25915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=25915"}],"version-history":[{"count":4,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/25915\/revisions"}],"predecessor-version":[{"id":25920,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/25915\/revisions\/25920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/25916"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=25915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=25915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=25915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}