{"id":23570,"date":"2020-05-26T11:21:16","date_gmt":"2020-05-26T14:21:16","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=23570"},"modified":"2026-04-14T15:18:14","modified_gmt":"2026-04-14T18:18:14","slug":"governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/","title":{"rendered":"Governador D\u00f3ria nega lockdown imediato e sinaliza flexibilizar quarentena em algumas regi\u00f5es de S\u00e3o Paulo em junho"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p><em>Governador vai anunciar nesta quarta-feira (27) detalhes sobre as medidas que ser\u00e3o adotadas em SP<\/em><\/p>\n<p>O governador Jo\u00e3o Doria (PSDB) de S\u00e3o Paulo disse na tarde desta segunda-feira (25) em entrevista \u00e0 GloboNews (assista) que n\u00e3o pretende decretar neste momento no estado o lockdown, vers\u00e3o mais r\u00edgida do distanciamento social. Doria disse ainda que a partir do dia 1\u00ba de junho dever\u00e1 adotar a &#8220;quarentena inteligente&#8221;, na qual as medidas de isolamento social ir\u00e3o variar a depender dos aspectos particulares de cada regi\u00e3o do estado.<\/p>\n<p>\u201cNeste momento n\u00e3o h\u00e1 perspectiva de lockdown imediato em S\u00e3o Paulo, mas o protocolo existe, ou seja, neste exato momento n\u00f3s n\u00e3o vamos decretar lockdown nem na capital de S\u00e3o Paulo, nem em nenhuma outra cidade do estado de S\u00e3o Paulo, n\u00f3s temos 645 munic\u00edpios aqui, mas o olhar \u00e9 di\u00e1rio, o acompanhamento \u00e9 feito diariamente&#8221;, disse Doria.<\/p>\n<p>Quanto \u00e0 &#8220;quarentena inteligente&#8221;, o governador de SP disse que a decis\u00e3o n\u00e3o ser\u00e1 homog\u00eanea e levar\u00e1 em conta a situa\u00e7\u00e3o de cada regi\u00e3o do estado. Ainda, segundo o governador, mais detalhes ser\u00e3o divulgados em uma coletiva que ser\u00e1 realizada na quarta-feira (27) com a presen\u00e7a do prefeito da capital paulista, Bruno Covas (PSDB).<\/p>\n<p>&#8220;Para ser muito preciso, n\u00f3s teremos uma nova quarentena. Mas ser\u00e1 uma quarentena inteligente, porque levar\u00e1 em considera\u00e7\u00e3o toda a regionaliza\u00e7\u00e3o de S\u00e3o Paulo, do interior, da capital e da regi\u00e3o metropolitana, do litoral.<\/p>\n<p>A decis\u00e3o n\u00e3o ser\u00e1 homog\u00eanea. At\u00e9 agora ela foi homog\u00eanea em todo o estado porque ela precisava ser. Agora, n\u00f3s temos a condi\u00e7\u00e3o de faz\u00ea-la heterog\u00eanea, seguindo as orienta\u00e7\u00f5es do comit\u00ea de sa\u00fade.<\/p>\n<p>\u00c1reas e regi\u00f5es em que possamos nessa quarentena inteligente ter um olhar diferente, n\u00f3s vamos fazer. Aonde n\u00e3o for poss\u00edvel porque os riscos e \u00edndices indicam que n\u00e3o devem, n\u00e3o haver\u00e1&#8221;, disse Doria.<\/p>\n<p>Por &#8211; G 1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Governador vai anunciar nesta quarta-feira (27) detalhes sobre as medidas que ser\u00e3o adotadas em SP O governador Jo\u00e3o Doria (PSDB) de S\u00e3o Paulo disse na tarde desta segunda-feira (25) em entrevista \u00e0 GloboNews (assista) que n\u00e3o pretende decretar neste momento no estado o lockdown, vers\u00e3o mais r\u00edgida do distanciamento social. Doria disse ainda que a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":23571,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-23570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Governador D\u00f3ria nega lockdown imediato e sinaliza flexibilizar quarentena em algumas regi\u00f5es de S\u00e3o Paulo em junho - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governador D\u00f3ria nega lockdown imediato e sinaliza flexibilizar quarentena em algumas regi\u00f5es de S\u00e3o Paulo em junho - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Governador vai anunciar nesta quarta-feira (27) detalhes sobre as medidas que ser\u00e3o adotadas em SP O governador Jo\u00e3o Doria (PSDB) de S\u00e3o Paulo disse na tarde desta segunda-feira (25) em entrevista \u00e0 GloboNews (assista) que n\u00e3o pretende decretar neste momento no estado o lockdown, vers\u00e3o mais r\u00edgida do distanciamento social. Doria disse ainda que a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-26T14:21:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T18:18:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/Jo\u00e3o-D\u00f3ria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"332\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lifefm\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lifefm\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/\"},\"author\":{\"name\":\"lifefm\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/1d4e4b1301322090c6221bf1c8420490\"},\"headline\":\"Governador D\u00f3ria nega lockdown imediato e sinaliza flexibilizar quarentena em algumas regi\u00f5es de S\u00e3o Paulo em junho\",\"datePublished\":\"2020-05-26T14:21:16+00:00\",\"dateModified\":\"2026-04-14T18:18:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/\"},\"wordCount\":356,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/Jo\u00e3o-D\u00f3ria.jpg\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/\",\"name\":\"Governador D\u00f3ria nega lockdown imediato e sinaliza flexibilizar quarentena em algumas regi\u00f5es de S\u00e3o Paulo em junho - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/Jo\u00e3o-D\u00f3ria.jpg\",\"datePublished\":\"2020-05-26T14:21:16+00:00\",\"dateModified\":\"2026-04-14T18:18:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/Jo\u00e3o-D\u00f3ria.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/Jo\u00e3o-D\u00f3ria.jpg\",\"width\":600,\"height\":332,\"caption\":\"Governador de S\u00e3o Paulo, Jo\u00e3o D\u00f3ria j\u00fanior - Foto - Reprodu\u00e7\u00e3o Globonews.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governador D\u00f3ria nega lockdown imediato e sinaliza flexibilizar quarentena em algumas regi\u00f5es de S\u00e3o Paulo em junho\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/1d4e4b1301322090c6221bf1c8420490\",\"name\":\"lifefm\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/eca268467d925ec97d20641bb054fd944c0abb2f92854171620706bbe6474e7c?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/eca268467d925ec97d20641bb054fd944c0abb2f92854171620706bbe6474e7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/eca268467d925ec97d20641bb054fd944c0abb2f92854171620706bbe6474e7c?s=96&d=mm&r=g\",\"caption\":\"lifefm\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Governador D\u00f3ria nega lockdown imediato e sinaliza flexibilizar quarentena em algumas regi\u00f5es de S\u00e3o Paulo em junho - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/","og_locale":"pt_BR","og_type":"article","og_title":"Governador D\u00f3ria nega lockdown imediato e sinaliza flexibilizar quarentena em algumas regi\u00f5es de S\u00e3o Paulo em junho - R\u00e1dio Life FM","og_description":"Governador vai anunciar nesta quarta-feira (27) detalhes sobre as medidas que ser\u00e3o adotadas em SP O governador Jo\u00e3o Doria (PSDB) de S\u00e3o Paulo disse na tarde desta segunda-feira (25) em entrevista \u00e0 GloboNews (assista) que n\u00e3o pretende decretar neste momento no estado o lockdown, vers\u00e3o mais r\u00edgida do distanciamento social. Doria disse ainda que a [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2020-05-26T14:21:16+00:00","article_modified_time":"2026-04-14T18:18:14+00:00","og_image":[{"width":600,"height":332,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/Jo\u00e3o-D\u00f3ria.jpg","type":"image\/jpeg"}],"author":"lifefm","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"lifefm","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/"},"author":{"name":"lifefm","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/1d4e4b1301322090c6221bf1c8420490"},"headline":"Governador D\u00f3ria nega lockdown imediato e sinaliza flexibilizar quarentena em algumas regi\u00f5es de S\u00e3o Paulo em junho","datePublished":"2020-05-26T14:21:16+00:00","dateModified":"2026-04-14T18:18:14+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/"},"wordCount":356,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/Jo\u00e3o-D\u00f3ria.jpg","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/","url":"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/","name":"Governador D\u00f3ria nega lockdown imediato e sinaliza flexibilizar quarentena em algumas regi\u00f5es de S\u00e3o Paulo em junho - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/Jo\u00e3o-D\u00f3ria.jpg","datePublished":"2020-05-26T14:21:16+00:00","dateModified":"2026-04-14T18:18:14+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/Jo\u00e3o-D\u00f3ria.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/Jo\u00e3o-D\u00f3ria.jpg","width":600,"height":332,"caption":"Governador de S\u00e3o Paulo, Jo\u00e3o D\u00f3ria j\u00fanior - Foto - Reprodu\u00e7\u00e3o Globonews."},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/governador-doria-nega-lockdown-imediato-e-sinaliza-flexibilizar-quarentena-em-algumas-regioes-de-sao-paulo-em-junho\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"Governador D\u00f3ria nega lockdown imediato e sinaliza flexibilizar quarentena em algumas regi\u00f5es de S\u00e3o Paulo em junho"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/1d4e4b1301322090c6221bf1c8420490","name":"lifefm","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/eca268467d925ec97d20641bb054fd944c0abb2f92854171620706bbe6474e7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eca268467d925ec97d20641bb054fd944c0abb2f92854171620706bbe6474e7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eca268467d925ec97d20641bb054fd944c0abb2f92854171620706bbe6474e7c?s=96&d=mm&r=g","caption":"lifefm"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/23570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=23570"}],"version-history":[{"count":1,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/23570\/revisions"}],"predecessor-version":[{"id":23572,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/23570\/revisions\/23572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/23571"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=23570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=23570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=23570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}