{"id":23510,"date":"2020-05-25T16:26:13","date_gmt":"2020-05-25T19:26:13","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=23510"},"modified":"2026-04-12T23:52:34","modified_gmt":"2026-04-13T02:52:34","slug":"oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/","title":{"rendered":"OMS suspende testes com cloroquina e hidroxicloroquina contra a Covid-19"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<h2><\/h2>\n<h2 class=\"content-head__subtitle\"><em><strong>Organiza\u00e7\u00e3o coordena ensaio com pesquisadores de 100 pa\u00edses, inclusive brasileiros. Suspens\u00e3o ocorre depois que estudo com 96 mil pacientes n\u00e3o viu efeito contra coronav\u00edrus e apontou maior risco de morte.<\/strong><\/em><\/h2>\n<p>&nbsp;<\/p>\n<p>A Organiza\u00e7\u00e3o Mundial de Sa\u00fade (OMS) suspendeu nesta segunda-feira (25) o uso da cloroquina e da hidroxicloroquina em pesquisas que ela coordenava com cientistas de 100 pa\u00edses. A suspens\u00e3o tempor\u00e1ria foi tomada at\u00e9 que a seguran\u00e7a da droga seja reavaliada, j\u00e1 que estudos recentes mostraram que ela n\u00e3o \u00e9 eficaz contra a\u00a0Covid-19\u00a0e pode aumentar a taxa de mortalidade.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"47\" data-block-id=\"4\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A OMS diz que est\u00e3o mantidos os demais testes dentro da iniciativa internacional batizada de Solidariedade. Al\u00e9m dos dois medicamentos agora vetados, os pesquisadores ainda avaliam em pacientes o resultados de tr\u00eas tipos de antivirais e de um rem\u00e9dio usado para tratar esclerose m\u00faltipla\u00a0<em>(leia mais abaixo).<\/em><\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"57\" data-block-id=\"5\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O diretor-geral da entidade, Tedros Adhanom Ghebreyesus, afirmou que a suspens\u00e3o foi determinada depois da divulga\u00e7\u00e3o dos resultados do\u00a0estudo publicado na sexta-feira (22) na revista cient\u00edfica &#8220;The Lancet&#8221;. A pesquisa, feita com 96 mil pessoas, apontou que n\u00e3o houve efic\u00e1cia das subst\u00e2ncias contra a Covid-19 e detectou risco de arritmia card\u00edaca nos pacientes que as utilizaram.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"56\" data-block-id=\"7\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A OMS j\u00e1 havia anunciado que era contra o uso amplo da cloroquina para tratar a Covid-19. Quando o Brasil passou a orientar que pacientes com quadros leves pudessem usar o medicamento, os diretores da entidade ressaltaram que a\u00a0droga s\u00f3 deveria ser usada dentro de &#8220;ensaios cl\u00ednicos&#8221;, que s\u00e3o os testes dentro de pesquisas m\u00e9dicas.<\/p>\n<\/div>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\"><span style=\"color: #999999\">Fonte: G1 &#8211; O\u00a0 portal de not\u00edcias da Globo<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Organiza\u00e7\u00e3o coordena ensaio com pesquisadores de 100 pa\u00edses, inclusive brasileiros. Suspens\u00e3o ocorre depois que estudo com 96 mil pacientes n\u00e3o viu efeito contra coronav\u00edrus e apontou maior risco de morte. &nbsp; A Organiza\u00e7\u00e3o Mundial de Sa\u00fade (OMS) suspendeu nesta segunda-feira (25) o uso da cloroquina e da hidroxicloroquina em pesquisas que ela coordenava com cientistas [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":23517,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-23510","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OMS suspende testes com cloroquina e hidroxicloroquina contra a Covid-19 - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OMS suspende testes com cloroquina e hidroxicloroquina contra a Covid-19 - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"Organiza\u00e7\u00e3o coordena ensaio com pesquisadores de 100 pa\u00edses, inclusive brasileiros. Suspens\u00e3o ocorre depois que estudo com 96 mil pacientes n\u00e3o viu efeito contra coronav\u00edrus e apontou maior risco de morte. &nbsp; A Organiza\u00e7\u00e3o Mundial de Sa\u00fade (OMS) suspendeu nesta segunda-feira (25) o uso da cloroquina e da hidroxicloroquina em pesquisas que ela coordenava com cientistas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-25T19:26:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T02:52:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/cloroquina-e1590435186872.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mayraferrari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mayraferrari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/\"},\"author\":{\"name\":\"mayraferrari\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/d37940c51f50a0c5db4e065bb527a35d\"},\"headline\":\"OMS suspende testes com cloroquina e hidroxicloroquina contra a Covid-19\",\"datePublished\":\"2020-05-25T19:26:13+00:00\",\"dateModified\":\"2026-04-13T02:52:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/\"},\"wordCount\":292,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/cloroquina-e1590435186872.jpg\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/\",\"name\":\"OMS suspende testes com cloroquina e hidroxicloroquina contra a Covid-19 - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/cloroquina-e1590435186872.jpg\",\"datePublished\":\"2020-05-25T19:26:13+00:00\",\"dateModified\":\"2026-04-13T02:52:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/cloroquina-e1590435186872.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/cloroquina-e1590435186872.jpg\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"OMS suspende testes com cloroquina e hidroxicloroquina contra a Covid-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/d37940c51f50a0c5db4e065bb527a35d\",\"name\":\"mayraferrari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/69374fafea2eae004e87f555bcb8bb6e24c5d501c2ffec6bbedf0a8f25427b93?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/69374fafea2eae004e87f555bcb8bb6e24c5d501c2ffec6bbedf0a8f25427b93?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/69374fafea2eae004e87f555bcb8bb6e24c5d501c2ffec6bbedf0a8f25427b93?s=96&d=mm&r=g\",\"caption\":\"mayraferrari\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OMS suspende testes com cloroquina e hidroxicloroquina contra a Covid-19 - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/","og_locale":"pt_BR","og_type":"article","og_title":"OMS suspende testes com cloroquina e hidroxicloroquina contra a Covid-19 - R\u00e1dio Life FM","og_description":"Organiza\u00e7\u00e3o coordena ensaio com pesquisadores de 100 pa\u00edses, inclusive brasileiros. Suspens\u00e3o ocorre depois que estudo com 96 mil pacientes n\u00e3o viu efeito contra coronav\u00edrus e apontou maior risco de morte. &nbsp; A Organiza\u00e7\u00e3o Mundial de Sa\u00fade (OMS) suspendeu nesta segunda-feira (25) o uso da cloroquina e da hidroxicloroquina em pesquisas que ela coordenava com cientistas [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2020-05-25T19:26:13+00:00","article_modified_time":"2026-04-13T02:52:34+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/cloroquina-e1590435186872.jpg","type":"image\/jpeg"}],"author":"mayraferrari","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mayraferrari","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/"},"author":{"name":"mayraferrari","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/d37940c51f50a0c5db4e065bb527a35d"},"headline":"OMS suspende testes com cloroquina e hidroxicloroquina contra a Covid-19","datePublished":"2020-05-25T19:26:13+00:00","dateModified":"2026-04-13T02:52:34+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/"},"wordCount":292,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/cloroquina-e1590435186872.jpg","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/","url":"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/","name":"OMS suspende testes com cloroquina e hidroxicloroquina contra a Covid-19 - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/cloroquina-e1590435186872.jpg","datePublished":"2020-05-25T19:26:13+00:00","dateModified":"2026-04-13T02:52:34+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/cloroquina-e1590435186872.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2020\/05\/cloroquina-e1590435186872.jpg","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/oms-suspende-testes-com-cloroquina-e-hidroxicloroquina-contra-a-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"OMS suspende testes com cloroquina e hidroxicloroquina contra a Covid-19"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/d37940c51f50a0c5db4e065bb527a35d","name":"mayraferrari","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/69374fafea2eae004e87f555bcb8bb6e24c5d501c2ffec6bbedf0a8f25427b93?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/69374fafea2eae004e87f555bcb8bb6e24c5d501c2ffec6bbedf0a8f25427b93?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/69374fafea2eae004e87f555bcb8bb6e24c5d501c2ffec6bbedf0a8f25427b93?s=96&d=mm&r=g","caption":"mayraferrari"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/23510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=23510"}],"version-history":[{"count":6,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/23510\/revisions"}],"predecessor-version":[{"id":23519,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/23510\/revisions\/23519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/23517"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=23510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=23510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=23510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}