{"id":122419,"date":"2026-07-15T12:25:14","date_gmt":"2026-07-15T15:25:14","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=122419"},"modified":"2026-07-15T14:38:27","modified_gmt":"2026-07-15T17:38:27","slug":"desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/","title":{"rendered":"&#8220;Desde crian\u00e7a sempre gostei da astronomia&#8221;, destacou Guilherme Bolis Jacinto no Pauta Aberta."},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Na manh\u00e3 da ultima ter\u00e7a-feira, 14 de julho, foi realizado nas plataformas digitais da R\u00e1dio comunit\u00e1ria Life FM, mais uma apresenta\u00e7\u00e3o do programa Pauta Aberta.<\/p>\n<p>Apresentado por Sergio Barbosa, jornalista diplomado, o programa contou com a ilustre participa\u00e7\u00e3o do estudante <strong>Guilherme Bolis Jacinto<\/strong>.<\/p>\n<div class='flex flex-wrap items-center -mx-1'>\r\n<a class='thumbnail gallery p-1 w-1\/2 md:w-1\/4' href='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Marca-dagua-Jornal-do-Meio-Dia-2026-07-14T112831.554.jpg'><img class='border border-white' src='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Marca-dagua-Jornal-do-Meio-Dia-2026-07-14T112831.554-200x200.jpg' alt='Marca D'agua Jornal Do Meio Dia   2026 07 14T112831.554' \/><\/a><a class='thumbnail gallery p-1 w-1\/2 md:w-1\/4' href='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Marca-dagua-Jornal-do-Meio-Dia-2026-07-14T112843.475.jpg'><img class='border border-white' src='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Marca-dagua-Jornal-do-Meio-Dia-2026-07-14T112843.475-200x200.jpg' alt='Marca D'agua Jornal Do Meio Dia   2026 07 14T112843.475' \/><\/a><\/div>\n<p><strong><em>O convidado:<\/em><\/strong><\/p>\n<p>Nascido em Adamantina, o estudante viveu aproximadamente 18 anos na cidade de Mari\u00e1polis, se mudando para Adamantina faz pouco tempo com sua fam\u00edlia.<\/p>\n<p>A pr\u00e9-escola foi consolidada em Mari\u00e1polis, mas, segundo o mesmo, a forma\u00e7\u00e3o no ensino m\u00e9dia, ocorreu em Adamantina, hoje reside.<\/p>\n<p>Com forma\u00e7\u00e3o escolar compat\u00edvel, Bolis se destaca por sua aptid\u00e3o pela astronomia.<\/p>\n<div class='flex flex-wrap items-center -mx-1'>\r\n<a class='thumbnail gallery p-1 w-1\/2 md:w-1\/4' href='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Marca-dagua-Jornal-do-Meio-Dia-2026-07-14T112903.212.jpg'><img class='border border-white' src='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Marca-dagua-Jornal-do-Meio-Dia-2026-07-14T112903.212-200x200.jpg' alt='Marca D'agua Jornal Do Meio Dia   2026 07 14T112903.212' \/><\/a><a class='thumbnail gallery p-1 w-1\/2 md:w-1\/4' href='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Marca-dagua-Jornal-do-Meio-Dia-2026-07-14T113252.722.jpg'><img class='border border-white' src='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Marca-dagua-Jornal-do-Meio-Dia-2026-07-14T113252.722-200x200.jpg' alt='Marca D'agua Jornal Do Meio Dia   2026 07 14T113252.722' \/><\/a><\/div>\n<p>Formado no ensino m\u00e9dio, atualmente Guilherme se prepara por meio do curso preparat\u00f3rio para aprova\u00e7\u00e3o no ITA- Instituto Tecnol\u00f3gico de Aeron\u00e1utica, uma das institui\u00e7\u00f5es p\u00fablicas de engenharia mais prestigiadas do Brasil.<\/p>\n<p>Al\u00e9m de estudante, Guilherme, participa de diversas atividades na \u00e1rea social pautada no respeito e dignidade, tais como da Ordem DeMolay, ainda, a maior organiza\u00e7\u00e3o juvenil do mundo e voltada para jovens do sexo masculino entre 12 e 21 anos.<\/p>\n<p>Na oportunidade durante o Pauta Aberta, Bolis apresentou diversas explica\u00e7\u00f5es sobre o &#8221; DeMolay&#8221;, ainda, para os ouvintes e internautas, portanto, acabou ocorrendo diversas quebras de barreiras e o f\u00e1cil entendimento sobre os conceitos da Ordem.<\/p>\n<div class='flex flex-wrap items-center -mx-1'>\r\n<a class='thumbnail gallery p-1 w-1\/2 md:w-1\/4' href='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Marca-dagua-Jornal-do-Meio-Dia-2026-07-14T113502.625.jpg'><img class='border border-white' src='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Marca-dagua-Jornal-do-Meio-Dia-2026-07-14T113502.625-200x200.jpg' alt='Marca D'agua Jornal Do Meio Dia   2026 07 14T113502.625' \/><\/a><a class='thumbnail gallery p-1 w-1\/2 md:w-1\/4' href='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Marca-dagua-Jornal-do-Meio-Dia-2026-07-14T112922.601.jpg'><img class='border border-white' src='https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Marca-dagua-Jornal-do-Meio-Dia-2026-07-14T112922.601-200x200.jpg' alt='Marca D'agua Jornal Do Meio Dia   2026 07 14T112922.601' \/><\/a><\/div>\n<p>Acessando o link desta edi\u00e7\u00e3o abaixo, poder\u00e1 conferir o Programa Pauta Aberta com a presen\u00e7a do estudante, <strong>Guilherme Bolis Jacinto<\/strong>.<\/p>\n<p><strong><em>Pauta Aberta:<\/em><\/strong><\/p>\n<p>Exibido semanalmente, todas as ter\u00e7as-feiras na Life FM, o Programa Pauta Aberta tem o Apoio Institucional da <strong>C\u00e1tedra UNESCO\/UMESP de Comunica\u00e7\u00e3o para o Desenvolvimento Regional<\/strong>, tamb\u00e9m, Apoio Cultural da <strong>ESPA\u00c7O ROCK STORE<\/strong>.<\/p>\n<p><strong><em>\u00a0<\/em><\/strong><\/p>\n<p><strong><em>Por: jornalista profissional Gilson Leandro<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Na manh\u00e3 da ultima ter\u00e7a-feira, 14 de julho, foi realizado nas plataformas digitais da R\u00e1dio comunit\u00e1ria Life FM, mais uma apresenta\u00e7\u00e3o do programa Pauta Aberta. Apresentado por Sergio Barbosa, jornalista diplomado, o programa contou com a ilustre participa\u00e7\u00e3o do estudante Guilherme Bolis Jacinto. O convidado: Nascido em Adamantina, o estudante viveu aproximadamente 18 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":122420,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[126],"tags":[],"class_list":["post-122419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pauta-aberta"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Desde crian\u00e7a sempre gostei da astronomia&quot;, destacou Guilherme Bolis Jacinto no Pauta Aberta. - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Desde crian\u00e7a sempre gostei da astronomia&quot;, destacou Guilherme Bolis Jacinto no Pauta Aberta. - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; Na manh\u00e3 da ultima ter\u00e7a-feira, 14 de julho, foi realizado nas plataformas digitais da R\u00e1dio comunit\u00e1ria Life FM, mais uma apresenta\u00e7\u00e3o do programa Pauta Aberta. Apresentado por Sergio Barbosa, jornalista diplomado, o programa contou com a ilustre participa\u00e7\u00e3o do estudante Guilherme Bolis Jacinto. O convidado: Nascido em Adamantina, o estudante viveu aproximadamente 18 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T15:25:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T17:38:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Capa-Site-2026-07-14T113545.724.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"joaograndao\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"joaograndao\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/\"},\"author\":{\"name\":\"joaograndao\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6876e1240feffe6e1b63fd5cb85abf28\"},\"headline\":\"&#8220;Desde crian\u00e7a sempre gostei da astronomia&#8221;, destacou Guilherme Bolis Jacinto no Pauta Aberta.\",\"datePublished\":\"2026-07-15T15:25:14+00:00\",\"dateModified\":\"2026-07-15T17:38:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/\"},\"wordCount\":319,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Capa-Site-2026-07-14T113545.724.jpg\",\"articleSection\":[\"Pauta Aberta\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/\",\"name\":\"\\\"Desde crian\u00e7a sempre gostei da astronomia\\\", destacou Guilherme Bolis Jacinto no Pauta Aberta. - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Capa-Site-2026-07-14T113545.724.jpg\",\"datePublished\":\"2026-07-15T15:25:14+00:00\",\"dateModified\":\"2026-07-15T17:38:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Capa-Site-2026-07-14T113545.724.jpg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Capa-Site-2026-07-14T113545.724.jpg\",\"width\":1366,\"height\":768,\"caption\":\"Sergio Barbosa, Jornalista diplomado e Guilherme Bolis Jacinto, Estudante\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Desde crian\u00e7a sempre gostei da astronomia&#8221;, destacou Guilherme Bolis Jacinto no Pauta Aberta.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6876e1240feffe6e1b63fd5cb85abf28\",\"name\":\"joaograndao\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/d5b1a3cf357ed9c50404e256a1294083aa8ab5d2a994001567302786016cb32c?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d5b1a3cf357ed9c50404e256a1294083aa8ab5d2a994001567302786016cb32c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d5b1a3cf357ed9c50404e256a1294083aa8ab5d2a994001567302786016cb32c?s=96&d=mm&r=g\",\"caption\":\"joaograndao\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Desde crian\u00e7a sempre gostei da astronomia\", destacou Guilherme Bolis Jacinto no Pauta Aberta. - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/","og_locale":"pt_BR","og_type":"article","og_title":"\"Desde crian\u00e7a sempre gostei da astronomia\", destacou Guilherme Bolis Jacinto no Pauta Aberta. - R\u00e1dio Life FM","og_description":"&nbsp; &nbsp; Na manh\u00e3 da ultima ter\u00e7a-feira, 14 de julho, foi realizado nas plataformas digitais da R\u00e1dio comunit\u00e1ria Life FM, mais uma apresenta\u00e7\u00e3o do programa Pauta Aberta. Apresentado por Sergio Barbosa, jornalista diplomado, o programa contou com a ilustre participa\u00e7\u00e3o do estudante Guilherme Bolis Jacinto. O convidado: Nascido em Adamantina, o estudante viveu aproximadamente 18 [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2026-07-15T15:25:14+00:00","article_modified_time":"2026-07-15T17:38:27+00:00","og_image":[{"width":1366,"height":768,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Capa-Site-2026-07-14T113545.724.jpg","type":"image\/jpeg"}],"author":"joaograndao","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"joaograndao","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/"},"author":{"name":"joaograndao","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6876e1240feffe6e1b63fd5cb85abf28"},"headline":"&#8220;Desde crian\u00e7a sempre gostei da astronomia&#8221;, destacou Guilherme Bolis Jacinto no Pauta Aberta.","datePublished":"2026-07-15T15:25:14+00:00","dateModified":"2026-07-15T17:38:27+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/"},"wordCount":319,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Capa-Site-2026-07-14T113545.724.jpg","articleSection":["Pauta Aberta"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/","url":"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/","name":"\"Desde crian\u00e7a sempre gostei da astronomia\", destacou Guilherme Bolis Jacinto no Pauta Aberta. - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Capa-Site-2026-07-14T113545.724.jpg","datePublished":"2026-07-15T15:25:14+00:00","dateModified":"2026-07-15T17:38:27+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Capa-Site-2026-07-14T113545.724.jpg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/07\/Capa-Site-2026-07-14T113545.724.jpg","width":1366,"height":768,"caption":"Sergio Barbosa, Jornalista diplomado e Guilherme Bolis Jacinto, Estudante"},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/desde-crianca-sempre-gostei-da-astronomia-destacou-guilherme-bolis-jacinto-no-pauta-aberta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"&#8220;Desde crian\u00e7a sempre gostei da astronomia&#8221;, destacou Guilherme Bolis Jacinto no Pauta Aberta."}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6876e1240feffe6e1b63fd5cb85abf28","name":"joaograndao","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/d5b1a3cf357ed9c50404e256a1294083aa8ab5d2a994001567302786016cb32c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d5b1a3cf357ed9c50404e256a1294083aa8ab5d2a994001567302786016cb32c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d5b1a3cf357ed9c50404e256a1294083aa8ab5d2a994001567302786016cb32c?s=96&d=mm&r=g","caption":"joaograndao"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/122419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=122419"}],"version-history":[{"count":1,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/122419\/revisions"}],"predecessor-version":[{"id":122427,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/122419\/revisions\/122427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/122420"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=122419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=122419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=122419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}