{"id":117417,"date":"2026-03-17T10:28:29","date_gmt":"2026-03-17T13:28:29","guid":{"rendered":"https:\/\/radiolifefm.com.br\/noticias\/?p=117417"},"modified":"2026-05-10T19:47:23","modified_gmt":"2026-05-10T22:47:23","slug":"2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas","status":"publish","type":"post","link":"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/","title":{"rendered":"2\u00aa rodada da segunda fase da Copa FAI define dois eliminados e acirra disputa por vagas"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>A 18\u00aa Copa FAI de Futsal teve mais uma noite decisiva na \u00faltima segunda-feira (16), com a realiza\u00e7\u00e3o da 2\u00aa rodada da segunda fase no Gin\u00e1sio Paulo Camargo, em Adamantina. Os confrontos foram marcados por intensidade e j\u00e1 come\u00e7aram a desenhar o cen\u00e1rio da competi\u00e7\u00e3o.<\/p>\n<p>No primeiro jogo, o Hookah venceu o S.E. 4 Amigos por 5 a 3, em uma partida movimentada e com bom volume ofensivo. Com o resultado, o S.E. 4 Amigos\u00a0 n\u00e3o possui mais chances de classifica\u00e7\u00e3o e est\u00e1 eliminado da competi\u00e7\u00e3o.<\/p>\n<p>Na sequ\u00eancia, o Inove \/ Z\u00e9 Gordo fez valer sua for\u00e7a e derrotou o Rangers Rovers por 3 a 1. A nova derrota confirmou a elimina\u00e7\u00e3o do Rangers, que se despede da Copa FAI ainda na segunda fase.<\/p>\n<p>Fechando a rodada, Parque Igua\u00e7u e Panela Caipira Morro protagonizaram um confronto equilibrado, que terminou empatado em 3 a 3. O resultado mant\u00e9m ambas as equipes vivas na disputa por uma vaga na pr\u00f3xima fase.<\/p>\n<p>Com os resultados da rodada, a segunda fase come\u00e7a a se afunilar, com duas equipes j\u00e1 eliminadas e as demais brigando ponto a ponto pela classifica\u00e7\u00e3o.<\/p>\n<p>A expectativa agora fica para as pr\u00f3ximas partidas, que prometem fortes emo\u00e7\u00f5es e a defini\u00e7\u00e3o dos classificados para as fases decisivas do campeonato.<\/p>\n<p>Por Rita Nery<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 18\u00aa Copa FAI de Futsal teve mais uma noite decisiva na \u00faltima segunda-feira (16), com a realiza\u00e7\u00e3o da 2\u00aa rodada da segunda fase no Gin\u00e1sio Paulo Camargo, em Adamantina. Os confrontos foram marcados por intensidade e j\u00e1 come\u00e7aram a desenhar o cen\u00e1rio da competi\u00e7\u00e3o. No primeiro jogo, o Hookah venceu o S.E. 4 Amigos [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":117418,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[21,56],"tags":[],"class_list":["post-117417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-adamantina","category-esporte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2\u00aa rodada da segunda fase da Copa FAI define dois eliminados e acirra disputa por vagas - R\u00e1dio Life FM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2\u00aa rodada da segunda fase da Copa FAI define dois eliminados e acirra disputa por vagas - R\u00e1dio Life FM\" \/>\n<meta property=\"og:description\" content=\"A 18\u00aa Copa FAI de Futsal teve mais uma noite decisiva na \u00faltima segunda-feira (16), com a realiza\u00e7\u00e3o da 2\u00aa rodada da segunda fase no Gin\u00e1sio Paulo Camargo, em Adamantina. Os confrontos foram marcados por intensidade e j\u00e1 come\u00e7aram a desenhar o cen\u00e1rio da competi\u00e7\u00e3o. No primeiro jogo, o Hookah venceu o S.E. 4 Amigos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/\" \/>\n<meta property=\"og:site_name\" content=\"R\u00e1dio Life FM\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/radiolifefm\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-17T13:28:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-10T22:47:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-10.26.53.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1599\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ritanery\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ritanery\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/\"},\"author\":{\"name\":\"ritanery\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\"},\"headline\":\"2\u00aa rodada da segunda fase da Copa FAI define dois eliminados e acirra disputa por vagas\",\"datePublished\":\"2026-03-17T13:28:29+00:00\",\"dateModified\":\"2026-05-10T22:47:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/\"},\"wordCount\":235,\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-10.26.53.jpeg\",\"articleSection\":[\"Adamantina\",\"Esporte\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/\",\"name\":\"2\u00aa rodada da segunda fase da Copa FAI define dois eliminados e acirra disputa por vagas - R\u00e1dio Life FM\",\"isPartOf\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-10.26.53.jpeg\",\"datePublished\":\"2026-03-17T13:28:29+00:00\",\"dateModified\":\"2026-05-10T22:47:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/#primaryimage\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-10.26.53.jpeg\",\"contentUrl\":\"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-10.26.53.jpeg\",\"width\":1599,\"height\":1066,\"caption\":\"Parque Igua\u00e7u x Panela Caipira\/ Morro (Foto: Rita Nery)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/radiolifefm.com.br\/noticias\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2\u00aa rodada da segunda fase da Copa FAI define dois eliminados e acirra disputa por vagas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#website\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"name\":\"R\u00e1dio Life FM\",\"description\":\"O Portal de Not\u00edcias de Adamantina\",\"publisher\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\"},\"alternateName\":\"Life FM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#organization\",\"name\":\"R\u00e1dio Life FM\",\"alternateName\":\"Life FM\",\"url\":\"https:\/\/radiolifefm.com.br\/noticias\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"contentUrl\":\"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png\",\"width\":196,\"height\":47,\"caption\":\"R\u00e1dio Life FM\"},\"image\":{\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/radiolifefm\/\",\"https:\/\/www.instagram.com\/life1079fm\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87\",\"name\":\"ritanery\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g\",\"caption\":\"ritanery\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2\u00aa rodada da segunda fase da Copa FAI define dois eliminados e acirra disputa por vagas - R\u00e1dio Life FM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/","og_locale":"pt_BR","og_type":"article","og_title":"2\u00aa rodada da segunda fase da Copa FAI define dois eliminados e acirra disputa por vagas - R\u00e1dio Life FM","og_description":"A 18\u00aa Copa FAI de Futsal teve mais uma noite decisiva na \u00faltima segunda-feira (16), com a realiza\u00e7\u00e3o da 2\u00aa rodada da segunda fase no Gin\u00e1sio Paulo Camargo, em Adamantina. Os confrontos foram marcados por intensidade e j\u00e1 come\u00e7aram a desenhar o cen\u00e1rio da competi\u00e7\u00e3o. No primeiro jogo, o Hookah venceu o S.E. 4 Amigos [&hellip;]","og_url":"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/","og_site_name":"R\u00e1dio Life FM","article_publisher":"https:\/\/www.facebook.com\/radiolifefm\/","article_published_time":"2026-03-17T13:28:29+00:00","article_modified_time":"2026-05-10T22:47:23+00:00","og_image":[{"width":1599,"height":1066,"url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-10.26.53.jpeg","type":"image\/jpeg"}],"author":"ritanery","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"ritanery","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/#article","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/"},"author":{"name":"ritanery","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87"},"headline":"2\u00aa rodada da segunda fase da Copa FAI define dois eliminados e acirra disputa por vagas","datePublished":"2026-03-17T13:28:29+00:00","dateModified":"2026-05-10T22:47:23+00:00","mainEntityOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/"},"wordCount":235,"publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-10.26.53.jpeg","articleSection":["Adamantina","Esporte"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/","url":"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/","name":"2\u00aa rodada da segunda fase da Copa FAI define dois eliminados e acirra disputa por vagas - R\u00e1dio Life FM","isPartOf":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/#primaryimage"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/#primaryimage"},"thumbnailUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-10.26.53.jpeg","datePublished":"2026-03-17T13:28:29+00:00","dateModified":"2026-05-10T22:47:23+00:00","breadcrumb":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/#primaryimage","url":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-10.26.53.jpeg","contentUrl":"https:\/\/radiolifefm.com.br\/noticias\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-17-at-10.26.53.jpeg","width":1599,"height":1066,"caption":"Parque Igua\u00e7u x Panela Caipira\/ Morro (Foto: Rita Nery)"},{"@type":"BreadcrumbList","@id":"https:\/\/radiolifefm.com.br\/noticias\/2a-rodada-da-segunda-fase-da-copa-fai-define-dois-eliminados-e-acirra-disputa-por-vagas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/radiolifefm.com.br\/noticias\/"},{"@type":"ListItem","position":2,"name":"2\u00aa rodada da segunda fase da Copa FAI define dois eliminados e acirra disputa por vagas"}]},{"@type":"WebSite","@id":"https:\/\/radiolifefm.com.br\/noticias\/#website","url":"https:\/\/radiolifefm.com.br\/noticias\/","name":"R\u00e1dio Life FM","description":"O Portal de Not\u00edcias de Adamantina","publisher":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization"},"alternateName":"Life FM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiolifefm.com.br\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/radiolifefm.com.br\/noticias\/#organization","name":"R\u00e1dio Life FM","alternateName":"Life FM","url":"https:\/\/radiolifefm.com.br\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","contentUrl":"https:\/\/static.radiolifefm.com.br\/noticias\/wp-content\/uploads\/2019\/10\/logo-lifefm.png","width":196,"height":47,"caption":"R\u00e1dio Life FM"},"image":{"@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/radiolifefm\/","https:\/\/www.instagram.com\/life1079fm\/"]},{"@type":"Person","@id":"https:\/\/radiolifefm.com.br\/noticias\/#\/schema\/person\/6339b9fac59d12b071dec680d7375d87","name":"ritanery","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e37bb19071f47c0b8a23f62a903df117c5a0e75f65a0c2901562f97cd41cf86?s=96&d=mm&r=g","caption":"ritanery"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/117417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=117417"}],"version-history":[{"count":1,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/117417\/revisions"}],"predecessor-version":[{"id":117419,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/posts\/117417\/revisions\/117419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media\/117418"}],"wp:attachment":[{"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=117417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=117417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiolifefm.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=117417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}